{"id":19160,"date":"2013-07-29T16:34:46","date_gmt":"2013-07-29T16:34:46","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=19160"},"modified":"2013-07-29T16:34:46","modified_gmt":"2013-07-29T16:34:46","slug":"happening-di-tarshito-a-lecce","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/29\/happening-di-tarshito-a-lecce\/","title":{"rendered":"HAPPENING DI TARSHITO A LECCE"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/BodyPart14.jpeg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/BodyPart14-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" class=\"alignleft size-medium wp-image-19161\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/BodyPart14-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/BodyPart14.jpeg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>LECCE 2 AGOSTO 2013<\/strong> \u2013 L\u2019estate leccese \u00e8 a regola d\u2019arte contemporanea con E-lite studiogallery e la collettiva Aliens, il progetto espositivo nazionale ideato da Sergio Curtacci \u2013 direttore del magazine milanese Frattura Scomposta -, presentata il 20 luglio a Palazzo Vernazza e presso la sede della galleria in Corte San Blasio. Venerd\u00ec 2 agosto, nell\u2019ambito degli appuntamenti performativi correlati alla mostra, sar\u00e0 la volta dell\u2019artista barese, di fama internazionale, Tarshito con l\u2019happening \u201cBeatitudine\u201d, che gi\u00e0 dal titolo si propone al pubblico come un\u2019esperienza artistica dal forte carattere spirituale.<\/p>\n<p>L\u2019appuntamento \u00e8 dalle ore 20 alle ore 24 in Corte san Blasio (alle spalle del cinema Massimo), presso E-lite studiogallery, dove i visitatori avranno la straordinaria possibilit\u00e0 di prendere parte in prima persona all\u2019happening, interagendo in maniera attiva con l\u2019artista, \u201cper costruire un\u2019Opera che sia al tempo stesso momento artistico e sociale, aspetto d\u2019Amore e di Unit\u00e0\u201d. Tarshito si sofferma sul significato dell\u2019atto performativo, dell\u2019happening, come \u201cstrada relazionale\u201d, come possibilit\u00e0 di entrare in contatto con le proprie personali qualit\u00e0 e con la propria realt\u00e0, al di l\u00e0 delle maschere che indossiamo nella nostra quotidianit\u00e0 e affida all&#8217;arte il compito di essere un respiro nuovo, un respiro pi\u00f9 profondo, pi\u00f9 ampio, pi\u00f9 gioioso, pi\u00f9 aperto, pi\u00f9 collegato al Trascendente.<\/p>\n<p>Spiega l\u2019artista: \u201cL&#8217;intervento non \u00e8 solo di ricerca visiva ed estetica, ma vuole essere anche uno stimolo alla ricerca interiore attivata attraverso il senso dell\u2019udito, della vista e dell\u2019olfatto e perseguita nell\u2019incontro tra me e la singola persona. Vivo le quattro ore dell\u2019happening accogliendo singolarmente tutti i presenti, in una ritualit\u00e0 semplice e avvolgente che viene ripetuta per 108 volte, per sancire con la sacralit\u00e0 che appartiene a questo numero la consapevolezza delle qualit\u00e0 proprie della nostra Essenza, l&#8217;immortalit\u00e0, la conoscenza e la beatitudine. Ed ecco il perch\u00e9 del titolo, un titolo che vuole essere un buon augurio per le persone, per tutte le creature, per me stesso, affinch\u00e9 si possa sentire e riconoscere questa nostra attitudine alla beatitudine\u201d.<\/p>\n<p><strong>\u00a0BIOGRAFIA TARSHITO<\/strong><\/p>\n<p>Tarshito (in sanscrito Sete di Dio) \u00e8 il nome che Osho, suo maestro spirituale, ha dato a Nicola Strippoli. Nasce in Puglia nel 1952. Architetto, artista, docente di Design presso l\u2019Accademia di Belle Arti di Bari. Tarshito crea ambienti e opere per la nuova umanit\u00e0 attraverso la meditazione.<\/p>\n<p>Nei primi anni \u201980 fonda a Bari la Galleria Speciale, insieme a Shama. L\u2019esperienza dura fino al 1987 coinvolgendo progettisti e artisti di fama (Alessandro Mendini, Mario Merz, Nanda Vigo) o anche ignoti, purch\u00e9 interessati all\u2019esperienza\/progettazione di momenti e oggetti di \u2018nuova ritualit\u00e0\u2019. Nel 1990 l\u2019esperienza di Speciale viene documentata con una Grande Mostra al Groninger Museum della citt\u00e0 di Groningen, in Olanda, conclusiva di una trilogia che il suo direttore Frans Hacks volle dedicare al design italiano degli anni Ottanta (uniche esperienze documentate nella stessa trilogia: quella di Ettore Sottsass ovvero Memphis e di Alessandro Mendini ovvero Alchimia).<\/p>\n<p>Gli anni \u201990 vedono Tarshito protagonista di mostre collettive e personali e sempre pi\u00f9 creativamente impegnato sull\u2019archetipo del Guerriero d\u2019Amore.<\/p>\n<p>Con la grande personale The Gold and the Clay (2001), curata da Daniela Bezzi e da Jyotindra Jain al Crafts Museum di New Delhi, il suo percorso artistico si espande e al tempo stesso si focalizza nell\u2019entusiasmante pratica di collaborazione con gli artigianati dell\u2019India.<\/p>\n<p>La sete di sperimentazione delle varie tradizioni indiane e le sempre nuove relazioni di \u2018condivisione creativa\u2019 non conoscono sosta, mentre si fa strada il desiderio di dipingere in proprio, di provarsi con il segno del pennello sulla tela con gesto proprio. Il risultato \u00e8 l\u2019infinita serie dei Vasi, grandi, enormi oppure piccoli, su carta, tessuto o in sculture di grandi dimensioni, che sono il pi\u00f9 eloquente Manifesto della sua poetica: l\u2019Opera di Tarshito si esprime nell\u2019atto dell\u2019accogliere e riempirsi, e quindi traboccare. Un travaso concettuale ed emotivo che avviene nella relazione con la forma\/materia dell\u2019artigiano, o guidando sedute particolarissime di meditazione, o progettando opere che possono considerarsi monumenti a un tipo completamente nuovo e al tempo stesso antico e purissimo di Arte sacra: quella in cui l\u2019artista si propone come umile canale di trasmissione, di una creativit\u00e0 che essendo gi\u00e0 in se stessa \u2018dono\u2019, potr\u00e0 solo gioiosamente condividersi, anche autorialmente, con altri.<\/p>\n<p><strong>\u00a0SCHEDA TECNICA<\/strong><\/p>\n<p>Happening: Beatitudine<\/p>\n<p>Artista: Tarshito<\/p>\n<p>Organizzazione e realizzazione: E-lite studiogallery galleria d\u2019arte contemporanea Lecce<\/p>\n<p>Data: venerd\u00ec 2 agosto 2013 dalle ore 20 :00 alle ore 24.00<\/p>\n<p>Luogo: E-lite studiogallery | Corte San Blasio 1c Lecce<\/p>\n<p>L\u2019happening \u00e8 uno degli eventi correlati alla collettiva nazionale di arte contemporanea:<\/p>\n<p>Aliens. Le forme alienanti del contemporaneo<\/p>\n<p>Artisti: Andrea Martinucci, Angela Viola, Anna Caruso, Anna Frida Madia, Annaclara Di Biase, Annal\u00f9, Antonio De Luca, Antonio Delluzio, Carlo Cofano, El Gato Chimney, Elisa Anfuso, Eva Reguzzoni, Fabio Mazzola, Fabrizio Riccardi, Francesco Sambo, Fulvio Martini, Giancarlo Bozzani, Giancarlo Marcali, Gianluca Chiodi, Ilaria Margutti, Irene Lucia Vanelli, Jara Marzulli, Marcella Bonfanti, Marco Rea, Massimiliano Manieri, Massimo Quarta, Matteo Nannini, Maurizio L\u2019Altrella, Mom\u00f2 Calascibetta, Nicola Caredda, Nunzio Paci, Orod\u00e8 Deoro, Raffaella Formenti, Roberta Ubaldi, Roberto Fontana, Streamcolors, Tarshito, Tiziano Soro, Vania Elettra Tam, Vincenzo Todaro<\/p>\n<p>Progetto a cura di: Sergio Curtacci | Frattura Scomposta Contemporary Art Magazine Milano<\/p>\n<p>Organizzazione e realizzazione: E-lite studiogallery galleria d\u2019arte contemporanea Lecce, Frattura Scomposta<\/p>\n<p>Patrocinio: Comune di Lecce e Assessorato Cultura, Turismo Spettacolo Lecce<\/p>\n<p>Sponsor: Vestas Hotels &amp; Resorts, Leone De Castris Vitivinicoltori dal 1665, Pezzuto Forniture per impiantistica civile e industriale<\/p>\n<p>Catalogo in mostra, a cura di Sergio Curtacci | Frattura Scomposta Contemporary Art Magazine Milano<\/p>\n<p>Luoghi:<\/p>\n<p>Elite studiogallery | Corte San Blasio 1c Lecce<\/p>\n<p>Palazzo Vernazza Castromediano| Piazzetta Giuseppe Pellegrino Lecce<\/p>\n<p>Periodo: 20 luglio \u2013 20 agosto 2013<\/p>\n<p>Inaugurazione: sabato, 20 luglio ore 20.00 \u2013 ingresso libero<\/p>\n<p><strong>Orari: mar \u2013 sab | 18.00 \u2013 21.30 \u2013 ingresso gratuito<\/strong><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/29\/happening-di-tarshito-a-lecce\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/29\/happening-di-tarshito-a-lecce\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>LECCE 2 AGOSTO 2013 \u2013 L\u2019estate leccese \u00e8 a regola d\u2019arte contemporanea con E-lite studiogallery e la collettiva Aliens, il progetto espositivo nazionale ideato da Sergio Curtacci \u2013 direttore del magazine milanese Frattura Scomposta -, presentata il 20 luglio a Palazzo Vernazza e presso la sede della galleria in Corte San Blasio. Venerd\u00ec 2 agosto, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19161,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19160"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19160"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19160\/revisions"}],"predecessor-version":[{"id":19163,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19160\/revisions\/19163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19161"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=19160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=19160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=19160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}