{"id":19194,"date":"2013-07-30T15:38:05","date_gmt":"2013-07-30T15:38:05","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=19194"},"modified":"2013-07-30T15:38:05","modified_gmt":"2013-07-30T15:38:05","slug":"santhia-da-affrontare-con-un-centrocampo-da-inventare-conosciamo-i-primi-avversari-del-lecce","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/30\/santhia-da-affrontare-con-un-centrocampo-da-inventare-conosciamo-i-primi-avversari-del-lecce\/","title":{"rendered":"SANTHIA\u2019 DA AFFRONTARE CON UN CENTROCAMPO DA INVENTARE: CONOSCIAMO I PRIMI AVVERSARI DEL LECCE"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/Schermata-2013-07-30-a-17.36.48.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/Schermata-2013-07-30-a-17.36.48-300x198.jpg\" alt=\"\" width=\"300\" height=\"198\" class=\"alignleft size-medium wp-image-19195\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/Schermata-2013-07-30-a-17.36.48-300x198.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/Schermata-2013-07-30-a-17.36.48.jpg 704w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Si discute tanto di calciomercato, di arrivi, di partenze, di simil-bandiere che vanno via non dimostrandosi tali, ma in tutto questo tourbillon di discussioni si rischia di perdere contatto dal primo impegno ufficiale del Lecce stagione 2013\/14 che vede i giallorossi opposti al Santhi\u00e0 domenica alle 20.45 al Via del Mare.<\/p>\n<p>Il Lecce se la dovr\u00e0 vedere con i biancorossi piemontesi che l\u2019anno scorso hanno sfiorato la promozione in Lega Pro 2, giungendo secondi nel girone A della serie D a 69 punti, tre lunghezze in meno del Bra che ha raggiunto la promozione diretta in Lega Pro 2.<\/p>\n<p>I vercellesi hanno poi disputato i playoff di Serie D finalizzati a creare una griglia per gli eventuali ripescaggi a causa degli endemici fallimenti che caratterizzano ogni anno il nostro calcio. Il Santhi\u00e0 ha vinto i playoff del suo girone avendo la meglio sul terzetto Chieri-Borgosesia-Lavagnese ma poi si \u00e8 fermata ai quarti di finale della fase nazionale sconfitta dai futuri vincitori della Virtus Vecomp Verona, terza squadra della citt\u00e0.<\/p>\n<p>I vercellesi quindi sono al nono posto di questa speciale griglia per i ripescaggi in Lega Pro 2 ma le situazioni incerte delle squadre situate davanti in griglia (Foligno, Gavorrano, Torre Neapolis) potranno far salire le probabilit\u00e0 di promozione a tavolino del Santhi\u00e0. Si decider\u00e0 tutto in questi giorni, in Lega Pro appaiono spacciate ormai compagini quali la Tritium, la Sambenedettese, il Treviso, l\u2019Andria ed il Portogruaro. Ogni nube sar\u00e0 disciolta il 9 agosto quando a Firenze verranno presentati gironi e calendari del campionato di Lega Pro 2013-2014.<\/p>\n<p>La squadra di Santhi\u00e0, comune di 8.900 abitanti nel vercellese, si prepara quindi aspettando il verdetto della serie dove dovr\u00e0 misurarsi, questo limbo blocca il calciomercato della squadra del presidente Fabrizio Guala che dovr\u00e0 definire il budget in base alla serie di competenza.<\/p>\n<p>Il precampionato dei vercellesi \u00e8 stato caratterizzato da esibizioni eccellenti: la squadra dell\u2019allenatore Flavio Nistic\u00f2 \u00e8 stata sconfitta per 6-0 dalla Sampdoria di Delio Rossi ma ha poi realizzato una sorprendente vittoria per 1-0 nella giornata di ieri contro il Varese.<\/p>\n<p>La vittoria contro una quotata squadra di Serie B, raggiunta grazie al gol di Ceci, dimostra che i vercellesi vendono cara la pelle e, nonostante la stagione sia ancora alle porte, una discreta forma.<\/p>\n<p>Il Santhi\u00e0 al Via del Mare non avr\u00e0 nulla da perdere e l\u2019obbligo di vincere e di fare bella figura graver\u00e0 tutto sul Lecce di Moriero che in questi giorni ha ceduto ufficialmente Ledian Memushaj al Carpi.<\/p>\n<p>Sembra orientata verso la rescissione la grana Giacomazzi: l\u2019uruguagio non ha gradito la cessione della fascia di capitano operata da Moriero a beneficio di Miccoli senza preavviso ed ha manifestato l\u2019intenzione di lasciare il Lecce rescindendo il contratto.<\/p>\n<p>La grana per la fascia di capitano sembra in ogni caso il \u201ccasus belli\u201d utile a far scoppiare una serie di detriti tra Giacomazzi ed il Lecce, nonostante 12 anni di permanenza in giallorosso (anch\u2019essi conditi da qualche diatriba e fuga, da ricordare per onest\u00e0 intellettuale).<\/p>\n<p>Giacomazzi ha lasciato il ritorno di Montecopiolo ed \u00e8 partito alla volta di Lecce per risolvere le sue ultime pendenze riguardanti il futuro.<\/p>\n<p>Per la partita di domenica il centrocampo, orfano delle due colonne della scorsa stagione Giacomazzi e Memushaj, sembra da inventare in toto, con l\u2019unica sicurezza in campo di Mariano Bogliacino. Ai suoi lati potrebbero essere impiegati Falcone, rientrante dall\u2019esperienza al Lancino, ed il giovane Tundo.<\/p>\n<p>In ogni caso ad oggi stilare una formazione quasi certa appare difficile: sar\u00e0 sicuro l\u2019impiego della punta di diamante Fabrizio Miccoli che sar\u00e0 affiancato probabilmente da Gianmarco Zigoni, favorito su Beretta. In porta debutter\u00e0 Perucchini ed in difesa probabilmente la coppia centrale sar\u00e0 Martinez-Vinetot.<\/p>\n<p>Il Via del Mare domenica sar\u00e0 aperto a met\u00e0 infatti il Lecce sconter\u00e0 la prima delle quattro giornate di squalifica delle curve.<\/p>\n<p>Dopo la partita con il Santhi\u00e0 verr\u00e0 presentata la campagna abbonamenti, che probabilmente vedr\u00e0 il testimonial in Fabrizio Miccoli.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Gabriele De Pandis.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/30\/santhia-da-affrontare-con-un-centrocampo-da-inventare-conosciamo-i-primi-avversari-del-lecce\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/30\/santhia-da-affrontare-con-un-centrocampo-da-inventare-conosciamo-i-primi-avversari-del-lecce\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Si discute tanto di calciomercato, di arrivi, di partenze, di simil-bandiere che vanno via non dimostrandosi tali, ma in tutto questo tourbillon di discussioni si rischia di perdere contatto dal primo impegno ufficiale del Lecce stagione 2013\/14 che vede i giallorossi opposti al Santhi\u00e0 domenica alle 20.45 al Via del Mare. Il Lecce se la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19195,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[44,42],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19194"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19194"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19194\/revisions"}],"predecessor-version":[{"id":19196,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19194\/revisions\/19196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19195"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=19194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=19194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=19194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}