{"id":19200,"date":"2013-07-31T07:18:53","date_gmt":"2013-07-31T07:18:53","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=19200"},"modified":"2013-07-31T07:18:53","modified_gmt":"2013-07-31T07:18:53","slug":"bomba-a-mano-in-una-grotta-e-ordigno-inerte-nella-discarica","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/31\/bomba-a-mano-in-una-grotta-e-ordigno-inerte-nella-discarica\/","title":{"rendered":"BOMBA A MANO IN UNA GROTTA E ORDIGNO INERTE NELLA DISCARICA"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/Unknown23.jpeg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/07\/Unknown23.jpeg\" alt=\"\" width=\"258\" height=\"195\" class=\"alignleft size-full wp-image-19201\" \/><\/a>Lunedi 29 luglio, i Carabinieri della Stazione di Ruffano sono intervenuti in Supersano, in <strong>localit\u00e0 Mendole<\/strong>, dove il gruppo di speleologi Ndronico di Lecce, nel corso di una loro attivit\u00e0 di settore, ha trovato, all\u2019interno di una grotta, alla profondit\u00e0 di circa trenta metri, ordigno incastrato fra due massi. Sul posto \u00e8 sopraggiunto l\u2019artificiere antisabotaggio del Comando Provinciale Carabinieri di Lecce che ha ispezionato il manufatto consistente in una bomba a mano mk2, tipo ananas, integra ed attiva, facendola brillare in sicurezza previa autorizzazione dell\u2019Autorit\u00e0 Giudiziaria.<\/p>\n<p>Invece ieri mattina, a<strong> Campi Salentina<\/strong>, un quarantanovenne rappresentante della societ\u00e0 che raccoglie e seleziona i rifiuti,\u00a0 denominata\u00a0<em>Sud Gas<\/em>\u00a0del luogo, ha trovato, rinveniva nell\u2019impianto di smaltimento dei rifiuti un manufatto simile ad un ordigno esplosivo. Sul posto l\u2019artificiere antisabotaggio del Comando Provinciale CC di Lecce lo ha identificato per una bomba da mortaio, accertando che lo stesso era inerte<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/31\/bomba-a-mano-in-una-grotta-e-ordigno-inerte-nella-discarica\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/07\/31\/bomba-a-mano-in-una-grotta-e-ordigno-inerte-nella-discarica\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Lunedi 29 luglio, i Carabinieri della Stazione di Ruffano sono intervenuti in Supersano, in localit\u00e0 Mendole, dove il gruppo di speleologi Ndronico di Lecce, nel corso di una loro attivit\u00e0 di settore, ha trovato, all\u2019interno di una grotta, alla profondit\u00e0 di circa trenta metri, ordigno incastrato fra due massi. Sul posto \u00e8 sopraggiunto l\u2019artificiere antisabotaggio [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19201,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[44,42],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19200"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19200"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19200\/revisions"}],"predecessor-version":[{"id":19203,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19200\/revisions\/19203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19201"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=19200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=19200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=19200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}