{"id":192338,"date":"2021-12-11T16:47:53","date_gmt":"2021-12-11T15:47:53","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=192338"},"modified":"2021-12-11T18:43:17","modified_gmt":"2021-12-11T17:43:17","slug":"serve-un-regolamento-per-il-verde-pubblico","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/12\/11\/serve-un-regolamento-per-il-verde-pubblico\/","title":{"rendered":"SERVE UN REGOLAMENTO PER IL VERDE PUBBLICO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-192339\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/unnamed-9.jpg\" alt=\"\" width=\"512\" height=\"384\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/unnamed-9.jpg 512w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/unnamed-9-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/unnamed-9-400x300.jpg 400w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>Riceviamo e volentieri pubblichiamo. Il Forum Ambiente e Salute Lecce ci manda il seguente comunicato______<\/p>\n<p style=\"font-weight: 400;\"><strong>VERDE URBANO DI LECCE:<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>SENZA REGOLAMENTO , INADEGUATA la \u00a0RIORGANIZZAZIONE<\/strong><\/p>\n<p style=\"font-weight: 400;\">L\u2019affidamento\u00a0 a Lupiae service in house delle gestione pianificata del verde pubblico di Lecce \u00e8 un passo utile per migliorare il servizio finora svolto in maniera frammentaria, spesso occasionale, non di rado \u00a0senza rispetto delle dinamiche\u00a0 naturali (periodo \u00a0e modalit\u00e0 di potature\u00a0 etc), pur sancite da norme nazionali. Criticit\u00e0 peraltro in parte riconosciute dall\u2019Amministrazione comunale, con l\u2019impegno a superarle.<\/p>\n<p style=\"font-weight: 400;\">Ma non \u00e8 sufficiente per perseguire una gestione virtuosa sia\u00a0 \u00a0del verde pubblico, \u00a0\u00a0sia per promuovere anche quella del verde\u00a0 privato urbano.<\/p>\n<p style=\"font-weight: 400;\">Il Comune deve dotarsi del Regolamento del verde urbano, del Piano del Verde, strumenti previsti \u2013seppur non obbligatori- e doverosi almeno per una citt\u00e0 quale Lecce, adottati anche da centri urbani\u00a0 meno importanti.<\/p>\n<p style=\"font-weight: 400;\">Infatti resta la domanda: con quali criteri , competenze , assunzione di responsabilit\u00e0 saranno assunte \u00a0le decisioni principali e\u00a0 adottati \u00a0gli \u00a0\u00a0interventi\u00a0 non di routine \u00a0nella gestione del verde pubblico e nel controllo di quello privato, che non \u00e8 nella piena\u00a0 e indiscriminata disponibilit\u00e0 dei proprietari , avendo anch\u2019esso una riconosciuta valenza pubblica?<\/p>\n<p style=\"font-weight: 400;\">Senza un Regolamento e un Piano, \u00a0le decisioni\u00a0 saranno ancora frammentate \u00a0almeno tra tre assessorati (Lavori pubblici, ambiente, urbanistica), e spesso affidate a funzionari\u00a0\u00a0 non competenti per titoli professionali (sono prevalentemente geometri o ingegneri). Nell\u2019assenza di\u00a0 Regole\u00a0 -a tutela propria e del verde- talora si \u00e8 propensi ad autorizzare \u00a0espianti \u201cpreventivi\u201d (anche \u00a0non\u00a0 corredati da adeguate perizie) \u00a0di alberature, nella paura che in futuro possano\u00a0 cedere, quindi comportare\u00a0 contenziosi e richiesta danni; oppure si procede ad \u00a0espianti generosi \u00a0e non indispensabili per i lavori previsti, \u00a0che possono essere evitati: lo confermano\u00a0 i tre pini salvati , sugli otto condannati pochi giorni fa \u00a0alla motosega, \u00a0nel recinto del Tribunale e nel Parco Corvaglia . grazie all\u2019intervento degli attivisti del Coordinamento per gli alberi e il verde di Lecce.<\/p>\n<p style=\"font-weight: 400;\">Per questo \u00a0oggi\u00a0da parte del Sindaco Salvemini\u00a0 va mantenuto l\u2019impegno dell\u2019allora consigliere Salvemini per il Regolamento del verde urbano!<\/p>\n<p style=\"font-weight: 400;\">\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/12\/11\/serve-un-regolamento-per-il-verde-pubblico\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/12\/11\/serve-un-regolamento-per-il-verde-pubblico\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Il Forum Ambiente e Salute Lecce ci manda il seguente comunicato______ VERDE URBANO DI LECCE: SENZA REGOLAMENTO , INADEGUATA la \u00a0RIORGANIZZAZIONE L\u2019affidamento\u00a0 a Lupiae service in house delle gestione pianificata del verde pubblico di Lecce \u00e8 un passo utile per migliorare il servizio finora svolto in maniera frammentaria, spesso occasionale, non [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":192339,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/192338"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=192338"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/192338\/revisions"}],"predecessor-version":[{"id":192340,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/192338\/revisions\/192340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/192339"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=192338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=192338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=192338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}