{"id":192359,"date":"2021-12-12T15:35:28","date_gmt":"2021-12-12T14:35:28","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=192359"},"modified":"2021-12-12T16:06:24","modified_gmt":"2021-12-12T15:06:24","slug":"partecipata-manifestazione-di-protesta-contro-lapertura-della-discarica-di-corigliano-dotranto-il-salento-scomunica-emiliano-e-maraschio","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/12\/12\/partecipata-manifestazione-di-protesta-contro-lapertura-della-discarica-di-corigliano-dotranto-il-salento-scomunica-emiliano-e-maraschio\/","title":{"rendered":"PARTECIPATA MANIFESTAZIONE DI PROTESTA CONTRO L&#8217;APERTURA DELLA DISCARICA DI CORIGLIANO D&#8217;OTRANTO, IL SALENTO &#8230;SCOMUNICA&#8230;EMILIANO E MARASCHIO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-192360\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/bu-1.jpg\" alt=\"\" width=\"1440\" height=\"1080\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/bu-1.jpg 1440w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/bu-1-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/bu-1-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/bu-1-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/bu-1-400x300.jpg 400w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/>di <strong>Giuseppe Puppo\u00a0<\/strong>______<\/p>\n<p>Giornata di lotta, di protesta, di indignazione questa domenica prenatalizia nel Salento.\u00a0 La nostra nuova terra dei fuochi, martoriata con accanimento dalle realizzazioni di opera inutili, dannose, pericolose, devastanti, in un territorio che detiene il triste primato della desertificazione e dove, per citare l&#8217;oncologo <strong><span style=\"color: #003300;\">Giuseppe Serravezza<\/span><\/strong>, non si potrebbe accendere neppure un cerino.<\/p>\n<p>A proposito, encomiabile nel suo impegno ambientalista, c&#8217;era pure il dottor Serravezza, &#8216;stamatina, fra il centinaio di dimostranti a Scomunica di Corigliano d&#8217;Otranto.<\/p>\n<p>E invece&#8230;Invece, oltre a continuare a prevedere l&#8217;uso della chimica in\u00a0 agricoltura, continuano a costruire\u00a0 e a progettare gasdotti, trivelle, pale, impianti, e discariche.<\/p>\n<p>Discariche, dico, mentre il Mostro di Burgesi \u00e8 ancora l\u00e0, con il suo letale carico di morte, di veleni e di chiss\u00e0 quali altre schifezze,\u00a0 nonostante le promesse di &#8216;bonifica&#8217; dell&#8217;intero sito rimaste, in maniera finanche irritante, parole al vento, quello stesso vento che porta nell&#8217;aria altri veleni da Taranto e da Brindisi.<\/p>\n<p>&nbsp;<\/p>\n<p>Il 19 ottobre scorso la giunta della Regione Puglia ha approvato il nuovo piano per la gestione dei rifiuti.\u00a0Discutibile, in pensieri, parole, opere e omissioni, per tante ragioni, almeno a leggere i rilievi fatti dalle associazioni ambientaliste, in primis per il riaffermato carattere di affidamento in oligopolio dell&#8217;intero settore.<\/p>\n<p>In questo piano, a parte tutto il resto di discutibile, c&#8217;\u00e8 per\u00f2 un vero e proprio obbrobrio.<\/p>\n<p>Non c&#8217;\u00e8 bisogno di essere esperti del settore, fisici, geologi, dotti, medici e sapienti per capirlo. Basta avere un minimo di comune buon senso, infatti, per capire che non si pu\u00f2 mettere una discarica di rifiuti su una falda acquifera che serve la popolazione.<\/p>\n<p>E invece&#8230;Invece il presidente della Regione Puglia Michele Emiliano e l&#8217;assessore all&#8217;Ambiente Anna Grazia Maraschio, 60 anni, salentina di Pat\u00f9, residente a Lecce, avvocato, di Sinistra Italiana, non l&#8217;hanno capito.<\/p>\n<p>Infatti, nel nuovo piano regionale, \u00e8 prevista l&#8217;apertura di una discarica di servizio -soccorso per rifiuti urbani nel territorio di\u00a0 Corigliano d&#8217; Otranto, localit\u00e0 Scomunica, in una cava che sta proprio sopra una grossa falsa acquifera, utilizzata dall&#8217;Acquedotto Pugliese per servire tanti paesi del Salento.<\/p>\n<p>Una brutta storia, cominciata tanto tempo fa, che per\u00f2 ora rischia di finire peggio.<\/p>\n<p>Per farla breve &#8211; ma \u00e8 incredibile il modo con cui, con tenacia sospetta, la vicenda si \u00e8 sviluppata, nonostante tutto e tutti quelli che si opponevano a ragion veduta, ab origine &#8211; progettata e costruita attraverso i decenni, questo impianto fu &#8216;ultimato&#8217; una prima volta nel 2013 e di nuovo nel 2017, e non \u00e8 mai entrato in funzione, grazie all&#8217;opposizione dei sindaci del territorio sui pericoli di inquinamento della falda acquifera.<\/p>\n<p>A volerli leggere, ci sono pareri qualificati e univoci che denunciano i pericoli di inquinamento, un rischio concreto, documentato, denunciato per primo proprio dall&#8217;Acquedotto Pugliese.<\/p>\n<p>E invece&#8230;E invece Emiliano e Maraschio due mesi fa hanno deciso l&#8217;apertura operativa, incredibile ma vero.<\/p>\n<p>Giornata di lotta, di protesta, di indignazione questa domenica prenatalizia nel Salento. Questa mattina associazioni ambientaliste salentine, con la partecipazione del Movimento Regione Salento, hanno organizzato una manifestazione a Corigliano d&#8217;Otranto. Dalla localit\u00e0 Scomunica \u00e8 partita la&#8230;scomunica popolare a Emiliano e Maraschio, la diffida a ritirare la loro decisione e, sulla discarica, metterci una pietra sopra, tombale.<\/p>\n<p>Nonostante il tempo inclemente di freddo e pioggia, si sono ritrovati in tanti, amministratori, attivisti di associazioni ambientaliste, cittadini.<\/p>\n<p>Un NO, partecipato e trasversale, grande quanto una casa.<\/p>\n<p><span style=\"color: #000080;\"><strong><em>\u201cNon possiamo accettare che sia messo in esercizio un impianto\u00a0 finora mai entrato in funzione per la sua pericolosit\u00e0 vista l\u2019ubicazione sulla falda freatica che serve i pozzi dell\u2019Acquedotto Pugliese portando l\u2019acqua a mezza provincia di Lecce<\/em> <\/strong><\/span>&#8211; ha detto il consigliere regionale <strong>Paolo Pagliaro<\/strong>, ed ha poi aggiunto &#8211; <strong><em><span style=\"color: #000080;\">Mi ha fatto piacere vedere tanta partecipazione perch\u00e9 il problema \u00e8 di massima importanza e serve l\u2019impegno di tutti per far comprendere il grave rischio al quale potrebbero essere sottoposti i cittadini. Questo \u00e8 l\u2019ennesimo alt del territorio salentino e non pu\u00f2 essere ignorato\u201d<\/span>.<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Le somme della mattinata le ha tirate poco fa l&#8217;ambientalista <strong><span style=\"color: #ff0000;\">Serena Fiorentino<\/span><\/strong>, che sul suo profilo di Facebook ha scritto in perfetta sintesi:<em><strong><span style=\"color: #ff0000;\"> \u201cNon \u00e8 accettabile una discarica sulla falda. L&#8217;acqua va tutelata in quanto bene prezioso ed irrinunciabile. Ottocentomila salentini non sono condannabili a sete e malattie \u201d.<\/span><\/strong><\/em><\/p>\n<p>.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/12\/12\/partecipata-manifestazione-di-protesta-contro-lapertura-della-discarica-di-corigliano-dotranto-il-salento-scomunica-emiliano-e-maraschio\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/12\/12\/partecipata-manifestazione-di-protesta-contro-lapertura-della-discarica-di-corigliano-dotranto-il-salento-scomunica-emiliano-e-maraschio\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Giuseppe Puppo\u00a0______ Giornata di lotta, di protesta, di indignazione questa domenica prenatalizia nel Salento.\u00a0 La nostra nuova terra dei fuochi, martoriata con accanimento dalle realizzazioni di opera inutili, dannose, pericolose, devastanti, in un territorio che detiene il triste primato della desertificazione e dove, per citare l&#8217;oncologo Giuseppe Serravezza, non si potrebbe accendere neppure un [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":192360,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,75,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/192359"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=192359"}],"version-history":[{"count":10,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/192359\/revisions"}],"predecessor-version":[{"id":192371,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/192359\/revisions\/192371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/192360"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=192359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=192359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=192359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}