{"id":192448,"date":"2021-12-14T18:36:33","date_gmt":"2021-12-14T17:36:33","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=192448"},"modified":"2021-12-14T18:46:05","modified_gmt":"2021-12-14T17:46:05","slug":"omicidio-di-copertino-lindagato-resta-in-carcere","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/12\/14\/omicidio-di-copertino-lindagato-resta-in-carcere\/","title":{"rendered":"OMICIDIO DI COPERTINO, L&#8217;INDAGATO RESTA IN CARCERE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-192452\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/unnamed-10.jpg\" alt=\"\" width=\"512\" height=\"260\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/unnamed-10.jpg 512w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/unnamed-10-300x152.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/p>\n<p>(e.l.)______Si \u00e8 tenuta oggi a Borgo San Nicola\u00a0(nella foto)\u00a0l&#8217;interrogatorio di garanzia di Michele Aportone, 70 anni, di San\u00a0Donaci, indagato quale assassino dell&#8217;ex maresciallo dei Carabinieri Silvano Nestola, 45 anni, di Copertino e arrestato una seconda volta lo scorso 25 novembre.<\/p>\n<p>A differenza della prima volta, il Tribunale del Riesame &#8211; presidente Carlo Cazzella, relatore Giovanni Gallo, giudice a latere Pia Verderosa &#8211; ha rigettato il ricorso della difesa a questo secondo provvedimento della Procura della Repubblica di Lecce.<\/p>\n<p>Le ragioni del ricorso, sia di ordine procedurale, sia nel merito della questione, sono state esposte dall&#8217;avvocato Francesca Conte, alla quale per\u00f2 questa volta il Riesame ha dato torto.______<\/p>\n<p>LA RICERCA nei nostri articoli del 19, 20 e 25 novembre scorsi<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"fWHpwLW81f\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/11\/19\/omicidio-di-copertino-limputato-torna-libero\/\">OMICIDIO DI COPERTINO, L&#8217;IMPUTATO TORNA LIBERO<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/11\/19\/omicidio-di-copertino-limputato-torna-libero\/embed\/#?secret=fWHpwLW81f\" data-secret=\"fWHpwLW81f\" width=\"500\" height=\"282\" title=\"&#8220;OMICIDIO DI COPERTINO, L&#8217;IMPUTATO TORNA LIBERO&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"Eefucpatru\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/11\/20\/approfondimento-lomicidio-nestola-e-lannullamento-dellordinanza-cautelare-disposta-dal-gip\/\">L&#8217;APPROFONDIMENTO \/ L&#8217;OMICIDIO DI COPERTINO E L&#8217;ANNULLAMENTO DELL&#8217;ORDINANZA CAUTELARE DISPOSTO IERI DAL TRIBUNALE DEL RIESAME<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/11\/20\/approfondimento-lomicidio-nestola-e-lannullamento-dellordinanza-cautelare-disposta-dal-gip\/embed\/#?secret=Eefucpatru\" data-secret=\"Eefucpatru\" width=\"500\" height=\"282\" title=\"&#8220;L&#8217;APPROFONDIMENTO \/ L&#8217;OMICIDIO DI COPERTINO E L&#8217;ANNULLAMENTO DELL&#8217;ORDINANZA CAUTELARE DISPOSTO IERI DAL TRIBUNALE DEL RIESAME&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"zJMJSV7NIp\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/11\/25\/omicidio-di-copertino-lindagato-torna-in-carcere\/\">OMICIDIO DI COPERTINO, L&#8217;INDAGATO TORNA IN CARCERE<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/11\/25\/omicidio-di-copertino-lindagato-torna-in-carcere\/embed\/#?secret=zJMJSV7NIp\" data-secret=\"zJMJSV7NIp\" width=\"500\" height=\"282\" title=\"&#8220;OMICIDIO DI COPERTINO, L&#8217;INDAGATO TORNA IN CARCERE&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/12\/14\/omicidio-di-copertino-lindagato-resta-in-carcere\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/12\/14\/omicidio-di-copertino-lindagato-resta-in-carcere\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______Si \u00e8 tenuta oggi a Borgo San Nicola\u00a0(nella foto)\u00a0l&#8217;interrogatorio di garanzia di Michele Aportone, 70 anni, di San\u00a0Donaci, indagato quale assassino dell&#8217;ex maresciallo dei Carabinieri Silvano Nestola, 45 anni, di Copertino e arrestato una seconda volta lo scorso 25 novembre. A differenza della prima volta, il Tribunale del Riesame &#8211; presidente Carlo Cazzella, relatore Giovanni [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":192452,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/192448"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=192448"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/192448\/revisions"}],"predecessor-version":[{"id":192453,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/192448\/revisions\/192453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/192452"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=192448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=192448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=192448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}