{"id":19253,"date":"2013-08-01T10:00:08","date_gmt":"2013-08-01T10:00:08","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=19253"},"modified":"2013-08-01T10:59:42","modified_gmt":"2013-08-01T10:59:42","slug":"ancora-lecce-carpi-3-nuovi-arresti","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/01\/ancora-lecce-carpi-3-nuovi-arresti\/","title":{"rendered":"ANCORA LECCE-CARPI !!! 3 NUOVI ARRESTI"},"content":{"rendered":"<p style=\"text-align: left;\">Questa mattina, personale della Digos della Questura di Lecce ha notificato nr. 2 ordinanze di applicazione della misura degli arresti domiciliari nei confronti delle persone di seguito indicate:<\/p>\n<p style=\"text-align: left;\">\u2022 GIANNINI Simone, nato a Nard\u00f2 (LE) il 26.04.1985, residente a Lecce, in ordine alla contravvenzione di cui all\u2019 art. 6 bis, secondo comma, della legge n.401 del 1989 e s.m.i. ed al delitto di cui agli articoli 81, 337 e 339, commi 2 e 3 del Codice Penale, e 6-quater della L. nr. 401 del 1989 e s.m.i.;<\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/01\/ancora-lecce-carpi-3-nuovi-arresti\/giannini\/\" rel=\"attachment wp-att-19292\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/Giannini-300x89.jpg\" alt=\"\" title=\"Giannini\" width=\"300\" height=\"89\" class=\"alignleft size-medium wp-image-19292\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/Giannini-300x89.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/Giannini-1024x305.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>\u2022 DE MATTEIS Michel, nato a Copertino (LE) il 21.4.1987, ivi residente, in ordine alla contravvenzione di cui all\u2019art. 6 bis della legge n.401 del 1989 e s.m.i..<\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/01\/ancora-lecce-carpi-3-nuovi-arresti\/de-matteis\/\" rel=\"attachment wp-att-19293\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/De-Matteis-300x89.jpg\" alt=\"\" title=\"De Matteis\" width=\"300\" height=\"89\" class=\"alignleft size-medium wp-image-19293\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/De-Matteis-300x89.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/De-Matteis-1024x305.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: left;\">Contestualmente, in Firenze, personale di quella DIGOS, ha eseguito la medesima ordinanza nei confronti di:<\/p>\n<p style=\"text-align: left;\">\u2022 STEFANIZZI Massimiliano, nato a Firenze il 16.9.1979, ivi residente, per il delitto di cui agli articoli 81, 337 e 339, commi 2 e 3 del Codice Penale; 6-quater della L. nr. 401 del 1989 e s.m.i., nonch\u00e8 per l\u2019art. 6 bis, secondo comma, entrambe le ipotesi, della legge n.401 del 1989 e s.m.i..<\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/01\/ancora-lecce-carpi-3-nuovi-arresti\/stefanizzi\/\" rel=\"attachment wp-att-19294\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/Stefanizzi-300x89.jpg\" alt=\"\" title=\"Stefanizzi\" width=\"300\" height=\"89\" class=\"alignleft size-medium wp-image-19294\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/Stefanizzi-300x89.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/Stefanizzi-1024x305.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: left;\">I provvedimenti sono stati emessi essendo stati riscontrati gravi indizi di colpevolezza, a carico dei predetti, in occasione dell\u2019incontro di calcio \u201cLecce-Carpi\u201d del 16.6.2013, valevole per i Play-off di Lega Pro.<\/p>\n<p style=\"text-align: left;\">In particolare, Simone GIANNINI e Massimiliano Stefanizzi, dopo aver invaso il terreno di gioco, hanno partecipato all\u2019aggressione in danno di steward nella zona antistante le scale che adducono negli spogliatoi mentre Michel DE MATTEIS \u00e8 stato riconosciuto quale autore di lanci di pietre, all\u2019esterno dello stadio, in danno delle forze dell\u2019ordine.<\/p>\n<p style=\"text-align: left;\">I provvedimenti sono stati emessi dal Giudice per le Indagini Preliminari Dr.ssa Annalisa De Benerdictis su richiesta del Pubblico Ministero Dr. Massimiliano Carducci.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/01\/ancora-lecce-carpi-3-nuovi-arresti\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/01\/ancora-lecce-carpi-3-nuovi-arresti\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Questa mattina, personale della Digos della Questura di Lecce ha notificato nr. 2 ordinanze di applicazione della misura degli arresti domiciliari nei confronti delle persone di seguito indicate: \u2022 GIANNINI Simone, nato a Nard\u00f2 (LE) il 26.04.1985, residente a Lecce, in ordine alla contravvenzione di cui all\u2019 art. 6 bis, secondo comma, della legge n.401 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19269,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[44,42],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19253"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19253"}],"version-history":[{"count":15,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19253\/revisions"}],"predecessor-version":[{"id":19271,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19253\/revisions\/19271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19269"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=19253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=19253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=19253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}