{"id":192607,"date":"2021-12-17T00:06:52","date_gmt":"2021-12-16T23:06:52","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=192607"},"modified":"2021-12-30T10:35:50","modified_gmt":"2021-12-30T09:35:50","slug":"la-torre-colombaia-di-veglie","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/12\/17\/la-torre-colombaia-di-veglie\/","title":{"rendered":"LA TORRE COLOMBAIA DI VEGLIE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-192611\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/VE.jpg\" alt=\"\" width=\"736\" height=\"981\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/VE.jpg 736w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/VE-225x300.jpg 225w\" sizes=\"(max-width: 736px) 100vw, 736px\" \/>di <strong>Fabio Coppola______\u00a0<\/strong><\/p>\n<p>Un monumento attivo.<\/p>\n<p>E\u2019 ancora possibile ammirarla in esercizio. Regala agli occhi uno scenario insolito alla periferia del centro urbano. In via Realino Mazzotta a Veglie.<\/p>\n<p>Uno stormo di colombi che si alza in volo dalla torre colombaia appartenuta alla Masseria \u201cPanareo\u201d.<\/p>\n<p>Pianta quadrata, priva di copertura per permettere ingresso e uscita dei volatili. All\u2019esterno dotata di cordone marcapiano per impedire l\u2019accesso ai predatori. Di colore rosa per distinguerla a distanza da altri edifici. La carne dei colombi utilizzata per uso alimentare, il guano sfruttato come concime.<\/p>\n<p>Altre torri colombaie hanno forma cilindrica. Utilizzate gi\u00e0 in epoca romana. Il Codice di Maria d\u2019Enghien del 1445 regolamentava anche le torri colombaie, soggette a tassazione, e vietava la caccia con arco, balestra o reti a chi non fosse il proprietario.<\/p>\n<p>Piccole colombaie venivano realizzate anche sui tetti delle case in centro abitato, come quella al civico ventidue di via Garibaldi a Copertino.\u00a0In alcuni casi in stato di abbandono e degrado, in altri restaurate, come in via Giovanni Falcone a Lecce, al centro di un parco pubblico.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/12\/17\/la-torre-colombaia-di-veglie\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/12\/17\/la-torre-colombaia-di-veglie\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Fabio Coppola______\u00a0 Un monumento attivo. E\u2019 ancora possibile ammirarla in esercizio. Regala agli occhi uno scenario insolito alla periferia del centro urbano. In via Realino Mazzotta a Veglie. Uno stormo di colombi che si alza in volo dalla torre colombaia appartenuta alla Masseria \u201cPanareo\u201d. Pianta quadrata, priva di copertura per permettere ingresso e uscita [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":192611,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/192607"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=192607"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/192607\/revisions"}],"predecessor-version":[{"id":192612,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/192607\/revisions\/192612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/192611"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=192607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=192607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=192607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}