{"id":19303,"date":"2013-08-01T14:40:37","date_gmt":"2013-08-01T14:40:37","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=19303"},"modified":"2013-08-01T14:41:34","modified_gmt":"2013-08-01T14:41:34","slug":"terminal-quartett-al-lido-salapia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/01\/terminal-quartett-al-lido-salapia\/","title":{"rendered":"\u201cTERMINAL QUARTETT\u201d  AL LIDO SALAPIA"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/Unknown1.jpeg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/Unknown1.jpeg\" alt=\"\" width=\"259\" height=\"194\" class=\"alignleft size-full wp-image-19304\" \/><\/a>Sar\u00e0 il \u201cTerminal Quartett\u201d il protagonista del concerto ad ingresso gratuito che <strong>sabato 3 agosto<\/strong> alle 21.30 si terr\u00e0 al Lido Salapia di San Cataldo.<\/p>\n<p>Lo spettacolo, inserito nella rassegna \u201cLecc\u2019\u00e8\u201d del Comune di Lecce, \u00e8 organizzato dall\u2019Assessorato al Turismo, Spettacoli ed Eventi guidato da Luigi Coclite in collaborazione con il lido Salapia, e per la parte artistica \u00e8 curato dall\u2019associazione Nireo.<\/p>\n<p>Il \u201cTerminal Quartett\u201d, composto da dai talenti pi\u00f9 vivaci e dotati del Conservatorio leccese \u201cTito Schipa\u201d che si sono imposti all\u2019attenzione del pubblico con l\u2019entusiasmante e coinvolgente partecipazione alla trasmissione televisiva su Rai1 \u201cMattina in Famiglia\u201d, \u00e8 formato dalle clarinettiste Raffaella Palumbo e Anna Romito, dal fagottista Antonio De Santis e dal fisarmonicista Michele Bianco. Il gruppo eseguir\u00e0 brani di Cjajkovskij, Brahms, Rossini e Joplin e di altri autori appositamente elaborati da Vincenzo Rana, docente di Lettura della Partitura al Conservatorio.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/01\/terminal-quartett-al-lido-salapia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/01\/terminal-quartett-al-lido-salapia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Sar\u00e0 il \u201cTerminal Quartett\u201d il protagonista del concerto ad ingresso gratuito che sabato 3 agosto alle 21.30 si terr\u00e0 al Lido Salapia di San Cataldo. Lo spettacolo, inserito nella rassegna \u201cLecc\u2019\u00e8\u201d del Comune di Lecce, \u00e8 organizzato dall\u2019Assessorato al Turismo, Spettacoli ed Eventi guidato da Luigi Coclite in collaborazione con il lido Salapia, e per [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19304,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19303"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19303"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19303\/revisions"}],"predecessor-version":[{"id":19307,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19303\/revisions\/19307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19304"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=19303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=19303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=19303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}