{"id":193193,"date":"2021-12-31T13:35:31","date_gmt":"2021-12-31T12:35:31","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=193193"},"modified":"2021-12-31T13:35:31","modified_gmt":"2021-12-31T12:35:31","slug":"il-riepilogo-settimanale-sui-covid-positivi-40","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2021\/12\/31\/il-riepilogo-settimanale-sui-covid-positivi-40\/","title":{"rendered":"IL RIEPILOGO SETTIMANALE SUI COVID POSITIVI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-193194\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/asl-1-1.jpg\" alt=\"\" width=\"512\" height=\"253\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/asl-1-1.jpg 512w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/asl-1-1-300x148.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/p>\n<p>(Rdl)______L\u2019 Asl di\u00a0Lecce ha reso noto questa mattina il report epidemiologico aggiornato a\u00a0oggi, venerd\u00ec 31 dicembre, sui casi di positivi al Covid nella nostra\u00a0 provincia,\u00a0a cura del dottor Fabrizio Quarta, direttore dell\u2019 Unit\u00e0 Operativa Epidemiologia e Statistica.<\/p>\n<p>Nel report emerge l\u2019andamento statistico, con la distribuzione dei casi Comune per Comune, il numero dei degenti, dei ricoveri e dei decessi con la distinzione per genere ed et\u00e0, il numero dei tamponi complessivamente eseguiti e il trend settimanale del rapporto casi positivi\/casi testati;\u00a0sono inseriti anche i dati sui vaccinati, distribuiti in base al Comune di residenza.<\/p>\n<p>Sono 8023 i\u00a0cittadini presenti in provincia di Lecce attualmente Covid positivi. Erano 2085 venerd\u00ec scorso.<\/p>\n<p>Quindi si tratta di un dato di nuovo in crescita, per la decima volta e questa volta in maniera considerevole, dopo le precedenti sette settimane di fila di diminuzioni.<\/p>\n<p>Rimane per\u00f2 uguale il numero dei\u00a0ricoverati in ospedale, che sono sempre 50.<\/p>\n<p>&nbsp;<\/p>\n<p>I positivi al Covid erano 1211 due settimane fa, 878 tre settimane fa, 850 un mese fa.<\/p>\n<p>&nbsp;<\/p>\n<p>Situazione analoga a Lecce citt\u00e0: i positivi sono attualmente 1.283, erano 291 venerd\u00ec scorso, 149 due settimane fa, 96 tre settimane fa, 97 un mese fa.<\/p>\n<p>&nbsp;<\/p>\n<p>Sull\u2019intero territorio provinciale, la percentuale degli attualmente positivi passa dall\u2019 2,6\u00a0 al 10 positivi ogni mille abitanti, uno su cento della popolazione.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2021\/12\/Report_31.12.2021.pdf\">Report_31.12.2021<\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2021\/12\/31\/il-riepilogo-settimanale-sui-covid-positivi-40\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2021\/12\/31\/il-riepilogo-settimanale-sui-covid-positivi-40\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______L\u2019 Asl di\u00a0Lecce ha reso noto questa mattina il report epidemiologico aggiornato a\u00a0oggi, venerd\u00ec 31 dicembre, sui casi di positivi al Covid nella nostra\u00a0 provincia,\u00a0a cura del dottor Fabrizio Quarta, direttore dell\u2019 Unit\u00e0 Operativa Epidemiologia e Statistica. Nel report emerge l\u2019andamento statistico, con la distribuzione dei casi Comune per Comune, il numero dei degenti, dei [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":193194,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193193"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=193193"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193193\/revisions"}],"predecessor-version":[{"id":193196,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193193\/revisions\/193196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/193194"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=193193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=193193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=193193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}