{"id":193462,"date":"2022-01-11T00:02:44","date_gmt":"2022-01-10T23:02:44","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=193462"},"modified":"2022-01-10T14:14:32","modified_gmt":"2022-01-10T13:14:32","slug":"artisti-salentini-le-capacita-figurative-di-rita-franco","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/11\/artisti-salentini-le-capacita-figurative-di-rita-franco\/","title":{"rendered":"ARTISTI SALENTINI \/ LE CAPACITA&#8217; DI RITA FRANCO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-193463\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/rita-franco.jpg\" alt=\"\" width=\"500\" height=\"577\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/rita-franco.jpg 293w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/rita-franco-260x300.jpg 260w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>di <strong>Raffaele Polo<\/strong>______<\/p>\n<p>Non era facile per una donna, nel secolo scorso, riuscire a vincere difficolt\u00e0 e diffidenza e andare lontano da casa, per studiare disegno e pittura&#8230; I Franco di Lecce, peraltro, erano una famiglia predisposta verso le Arti, di buoni mezzi e ne \u00e8 riprova il successo di Carlo, ottimo musicista, che diventa direttore artistico del San Carlo di Napoli.<\/p>\n<p>A Napoli, perci\u00f2, pu\u00f2 arrivare la sorella Rita (1888-1986) che frequenta con entusiasmo l&#8217;Istituto di Belle Arti prima e poi la bottega di Casciaro, vero punto di riferimento per tutti i salentini che desiderano apprendere i rudimenti del mestiere di &#8216;artista&#8217; studiando nella patria dell&#8217;Arte, che per noi era Napoli.<\/p>\n<p>Ai modelli, alle tradizioni e alla cultura napoletana, del resto, si ispirano tutti i nostri maggiori esponenti che, prediligendo sovente pi\u00f9 spesso il pastello che l&#8217;olio, finiscono ad inspessire la folta schiera di quella &#8216;scuola napoletana&#8217; che appare anche nelle scelte dei soggetti, dove i paesaggi, le marine e i volti partenopei sono praticamente obbligatori&#8230;<\/p>\n<p>La critica non \u00e8 stata mai tenera con questi fermenti che provenivano da Napoli e, pur riconoscendo la validit\u00e0 dell&#8217;insegnamento delle tecniche pittoriche, finisce per relegare molti capaci artisti in una semplice menzione, di trascurabile importanza.<\/p>\n<p>\u00c8 cos\u00ec che, essendo donna e facendo parte della &#8216;scuola napoletana&#8217;, <strong>Rita Franco<\/strong>\u00a0(nella foto di copertina),\u00a0ottiene tanti, importanti consensi: ma finisce presto nel dimenticatoio, proprio nella citt\u00e0 da cui proviene, Lecce (anche se \u00e8 nata a\u00a0 Gallipoli), che \u00e8 invece prodiga e riconoscente verso altri suoi coetanei.<\/p>\n<p>&nbsp;<\/p>\n<p>Le opere di Rita sono apprezzatissime nelle mostre alle quali partecipa e viene invitata. E i suoi pastelli, i paesaggi ma anche le nature morte, non sfigurano accanto ai pi\u00f9 noti artisti del momento. Attivissima e longeva, Rita non tradisce mai la &#8216;scuola&#8217; tradizionale da cui proviene, e propone la sua maestria e la capacit\u00e0 figurativa, senza lasciarsi sedurre da avanguardie e movimenti rivoluzionari.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-193464\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/FRANCO-RITA-pastello-su-carta-cm25x32-1024x777.jpg\" alt=\"\" width=\"1024\" height=\"777\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/FRANCO-RITA-pastello-su-carta-cm25x32-1024x777.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/FRANCO-RITA-pastello-su-carta-cm25x32-1024x777-300x228.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/FRANCO-RITA-pastello-su-carta-cm25x32-1024x777-768x583.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Dimostra un particolare interesse per i soggetti tradizionali che raffigurano la vita nei borghi e nei centri meno popolosi, trasformando l&#8217;idillio dei panorami e delle marine isolate con una chiara immersione nella vita semplice dei meno ricchi. E non \u00e8 un caso se i suoi dipinti su tali immagini siano apprezzati e premiati negli anni Venti (Impressioni di paese, Due interni, Un paese, la vita nel Paese).<\/p>\n<p>Sarebbe proprio il caso di riscoprire e rivalutare\u00a0 le opere di questa nostra artista.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/11\/artisti-salentini-le-capacita-figurative-di-rita-franco\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/11\/artisti-salentini-le-capacita-figurative-di-rita-franco\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Raffaele Polo______ Non era facile per una donna, nel secolo scorso, riuscire a vincere difficolt\u00e0 e diffidenza e andare lontano da casa, per studiare disegno e pittura&#8230; I Franco di Lecce, peraltro, erano una famiglia predisposta verso le Arti, di buoni mezzi e ne \u00e8 riprova il successo di Carlo, ottimo musicista, che diventa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":193463,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193462"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=193462"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193462\/revisions"}],"predecessor-version":[{"id":193466,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193462\/revisions\/193466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/193463"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=193462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=193462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=193462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}