{"id":193467,"date":"2022-01-10T15:10:10","date_gmt":"2022-01-10T14:10:10","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=193467"},"modified":"2022-01-10T15:52:44","modified_gmt":"2022-01-10T14:52:44","slug":"taranto-rapinatore-allassalto-di-unagenzia-di-scommesse-fugge-con-il-bottino","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/10\/taranto-rapinatore-allassalto-di-unagenzia-di-scommesse-fugge-con-il-bottino\/","title":{"rendered":"RAPINA A TARANTO AD UN&#8217;AGENZIA DI SCOMMESSE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-193468\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/9a67db6c-2921-11ec-a84f-0e11b896b99e_1200x675.jpg\" alt=\"\" width=\"1200\" height=\"675\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/9a67db6c-2921-11ec-a84f-0e11b896b99e_1200x675.jpg 1200w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/9a67db6c-2921-11ec-a84f-0e11b896b99e_1200x675-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/9a67db6c-2921-11ec-a84f-0e11b896b99e_1200x675-1024x576.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/9a67db6c-2921-11ec-a84f-0e11b896b99e_1200x675-768x432.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>(f.f.) ______<\/p>\n<p>Paura ieri sera a Lama, una borgata alle porte di Taranto, dove un uomo ha assaltato, pistola alla mano e con il volto coperto da una sciarpa, un\u2019agenzia di scommesse poco prima che chiudesse.<\/p>\n<p>Dopo aver minacciato il dipendente dell\u2019attivit\u00e0, intimandogli di consegnare l\u2019incasso, \u00e8 scappato con un bottino di 1.500 euro.<\/p>\n<p>&nbsp;<\/p>\n<p>Immediato l\u2019intervento dei Carabinieri del Comando provinciale, che, ricevuta la segnalazione, hanno raccolto la testimonianza dell&#8217;impiegato, ed hanno avviato le indagini per risalire all\u2019identit\u00e0 del rapinatore..<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/10\/taranto-rapinatore-allassalto-di-unagenzia-di-scommesse-fugge-con-il-bottino\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/10\/taranto-rapinatore-allassalto-di-unagenzia-di-scommesse-fugge-con-il-bottino\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.) ______ Paura ieri sera a Lama, una borgata alle porte di Taranto, dove un uomo ha assaltato, pistola alla mano e con il volto coperto da una sciarpa, un\u2019agenzia di scommesse poco prima che chiudesse. Dopo aver minacciato il dipendente dell\u2019attivit\u00e0, intimandogli di consegnare l\u2019incasso, \u00e8 scappato con un bottino di 1.500 euro. &nbsp; [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":193468,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193467"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=193467"}],"version-history":[{"count":7,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193467\/revisions"}],"predecessor-version":[{"id":193475,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193467\/revisions\/193475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/193468"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=193467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=193467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=193467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}