{"id":193494,"date":"2022-01-11T11:33:50","date_gmt":"2022-01-11T10:33:50","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=193494"},"modified":"2022-01-11T11:35:00","modified_gmt":"2022-01-11T10:35:00","slug":"botte-e-droga-in-un-centro-di-recupero-per-minori-a-latiano-indagato-un-operatore","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/11\/botte-e-droga-in-un-centro-di-recupero-per-minori-a-latiano-indagato-un-operatore\/","title":{"rendered":"BOTTE E DROGA IN UN CENTRO DI RECUPERO PER MINORI A LATIANO, INDAGATO UN GIOVANE &#8216;EDUCATORE&#8217;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-193498\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/buppro.jpg\" alt=\"\" width=\"512\" height=\"242\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/buppro.jpg 512w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/buppro-300x142.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/p>\n<p>di <strong>Flora Fina<\/strong>\u00a0______<\/p>\n<p>Nel pomeriggio di ieri, i Carabinieri del Comando Compagnia di San Vito dei Normanni hanno accertato, grazie alle indagini disposte dalla Procura della Repubblica di Brindisi\u00a0(nella foto),\u00a0che un giovane di 26 anni originario di Sandonaci, ex educatore in un centro di recupero per minori di Latiano presso cui aveva prestato servizio, era stato invece dedito allo spaccio di droga e a maltrattamenti su minori, proprio all\u2019interno della comunit\u00e0.<\/p>\n<p>I fatti, risalgono al periodo che va dal novembre 2018al maggio 2019, quando il presunto spacciatore ha ceduto sostanze stupefacenti di vario tipo \u2013 in particolare marijuana e cocaina &#8211; ai minori ospiti del centro educativo. Non solo: \u00e8 emerso inoltre dalle indagini che sono stati numerosi gli episodi di maltrattamenti da parte dell\u2019 \u201ceducatore\u201d che non ha esitato ad usare violenza gratuita nei confronti di un ragazzino ospite del centro di recupero, che si era per l\u2019appunto rifiutato di acquistare e consumare la droga venduta dal presunto spacciatore.<\/p>\n<p>Le indagini degli inquirenti hanno portato alla luce episodi di violenza verbale e fisica, fatta di botte, morsi e graffi sulla schiena della vittima, accompagnati dall\u2019appellativo di \u201cinfame\u201d per aver confidato ai genitori la malsana situazione che si viveva nella comunit\u00e0.<\/p>\n<p>In seguito all\u2019attivit\u00e0 investigativa partita a seguito delle denunce da parte del minore, l&#8217;indagato\u00a0 si trova ora su disposizione dell\u2019autorit\u00e0 giudiziaria in regime di obbligo di dimora con le accuse di maltrattamenti su minore e spaccio e detenzione di sostanze stupefacenti, mentre per gli altri educatori del centro non sono state accertate responsabilit\u00e0.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/11\/botte-e-droga-in-un-centro-di-recupero-per-minori-a-latiano-indagato-un-operatore\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/11\/botte-e-droga-in-un-centro-di-recupero-per-minori-a-latiano-indagato-un-operatore\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Flora Fina\u00a0______ Nel pomeriggio di ieri, i Carabinieri del Comando Compagnia di San Vito dei Normanni hanno accertato, grazie alle indagini disposte dalla Procura della Repubblica di Brindisi\u00a0(nella foto),\u00a0che un giovane di 26 anni originario di Sandonaci, ex educatore in un centro di recupero per minori di Latiano presso cui aveva prestato servizio, era [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":193498,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193494"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=193494"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193494\/revisions"}],"predecessor-version":[{"id":193501,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193494\/revisions\/193501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/193498"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=193494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=193494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=193494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}