{"id":193621,"date":"2022-01-15T10:18:46","date_gmt":"2022-01-15T09:18:46","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=193621"},"modified":"2022-01-15T10:20:21","modified_gmt":"2022-01-15T09:20:21","slug":"sgominata-banda-di-trafficanti-di-opere-darte","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/15\/sgominata-banda-di-trafficanti-di-opere-darte\/","title":{"rendered":"SGOMINATA BANDA DI TRAFFICANTI DI OPERE D&#8217;ARTE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-193622\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/dipinti-falsi-mauro-reggiani.jpg\" alt=\"\" width=\"754\" height=\"475\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/dipinti-falsi-mauro-reggiani.jpg 754w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/dipinti-falsi-mauro-reggiani-300x189.jpg 300w\" sizes=\"(max-width: 754px) 100vw, 754px\" \/>(e.l.) ______I Carabinieri del Nucleo Tutela Patrimonio Culturale di Bari\u00a0(nella foto), a conclusione di una lunga e\u00a0complessa attivit\u00e0 investigativa, coordinata dalla Procura della Repubblica di Lecce, ha<br \/>\naccertato l&#8217;esistenza di un gruppo criminale, composto da mercanti d\u2019arte, collezionisti e<br \/>\nspeculatori occasionali, avente ramificazioni in tutta Italia.<\/p>\n<p>Era stata creata una vera e propria\u00a0rete commerciale di ricettazione e commercializzazione di opere d&#8217;arte false e\/o\u00a0contraffatte, attribuite al maestro Mauro Reggiani (Nonantola 1897 \u2013 Milano 1980), uno dei\u00a0massimi esponenti dell\u2019astrattismo in Italia.<\/p>\n<p>Le indagini, che duravano da tre anni, grazie alla segnalazione dell\u2019Associazione per la tutela<br \/>\ndelle opere di Mauro Reggiani che denunciava un\u2019insolita e continua richiesta di verifica di<br \/>\nautentiche di dipinti, hanno permesso di accertare che opere falsamente attribuite<br \/>\nall\u2019artista venivano immesse sul mercato nazionale grazie alla complicit\u00e0 di gallerie,<br \/>\ncollezionisti privati e mercanti d\u2019arte, prevalentemente attraverso l\u2019utilizzo di piattaforme<br \/>\n\u201ce-commerce\u201d, eludendo cos\u00ec le norme vigenti sull\u2019esercizio del commercio.<\/p>\n<p>Il ruolo\u00a0fondamentale della sodalizio criminale, veniva svolto da un mercante abruzzese che,<br \/>\nattraverso una serie di intermediari su tutto il territorio nazionale, aveva messo in<br \/>\ncircolazione un numero indefinito di beni d\u2019arte falsi.<\/p>\n<p>Le opere, risultate copie di dipinti autentici, erano riproduzioni estrapolate dal catalogo<br \/>\ngenerale delle opere di Mauro Reggiani, pubblicato in bianco e nero negli anni Novanta<br \/>\ngeometricamente identiche a quelle catalogate, ma con colorazioni diverse da quelle<br \/>\noriginali.<br \/>\nLe opere sequestrate, proposte in commercio a prezzi compresi tra 15.000 e 70.000 euro,<br \/>\navrebbero fruttato oltre un milione di euro.<\/p>\n<p>Moltissime le vittime del raggiro che si sono<br \/>\nritrovate in casa dipinti falsi pagati migliaia di euro.<br \/>\nLe opere sono state sequestrate nelle province di Lecce, Napoli, Perugia, Teramo, Cagliari,<br \/>\nMilano, Firenze, Roma, Alessandria, Como, Modena, Cesena, Ferrara, Brescia, Savona,<br \/>\nPadova e La Spezia, con la collaborazione dell\u2019Arma territoriale e dei Nuclei TPC<br \/>\nterritorialmente competenti.<\/p>\n<p>Ci sono\u00a0ventitr\u00e9 persone denunciate a piede libero con le accuse di\u00a0ricettazione, e di aver posto in circolazione opere d\u2019arte\u00a0false.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/15\/sgominata-banda-di-trafficanti-di-opere-darte\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/15\/sgominata-banda-di-trafficanti-di-opere-darte\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______I Carabinieri del Nucleo Tutela Patrimonio Culturale di Bari\u00a0(nella foto), a conclusione di una lunga e\u00a0complessa attivit\u00e0 investigativa, coordinata dalla Procura della Repubblica di Lecce, ha accertato l&#8217;esistenza di un gruppo criminale, composto da mercanti d\u2019arte, collezionisti e speculatori occasionali, avente ramificazioni in tutta Italia. Era stata creata una vera e propria\u00a0rete commerciale di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":193622,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193621"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=193621"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193621\/revisions"}],"predecessor-version":[{"id":193624,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193621\/revisions\/193624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/193622"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=193621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=193621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=193621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}