{"id":193859,"date":"2022-01-20T14:52:17","date_gmt":"2022-01-20T13:52:17","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=193859"},"modified":"2022-01-20T14:53:43","modified_gmt":"2022-01-20T13:53:43","slug":"furto-di-dati-sul-web-la-guardia-di-finanza-smaschera-organizzazione-criminale-l-sicurezza-su-internet-e-diventato-un-problema-prioritario","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/20\/furto-di-dati-sul-web-la-guardia-di-finanza-smaschera-organizzazione-criminale-l-sicurezza-su-internet-e-diventato-un-problema-prioritario\/","title":{"rendered":"FURTO DI DATI SUL WEB: LA GUARDIA DI FINANZA SMASCHERA ORGANIZZAZIONE CRIMINALE. LA SICUREZZA DI INTERNET E&#8217; DIVENTATO UN PROBLEMA PRIORITARIO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-193860\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/2020_guardia_finanza_intercettazioni.jpeg\" alt=\"\" width=\"670\" height=\"341\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/2020_guardia_finanza_intercettazioni.jpeg 670w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/2020_guardia_finanza_intercettazioni-300x153.jpeg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/p>\n<p>di <strong>Flora Fina<\/strong> ______<\/p>\n<p>Nella giornata odierna e nell\u2019ambito di un\u2019 articolata ed innovativa indagine, i finanzieri del Nucleo Speciale Tutela Privacy e Frodi Tecnologiche \u2013 coordinati dal IV Dipartimento della Procura della Repubblica di Milano \u2013 hanno portato a termine un\u2019 importante operazione per sgominare un\u2019 organizzazione che, da anni, faceva del traffico illecito di dati personali diffusi poi sul web\u00a0 &#8211; a discapito di ignari cittadini \u2013 il suo &#8216;cavallo di battaglia&#8217;.<\/p>\n<p>&nbsp;<\/p>\n<p>Sono state migliaia le generalit\u00e0 \u2013 nomi, cognomi, numeri di telefono, indirizzi &#8211; sottratte con l\u2019inganno, attraverso un sistema articolato pronto ad eludere le impostazioni di sicurezza sulla privacy, e aggirare cos\u00ec \u00a0le normative a tutela dei dati personali dei consumatori, ottenendo cos\u00ec\u00a0 senza vincoli di preziose liste di clienti a cui sottoporre i propri prodotti.<\/p>\n<p>Il bacino delle potenziali vittime veniva selezionato tra gli acquirenti di opere d\u2019arte e numismatica di rinomate aziende del settore. Non solo: l\u2019enorme quantit\u00e0 di dati sensibili raccolti veniva poi sottratta, catalogata e commercializzata, mediante apposite societ\u00e0 \u201cschermo\u201d costituite all\u2019estero e intestate a dei prestanome.<\/p>\n<p>&nbsp;<\/p>\n<p>Il modus operandi di volta in volta in volta non cambiava.<\/p>\n<p>Dalle indagini \u00e8 emerso chiaramente che gli indagati arrivavano a presentarsi telefonicamente come agenti della nota Enciclopedia Treccani, per promuovere in maniera subdola ai malcapitati, con la scusa di rivalutare le opere d\u2019arte gi\u00e0 in loro possesso, la vendita di quadri, enciclopedie e altri prodotti una volta fissato l\u2019appuntamento.<\/p>\n<p>Un sistema criminale difficile da individuare, se non grazie a strumenti di indagine ad alta tecnologia e strumenti di investigazione avanzata, di cui si \u00e8 avvalsa la Guardia di Finanza per porre fine all\u2019enorme furto di dati ancora in corso.<\/p>\n<p>Il giro d\u2019affari che \u00e8 emerso dalle indagini ammonta a centinaia di migliaia di euro: numerose le perquisizioni effettuate poi nelle province di Napoli, Caserta e Milano.<\/p>\n<p>I fatti per la loro gravit\u00e0 sono stati segnalati anche all\u2019Autorit\u00e0 Garante per la protezione dei dati personali con richiesta di avviare il procedimento istruttorio propedeutico all\u2019applicazione di\u00a0 sanzioni pecuniarie.<\/p>\n<p>&nbsp;<\/p>\n<p>Furto di dati dunque, riciclo, riutilizzo e commercio. Non siamo per\u00f2 davanti ad un bene materiale, bens\u00ec davanti a qualcosa di immateriale, volatile potremmo dire.<\/p>\n<p>Come \u00e8 chiaro ormai da tantissimo tempo, siamo dunque nell\u2019era della tecnologia \u201cviolenta\u201d : violenta perch\u00e9 l\u2019attaccamento dell\u2019ordinaria popolazione ai sistemi informatici e smart \u00e8 diventata prerogativa di tutti i giorni, \u00e8 difficile staccarsene. Il flusso di dati continui in entrata ed in uscita sulle reti di internet ha fatto s\u00ec che la nuova societ\u00e0 potesse essere basata solo ed esclusivamente &#8211; purtroppo &#8211; su fondamenta cybernetiche, asettiche, con contorni ben definiti.<\/p>\n<p>Un privilegio questo, per la societ\u00e0, che progredisce, avanza, viene a conoscenza di qualsiasi evento \u2013 anche dall\u2019altra parte del mondo \u2013 nell\u2019immediato.<\/p>\n<p>Tuttavia, il progresso si sa,\u00a0 porta sempre con s\u00e9 grossi rischi, e non \u00e8 una novit\u00e0 che il furto di dati sia tra i reati del nuovo millennio il pi\u00f9 gettonato, perch\u00e9 \u00e8 semplice ed immediato, &#8220;basta un click&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Salta subito all\u2019occhio una considerazione: il furto dei dati sensibili negli ultimi anni di progresso tecnologico che stiamo vivendo, ha fatto s\u00ec che nascessero \u2013 e per fortuna \u2013 normative ad hoc per la protezione dei dati personali, questo perch\u00e9 perpetrare truffe che viaggiano alla velocit\u00e0 della luce sulla rete, consente di arricchirsi di qualcosa che \u00e8 ben pi\u00f9 del semplice denaro.<\/p>\n<p>Il dato sensibile, il concetto di privacy, sono nel 2022, quanto di pi\u00f9 sacro possa esistere, tuttavia, questi concetti sono facilmente sdoganati da tutte quelle strutture teoriche dell\u2019ipersocialit\u00e0 che corre sul web: come possiamo sperare di essere al sicuro se gi\u00e0 tutti i nostri dati vengono quotidianamente riversati \u2013 da noi stessi &#8211; sui social, su siti per acquisti online, tramite geolocalizzazione, tramite l\u2019utilizzo di dispositivi che si avvalgono dell\u2019 intelligenza artificiale per profilare i nostri gusti persino in fatto di cucina?<\/p>\n<p>Ebbene, il tema \u00e8 spinoso e lascia spazio ad ampissime riflessioni, una in particolare: le tecnologie sono fonte di gioia, di comodit\u00e0, di felice pigrizia e spensieratezza, tutte sorrette \u201csaldamente\u201d da fondamenta di gesso: le fondamenta della sicurezza, della riservatezza personale, della tanto declamata privacy.<\/p>\n<p>Ci si chiede allora se il gioco possa davvero valere la candela, e se nel mondo d\u2019oggi, siamo ancora disposti a barattare la nostra intimit\u00e0 sociale con la comodit\u00e0 fornita \u2013 a caratteri cubitali, pesanti, prepotenti &#8211; dal grande colosso chiamato Internet.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/20\/furto-di-dati-sul-web-la-guardia-di-finanza-smaschera-organizzazione-criminale-l-sicurezza-su-internet-e-diventato-un-problema-prioritario\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/20\/furto-di-dati-sul-web-la-guardia-di-finanza-smaschera-organizzazione-criminale-l-sicurezza-su-internet-e-diventato-un-problema-prioritario\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Flora Fina ______ Nella giornata odierna e nell\u2019ambito di un\u2019 articolata ed innovativa indagine, i finanzieri del Nucleo Speciale Tutela Privacy e Frodi Tecnologiche \u2013 coordinati dal IV Dipartimento della Procura della Repubblica di Milano \u2013 hanno portato a termine un\u2019 importante operazione per sgominare un\u2019 organizzazione che, da anni, faceva del traffico illecito [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":193860,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193859"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=193859"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193859\/revisions"}],"predecessor-version":[{"id":193864,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193859\/revisions\/193864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/193860"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=193859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=193859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=193859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}