{"id":193879,"date":"2022-01-21T00:03:33","date_gmt":"2022-01-20T23:03:33","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=193879"},"modified":"2022-01-21T16:56:03","modified_gmt":"2022-01-21T15:56:03","slug":"cronaca-di-una-ricetta-ecco-la-prima-buona-degustazione","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/21\/cronaca-di-una-ricetta-ecco-la-prima-buona-degustazione\/","title":{"rendered":"&#8220;CRONACA DI UNA RICETTA&#8221;, ECCO LA PRIMA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-193880\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/IMG-20220121-WA0010.jpg\" alt=\"\" width=\"750\" height=\"394\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/IMG-20220121-WA0010.jpg 750w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/IMG-20220121-WA0010-300x158.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>di <strong>Zia Eli______\u00a0<\/strong><\/p>\n<p>A carnevale ogni scherzo vale!<\/p>\n<p>E invece no! Non \u00e8 uno scherzo, da oggi sulla nostra pagina web inauguriamo la nuova rubrica di cucina:<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Cronaca di una ricetta&#8221;<\/p>\n<p>&nbsp;<\/p>\n<p>Abbiamo detto carnevale? E allora chiacchiere, cenci, bug\u00ece, frappe. Chiamatele come volete, ma usate la nostra ricetta.\u00a0 Vi piacer\u00e0.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-193881\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/IMG-20220121-WA0011.jpg\" alt=\"\" width=\"1900\" height=\"646\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/IMG-20220121-WA0011.jpg 1900w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/IMG-20220121-WA0011-300x102.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/IMG-20220121-WA0011-1024x348.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/IMG-20220121-WA0011-768x261.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/IMG-20220121-WA0011-1536x522.jpg 1536w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/><\/p>\n<p>Ingredienti<\/p>\n<p>\u2022700 g di farina 00<\/p>\n<p>&nbsp;<\/p>\n<p>\u20225 uova<\/p>\n<p>&nbsp;<\/p>\n<p>\u2022Un pizzico di sale<\/p>\n<p>&nbsp;<\/p>\n<p>\u2022Un pizzico di zucchero<\/p>\n<p>&nbsp;<\/p>\n<p>\u2022100 g di burro o margarina<\/p>\n<p>&nbsp;<\/p>\n<p>\u20222 cucchiai di grappa<\/p>\n<p>&nbsp;<\/p>\n<p>\u2022Buccia di limone e un po\u2019 di scorza di arancia grattugiate<\/p>\n<p>&nbsp;<\/p>\n<p>\u2022Zucchero a velo in grande quantit\u00e0<\/p>\n<p>&nbsp;<\/p>\n<p>\u2022Olio di semi di girasole per friggere.<\/p>\n<p>&nbsp;<\/p>\n<p>Capiente pentola per frittura.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-193882\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/IMG-20220118-WA0025.jpg\" alt=\"\" width=\"750\" height=\"681\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/IMG-20220118-WA0025.jpg 750w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/IMG-20220118-WA0025-300x272.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>Unite tutti gli ingredienti e formate un panetto.<\/p>\n<p>Avvolgetelo nella pellicola e lasciatelo riposare per una mezz\u2019ora a temperatura ambiente.<\/p>\n<p>Ora tagliate l\u2019impasto in piccole parti e con l\u2019aiuto di una macchina per la pasta (la mitica nonna papera) iniziate a stendere.<\/p>\n<p>Ricordate che per averle molto bollose, dovete passarle e ripassarle almeno 5\/6 volte. (devono acquisire aria).<\/p>\n<p>A noi piacciono super sottili, quindi dopo la nonna papera, gli diamo comunque una ripassatina sotto il mattarello\u00a0(con olio di gomito)<\/p>\n<p>Con l\u2019aiuto di un tagliapasta (detto anche rotella), tira delle linee orizzontali e poi verticali. (crea dei rettangoli o dei quadrati) .<\/p>\n<p>Fate un piccolo taglio nel mezzo e la chiacchiera \u00e8 pronta. (potete anche metterci un po\u2019 di fantasia e creare dei fiocchi o delle mascherine.)<\/p>\n<p>&nbsp;<\/p>\n<p>Friggere immediatamente in olio bollente . Girare e rigirare fino a doratura, occhio a non bruciarle.<\/p>\n<p>Scolatele dall\u2019olio e adagiatele su carta assorbente pochi secondi.<\/p>\n<p>Successivamente ponetele su un piatto da portata e spolverizzate zucchero a velo \u201ccome se non ci fosse un domani\u201d!<\/p>\n<p>E ricorda che per le chiacchiere il motto \u00e8: se non ti lecchi le dita, godi solo a met\u00e0!<\/p>\n<p>Buona degustazione!<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-193883\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/IMG-20220121-WA0008.jpg\" alt=\"\" width=\"750\" height=\"425\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/IMG-20220121-WA0008.jpg 750w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/IMG-20220121-WA0008-300x170.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/21\/cronaca-di-una-ricetta-ecco-la-prima-buona-degustazione\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/21\/cronaca-di-una-ricetta-ecco-la-prima-buona-degustazione\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Zia Eli______\u00a0 A carnevale ogni scherzo vale! E invece no! Non \u00e8 uno scherzo, da oggi sulla nostra pagina web inauguriamo la nuova rubrica di cucina: &nbsp; &#8220;Cronaca di una ricetta&#8221; &nbsp; Abbiamo detto carnevale? E allora chiacchiere, cenci, bug\u00ece, frappe. Chiamatele come volete, ma usate la nostra ricetta.\u00a0 Vi piacer\u00e0. Ingredienti \u2022700 g [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193879"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=193879"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193879\/revisions"}],"predecessor-version":[{"id":193888,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/193879\/revisions\/193888"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=193879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=193879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=193879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}