{"id":194022,"date":"2022-01-24T13:20:46","date_gmt":"2022-01-24T12:20:46","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=194022"},"modified":"2022-01-24T13:48:51","modified_gmt":"2022-01-24T12:48:51","slug":"mafia-maxi-seuqestro-di-5-milioni-per-un-imprenditore-tarantino","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/24\/mafia-maxi-seuqestro-di-5-milioni-per-un-imprenditore-tarantino\/","title":{"rendered":"MAXI SEQUESTRO DA 5 MILIONI PER UN IMPRENDITORE TARANTINO CONDANNATO PER MAFIA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-194024\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/DIA.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/DIA.jpg 1280w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/DIA-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/DIA-1024x576.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/01\/DIA-768x432.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>(f.f.) ______<\/p>\n<p>Nella giornata di oggi, la Direzione Investigativa Antimafia di Lecce ha eseguito a Taranto e provincia un decreto di confisca di beni, emesso dal Tribunale di Lecce: il patrimonio confiscato, di oltre cinque milioni di euro \u00e8 attribuibile all\u2019imprenditore Giuseppe Catapano, 53 anni, gi\u00e0 condannato in precedenza ed in via definitiva per associazione di stampo mafioso, estorsione e violazione sulla disciplina di detenzione di armi.<\/p>\n<p>Le indagini della Dia, hanno messo in luce, grazie al coordinamento da parte del Dda di Lecce, un comportamento da parte dell\u2019indagato socialmente pericoloso.<\/p>\n<p>Secondo le indagini degli inquirenti, l\u2019imprenditore non aveva formalmente dichiarato redditi sufficienti a giustificare le sue rilevanti disponibilit\u00e0 economiche, tuttavia era comunque riuscito ad accrescere il suo patrimonio ricorrendo all\u2019intestazione dei beni mobili ed immobili ad un prestanome.<\/p>\n<p>Tra gli innumerevoli beni confiscati: due ville, un immobile ad uso abitativo, otto magazzini e un terreno, ubicati a Taranto, Castellaneta Marina e Martina Franca,\u00a0 oltre al 50% delle quote societarie, cinque compendi aziendali nel settore dei mitili e frutti di mare, cinque auto, tre motocicli e cinque rapporti finanziari.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/24\/mafia-maxi-seuqestro-di-5-milioni-per-un-imprenditore-tarantino\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/01\/24\/mafia-maxi-seuqestro-di-5-milioni-per-un-imprenditore-tarantino\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.) ______ Nella giornata di oggi, la Direzione Investigativa Antimafia di Lecce ha eseguito a Taranto e provincia un decreto di confisca di beni, emesso dal Tribunale di Lecce: il patrimonio confiscato, di oltre cinque milioni di euro \u00e8 attribuibile all\u2019imprenditore Giuseppe Catapano, 53 anni, gi\u00e0 condannato in precedenza ed in via definitiva per associazione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":194024,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/194022"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=194022"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/194022\/revisions"}],"predecessor-version":[{"id":194033,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/194022\/revisions\/194033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/194024"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=194022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=194022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=194022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}