{"id":19403,"date":"2013-08-02T16:56:29","date_gmt":"2013-08-02T16:56:29","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=19403"},"modified":"2013-08-02T16:56:29","modified_gmt":"2013-08-02T16:56:29","slug":"il-truffatore-colpisce-anche-in-chiesa","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/02\/il-truffatore-colpisce-anche-in-chiesa\/","title":{"rendered":"IL TRUFFATORE COLPISCE ANCHE IN CHIESA"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/PELLEGRINO-Giovanni-Luigi.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/PELLEGRINO-Giovanni-Luigi-222x300.jpg\" alt=\"\" width=\"222\" height=\"300\" class=\"alignleft size-medium wp-image-19272\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/PELLEGRINO-Giovanni-Luigi-222x300.jpg 222w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/PELLEGRINO-Giovanni-Luigi.jpg 448w\" sizes=\"(max-width: 222px) 100vw, 222px\" \/><\/a>Alle ore 17.40., in Via 95\u00b0 Reggimento Fanteria nr. 70 presso l\u2019attivit\u00e0 commerciale \u201cClio s.p.a.\u201d veniva segnalata una truffa consumata.<\/p>\n<p>L\u2019equipaggio della Sezione Volanti, giunto sul posto, apprendeva dalla richiedente che circa un ora prima del loro arrivo si era presentato in negozio un ragazzo alto circa 1.75, corporatura normale, vestito con pantaloni blu , ed una maglietta di colore scuro il quale, dopo essersi presentato quale rappresentante di una ditta di servizi, le aveva chiesto la somma di 100 \u20ac per una sponsorizzazione presso un noto centro sportivo della citt\u00e0, specificando che il proprietario del negozio era gi\u00e0 a conoscenza dell\u2019affare.<\/p>\n<p>Diffidando dell\u2019uomo, la commessa aveva contattato direttamente il proprietario sul cellulare passandogli il procacciatore di affari e nel frattempo si accingeva a rilasciare uno scontrino ad un cliente che aveva depositato sul bancone 100,00 euro. Approfittando della distrazione della commessa, il procacciatore di affari, interrompendo la telefonata, si impossessava dei 100,00 euro sul bancone per poi allontanarsi velocemente dal negozio, a bordo della propria autovettura Fiat Bravo di colore bourdeaux.<\/p>\n<p>Agli agenti non occorrevano altri particolari per comprendere che l\u2019autore della truffa, assolutamente analoga a quella avvenuta il giorno precedente era Pellegrino Giovanni, un leccese del\u201971 , che negli ultimi giorni non aveva fatto altro che andare in giro per esercizi commerciali truffando proprietari e dipendenti e gi\u00e0 pi\u00f9 volte denunciato.<\/p>\n<p>Diramate immediatamente le ricerche il Pellegrino veniva rintracciato alle successive ore ore 18.15 nella medesima via dove era stato perpetrato il furto, mentre stava uscendo dal negozio \u201cSchonhuber\u201d.<\/p>\n<p>Al fine di meglio chiarire il motivo della presenza del PELLEGRINO in quel luogo, veniva ascoltato il titolare dell\u2019attivit\u00e0 \u201cSchonhuber\u201d, di Via 95\u00b0 Reg. Fanteria che riferiva di essere stato avvicinato dall\u2019uomo fermato dalla polizia, il quale dopo aver chiesto se fosse presente il \u201c grande capo\u201d, faceva richiesta di consegnargli 100 \u20ac in cambio di un logo pubblicitario da apporre presso il solito noto centro sportivo di Lecce. Ricevuta una categorica risposta negativa, il PELLEGRINO si dileguava velocemente ma veniva subito rintracciato e sottoposto a perquisizione personale, estesa all\u2019autovettura, nella quale, occultato sotto il sedile anteriore lato passeggero, veniva trovato un coltello con lama in metallo e manico in plastica di colore rosso lungo 17,5 cm ed un\u2019agenda con riportati all\u2019interno diversi timbri riconducibili a probabili aziende truffate.<\/p>\n<p>Nel mentre si effettuavano ulteriori accertamenti presso il su menzionato negozio, gli operatori venivano avvicinati da un uomo che raccontava di aver subito anche lui un tentativo di truffa da parte del PELLEGRINO Giovanni all\u2019interno dell\u2019agenzia immobiliare \u201cMazzini\u201d di cui \u00e8 dipendente, sempre con le stesse modalit\u00e0 dell\u2019offerta di pubblicit\u00e0.<\/p>\n<p>Alla luce di quanto accaduto Pellegrino Giovanni veniva posto agli arresti domiciliari per TRUFFA CONTINUATA E PORTO INGIUSTIFICATO DI ARNESI ATTI AD OFFENDERE.<\/p>\n<p>Aveva scelto un obbiettivo curioso come una parrocchia, P.G., 42 anni originario di Lecce, una sfilza di reati collezionati nel corso del tempo a cominciare dalle truffe. E proprio di una di queste era rimasto vittima un parroco di Campi Salentina. Tutto si \u00e8 svolto il 12 luglio scorso. PG. si era recato infatti direttamente dal sacerdote, fingendosi rappresentante di cera: una sostanza di uso ordinario in chiesa, e dunque la possibilit\u00e0 di far subito presa sull&#8217;interlocutore. I giusti convenevoli e poi l&#8217;accordo: 95\u20ac in contanti subito (ovviamente con regolare ricevuta) e la consegna immediata della merce. Solo che al pagamento non \u00e8 seguita alcuna consegna, perch\u00e9 il presunto rappresentante si \u00e8 subito dileguato; ci\u00f2, non prima di aver rilasciato al malcapitato prete regolare fattura falsa a nome di una inesistente cereria del basso Salento. Informati della cosa, i Carabinieri della Stazione di Campi Salentina hanno per\u00f2 ricostruito rapidamente la vicenda grazie a testimonianze e analisi delle tecniche di raggiro pi\u00f9 note, e si sono messi sulle tracce del truffatore, identificandolo in breve tempo. Per lui \u00e8 scattata la denuncia alla Procura della Repubblica presso il Tribunale di Lecce.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/02\/il-truffatore-colpisce-anche-in-chiesa\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/02\/il-truffatore-colpisce-anche-in-chiesa\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Alle ore 17.40., in Via 95\u00b0 Reggimento Fanteria nr. 70 presso l\u2019attivit\u00e0 commerciale \u201cClio s.p.a.\u201d veniva segnalata una truffa consumata. L\u2019equipaggio della Sezione Volanti, giunto sul posto, apprendeva dalla richiedente che circa un ora prima del loro arrivo si era presentato in negozio un ragazzo alto circa 1.75, corporatura normale, vestito con pantaloni blu , [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19272,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19403"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19403"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19403\/revisions"}],"predecessor-version":[{"id":19405,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19403\/revisions\/19405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19272"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=19403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=19403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=19403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}