{"id":19406,"date":"2013-08-03T08:21:30","date_gmt":"2013-08-03T08:21:30","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=19406"},"modified":"2013-08-03T08:21:30","modified_gmt":"2013-08-03T08:21:30","slug":"turris-magna-premio-citta-di-tricase","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/03\/turris-magna-premio-citta-di-tricase\/","title":{"rendered":"TURRIS MAGNA, PREMIO CITTA&#8217; DI TRICASE"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/DownloadedFile.jpeg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/DownloadedFile.jpeg\" alt=\"\" width=\"278\" height=\"181\" class=\"alignleft size-full wp-image-19407\" \/><\/a>Tricase:<\/strong> Il Turris Magna, il prestigioso premio che la Citta&#8217; di Tricase assegna agli uomini piu&#8217; illustri del Salento e non solo, quest&#8217; anno andra&#8217; anche al Cardinale Salvatore De Giorgi. Il 7 agosto, infatti, nella suggestiva atmosfera de l&#8217; Aia Nova in Tricase, l&#8217; illustre prelato ricevera&#8217; la preziosa statuetta dell&#8217; artista Ilaria De Marco che hanno ricevuto tanti uomini illustri nel passato. Con il Card. Salvatore De Giorgi, nel rispetto dello spirito del premio che privilegia tutte le professionalita&#8217;, saranno premiati anche il prof. Cosimo D&#8217; Angela, docente universitario e presidente regionale della Societa di Storia Patria; Antonio Tamborrino, commercialista, ex presidente nazionale della categoria; Toto&#8217; Piccinni, imprenditorre di Tricase; Giuseppe Afrune, pittore; Iolanda Ferramosca, ristoratrice; Giancamillo Carluccoi, primario urologo dell&#8217; Ospedale Card. Giovanni Panico di Tricase.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/03\/turris-magna-premio-citta-di-tricase\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/03\/turris-magna-premio-citta-di-tricase\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Tricase: Il Turris Magna, il prestigioso premio che la Citta&#8217; di Tricase assegna agli uomini piu&#8217; illustri del Salento e non solo, quest&#8217; anno andra&#8217; anche al Cardinale Salvatore De Giorgi. Il 7 agosto, infatti, nella suggestiva atmosfera de l&#8217; Aia Nova in Tricase, l&#8217; illustre prelato ricevera&#8217; la preziosa statuetta dell&#8217; artista Ilaria De [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19407,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19406"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19406"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19406\/revisions"}],"predecessor-version":[{"id":19408,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19406\/revisions\/19408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19407"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=19406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=19406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=19406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}