{"id":194442,"date":"2022-02-02T00:02:34","date_gmt":"2022-02-01T23:02:34","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=194442"},"modified":"2022-02-01T15:56:49","modified_gmt":"2022-02-01T14:56:49","slug":"novita-editoriali-nuova-edizione-per-il-pane-sotto-la-neve-di-anotonio-verri","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/02\/02\/novita-editoriali-nuova-edizione-per-il-pane-sotto-la-neve-di-anotonio-verri\/","title":{"rendered":"NOVITA&#8217; EDITORIALI \/ NUOVA EDIZIONE PER \u201cIl pane sotto la neve\u201d DI ANTONIO VERRI"},"content":{"rendered":"<p><strong><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-194443 size-full\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/antonio-verri-poeta.jpg\" alt=\"\" width=\"584\" height=\"359\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/antonio-verri-poeta.jpg 584w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/antonio-verri-poeta-300x184.jpg 300w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/><\/strong>di<strong> Raffaele Polo_______\u00a0<\/strong><\/p>\n<p>Continua la meritoria opera di diffusione editoriale dei lavori di <strong>Antonio Verri\u00a0<\/strong>(nella foto): dopo l\u2019uscita, lo scorso dicembre, di <em>Bucherer l<\/em>\u2019<em>orologiaio<\/em>, romanzo postumo dello scrittore di Caprarica, pubblicato nel 1995, a due anni dalla sua scomparsa, esce, in questi giorni in libreria la nuova edizione de <em><strong>Il pane sotto la neve<\/strong> (per Otranto, per occasioni), <\/em>raccolta-manifesto contenente uno dei messaggi pi\u00f9 forti della scrittura di Verri.<\/p>\n<p>\u00ab<em>Ecco. Fate solo quel che v\u2019incanta! Fate fogli di poesia, poeti<\/em>\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p><em>Declaro<\/em> \u00e8 la nuova collana di Kurumuny, diretta da Simone Giorgino, dedicata all\u2019opera dello scrittore di Caprarica, tra i protagonisti indiscussi dello scenario culturale salentino del secondo Novecento.<\/p>\n<p>&#8216;<em>Il pane sotto la neve&#8217;<\/em> viene presentato sabato 5 febbraio 2022 alle ore 18.30 nella Sala Lettura della Biblioteca Bernardini di Lecce (piazzetta Giosu\u00e8 Carducci) in occasione dell&#8217;inaugurazione di un nuovo segmento espositivo dedicato ad Antonio Verri, cio\u00e8 la mostra dal titolo &#8220;Gli autori cari al Pensionante de&#8217;Saraceni&#8221; nelle fotografie di Fernando Bevilacqua.<\/p>\n<p>Intervengono Luigi De Luca, direttore del PoloBiblioMuseale di Lecce, Fernando Bevilacqua, Antonio Melcore, sindaco di Cursi, Ada Donno, Maurizio Nocera e Luciano Pagano.<\/p>\n<p>Letture a cura di Piero Rapan\u00e0 e Simone Franco.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-194448 size-full\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/Il-pane-sotto-la-neve-_t.jpg\" alt=\"\" width=\"1024\" height=\"1417\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/Il-pane-sotto-la-neve-_t.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/Il-pane-sotto-la-neve-_t-217x300.jpg 217w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/Il-pane-sotto-la-neve-_t-740x1024.jpg 740w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/Il-pane-sotto-la-neve-_t-768x1063.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/02\/02\/novita-editoriali-nuova-edizione-per-il-pane-sotto-la-neve-di-anotonio-verri\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/02\/02\/novita-editoriali-nuova-edizione-per-il-pane-sotto-la-neve-di-anotonio-verri\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Raffaele Polo_______\u00a0 Continua la meritoria opera di diffusione editoriale dei lavori di Antonio Verri\u00a0(nella foto): dopo l\u2019uscita, lo scorso dicembre, di Bucherer l\u2019orologiaio, romanzo postumo dello scrittore di Caprarica, pubblicato nel 1995, a due anni dalla sua scomparsa, esce, in questi giorni in libreria la nuova edizione de Il pane sotto la neve (per [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,57],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/194442"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=194442"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/194442\/revisions"}],"predecessor-version":[{"id":194449,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/194442\/revisions\/194449"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=194442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=194442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=194442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}