{"id":19445,"date":"2013-08-06T09:20:17","date_gmt":"2013-08-06T09:20:17","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=19445"},"modified":"2013-08-06T09:20:29","modified_gmt":"2013-08-06T09:20:29","slug":"le-pagelle-del-lecce-a-cura-di-gabriele-de-pandis-6","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/06\/le-pagelle-del-lecce-a-cura-di-gabriele-de-pandis-6\/","title":{"rendered":"LE PAGELLE DEL LECCE a cura di GABRIELE DE PANDIS"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/foto.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/foto-224x300.jpg\" alt=\"\" width=\"224\" height=\"300\" class=\"alignleft size-medium wp-image-19446\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/foto-224x300.jpg 224w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/foto.jpg 747w\" sizes=\"(max-width: 224px) 100vw, 224px\" \/><\/a>Perucchini SV: non \u00e8 stato certo un esordio impegnativo per il neoportiere del Lecce ex Como. \u00c8 stato impegnato solo da una conclusione di Bogo al 20\u2019 della ripresa con una parata a terra. In ogni caso \u00e8 sembrato presente nella guida della difesa di giornata.<\/p>\n<p>D\u2019Ambrosio 6: \u00e8 sembrato pi\u00f9 in palla rispetto alle esibizioni della seconda met\u00e0 della stagione scorsa. La pochezza dell\u2019avversario lo ha aiutato, specialmente in fase di contenimento, ma ha dimostrato di avere gamba in un paio di discese concretizzate grazie a veloci scambi con Bellazzini. In ogni caso \u00e8 tra i partenti, ma un D\u2019Ambrosio cos\u00ec potr\u00e0 essere utile alla causa giallorossa?<\/p>\n<p>Vinetot 5,5: inizia bene, \u00e8 roccioso sulle palle alte, attento e preciso, ma con il tempo incappa in disattenzioni fatali: al 18\u2019 fa la frittata con Nunzella perdendo palla al vertice dell\u2019area destra (Bogo poi non sfrutter\u00e0). L\u2019errore lo frena un po\u2019 e diventa macchinoso in fase di disimpegno. La coppia centrale con Diniz \u00e8 da verificare, ieri ha ballato un po\u2019.<\/p>\n<p>Diniz 5,5: il leitmotiv della partita del difensore ex Livorno \u00e8 sempre lo stesso, fatto di tanta fisicit\u00e0, attenzione sulle palle alte ed errori a volte grossolani. Cerca di far ripartire il gioco arrivando palla al piede a centrocampo ma poi le soluzioni non diventano diverse dal passaggio sugli esterni. Deve migliorare il suo solito tallone d\u2019Achille dell\u2019attenzione nel corso dell\u2019intera partita.<\/p>\n<p>Nunzella 5,5: il meno in palla dei nuovi. Il terzino brindisino ha tanta grinta e corsa (manna per il calcio d\u2019agosto fatto di gambe imballate e fatica) ma in qualche occasione si fa trovare fuori posizione sulla linea difensiva concedendo un po\u2019 troppo spazio agli esterni Assumma e Riggio. Arriva spesso in zona cross ma non riesce a scodellare la palla giusta. Rimandato ma non bocciato.<\/p>\n<p>Bellazzini 6: tanto amore per il pallone. L\u2019ex Cittadella si dimostra gi\u00e0 calato nella nuova realt\u00e0 ma ieri il suo eccessivo individualismo fatto di lunghe azioni palla al piede gli ha fatto perdere il tempo per l\u2019ultimo passaggio che arrivava sempre in ritardo. In ogni caso crea tante preoccupazioni alla difesa del Santhi\u00e0 e bagna il suo esordio con un delizioso assist di spallino per il 3-0 realizzato da Bogliacino.<\/p>\n<p>Tundo 7: la favola di un ragazzo leccese. Comincia cos\u00ec cos\u00ec il match ma poi a met\u00e0 primo tempo si perde un po\u2019 sbagliando appoggi ed uscendo dalla posizione a volte troppo presto. La ripresa \u00e8 tutta un\u2019altra musica. Comincia agguerrito, caparbio e riesce ad arpionare tre palloni sulla trequarti difensiva del Santhi\u00e0. Il terzo \u00e8 il preludio alla gloria: scambio con Miccoli, ingresso in area e gol infilando Maio in uscita sul primo palo. Il gol lo fa giocare sul velluto ma il classe 1995 della Berretti giallorossa non cerca di strafare.<\/p>\n<p>Bogliacino 6: \u00e8 sacrificato sulla mediana, non \u00e8 il suo ruolo ma, complice il cartello di lavori in corso presente alla corte di mister Moriero, deve adattarsi a giocare qualche metro dietro. Fatica un po\u2019 in copertura ed a far ripartire l\u2019azione con i suoi lanci che devono percorrere dieci metri in pi\u00f9. Nell\u2019ultimo quarto d\u2019ora di partita torna al suo ruolo naturale grazie al cambio Salvi-Zigoni ed arriva anche il gol del 3-0 con un destro secco rasoterra scagliato dopo un perfetto dribbling nello stretto.<\/p>\n<p>Falcone 6,5: nel primo tempo \u00e8 lui l\u2019uomo in pi\u00f9 del Lecce. Ha costantemente il raddoppio di marcatura addosso ma in ogni caso non cerca la giocata facile in appoggio dietro ma cerca sempre il contributo in fase offensiva. Pu\u00f2 dare un gran contributo alla causa del Lecce, su quella fascia va come pochi in Lega Pro. Anche a lui manca solo l\u2019ultimo passaggio. Esce al 6\u2019 della ripresa per Bencivenga.<\/p>\n<p>Miccoli 7: doveva essere il suo Lecce e lo \u00e8. Il primo tempo \u00e8 un po\u2019 frenato dall\u2019evidente emozione del debutto con la maglia dei suoi sogni e si vede: Fabrizio gol al 10\u2019 lisciando su uno spiovente di Bogliacino. Fa la barba al palo direttamente da calcio piazzato al 12\u2019 e, nei minuti di recupero, fallisce il gol di testa. Nella ripresa prende per mano la sua squadra e diventa il fulcro del gioco: azioni, passaggi, lanci, appoggi, sponde: la manovra offensiva del Lecce passa da lui. A risultato acquisito cerca il gol personale che non arriver\u00e0 per questione di centimetri e per la bravura di Maio.<\/p>\n<p>Zigoni 6: il calcio d\u2019agosto per un attaccante della sua mole \u00e8 un Everest da scalare. In ogni caso si muove bene tra le fitte maglie della difesa del Santhi\u00e0 sembrando un attaccante di altri tempi, sempre spalle alla porta e pronto a far salire la sua squadra. Ha una sola occasione per il timbro personale ma la difficile deviazione volante finisce alta. Esce stremato per Salvi.<\/p>\n<p>Subentrati<\/p>\n<p>Bencivenga 7: una piacevole sorpresa. Impiegato sulla fascia destra offensiva, si dimostra dotato di tanta corsa, sostanza e piede veloce. \u00c8 il pi\u00f9 lesto di tutti al 21\u2019 della ripresa nel raccogliere la respinta di Maio e segnare il gol del 2-0. La sua partita \u00e8 cos\u00ec, su e gi\u00f9 da quella fascia correndo, rompendo e costruendo. Poco dopo il gol sfiora la doppietta personale incuneandosi perfettamente tra i due centrali ma trovando l\u2019opposizione di Maio.<\/p>\n<p>Luperto 6: bel debutto per il classe 1996. Un paio di anticipi ben fatti che hanno subito tolto il tremolio dell\u2019esordio nello stadio di casa. In bocca al lupo.<\/p>\n<p>Salvi SV<\/p>\n<p>Moriero 6,5: la squadra \u00e8 un cantiere e lui fa il possibile schierando il miglior Lecce, un Lecce a tante facce specialmente in fase offensiva. Il mercato dovrebbe portargli altri elementi per gestire un gruppo, una squadra, uno stile di gioco a sua immagine e somiglianza, fatto di scambi corti e tanto movimento senza palla.<\/p>\n<p><strong>Gabriele De Pandis.<\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/06\/le-pagelle-del-lecce-a-cura-di-gabriele-de-pandis-6\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/06\/le-pagelle-del-lecce-a-cura-di-gabriele-de-pandis-6\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Perucchini SV: non \u00e8 stato certo un esordio impegnativo per il neoportiere del Lecce ex Como. \u00c8 stato impegnato solo da una conclusione di Bogo al 20\u2019 della ripresa con una parata a terra. In ogni caso \u00e8 sembrato presente nella guida della difesa di giornata. D\u2019Ambrosio 6: \u00e8 sembrato pi\u00f9 in palla rispetto alle [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19446,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19445"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19445"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19445\/revisions"}],"predecessor-version":[{"id":19449,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19445\/revisions\/19449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19446"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=19445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=19445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=19445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}