{"id":19453,"date":"2013-08-06T10:04:25","date_gmt":"2013-08-06T10:04:25","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=19453"},"modified":"2013-08-06T10:04:25","modified_gmt":"2013-08-06T10:04:25","slug":"fimmana-mare-e-focu","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/06\/fimmana-mare-e-focu\/","title":{"rendered":"FIMMANA MARE E FOCU"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/BodyPart3.jpeg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/BodyPart3-300x184.jpg\" alt=\"\" width=\"300\" height=\"184\" class=\"alignleft size-medium wp-image-19454\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/BodyPart3-300x184.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/BodyPart3-1024x628.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/BodyPart3.jpeg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Prosegue con successo al Castello Aragonese di Otranto (Le) la mostra \u201cGiorgio de Chirico &#8211; Mistero e poesia\u201d a cura di Franco Calarota che in meno di due mesi di apertura ha superato abbondantemente le 15 mila presenze. Dopo aver accolto oltre 200mila visitatori con le mostre di Joan Mir\u00f2, Pablo Picasso, Salvador Dal\u00ec e Andy Warhol, l\u2019antico maniero idruntino ospita, infatti, sino a domenica 29 settembre le opere del maestro de Chirico che partito dall&#8217;Italia con la sua Metafisica, ha conquistato la scena internazionale fin dalla prima met\u00e0 del secolo scorso, travalicando i confini dell&#8217;arte per influenzare con il suo universo artistico non solo la generazione successiva di pittori, ma anche letterati, filosofi, architetti e la psicanalisi. Sempre nelle Sale del Castello, Metafisica a sud, enigma di un pomeriggio d\u2019estate, a cura di Raffaela Zizzari, ospita la proiezione di Metafisica a Sud. De Chirico, Magna Grecia, di Chiara Idrusa Scrimieri, un percorso tra docufilm e videoarte, un viaggio di lettura metafisica applicata al paesaggio sensibile della nostra Magna Grecia; le opere di quattro artisti pugliesi (Antonio Giannini, Beppe Labianca, Oronzo Liuzzi e Vincenzo Mascoli) e una sezione dedicata al fumetto con alcune tavole di Sebastiano Vilella.<\/p>\n<p>Ricco e articolato anche il programma degli eventi (ad ingresso gratuito per i visitatori della mostra) che si alternano nelle sale e negli spazi all&#8217;aperto del Castello.<strong> Sabato 10 agosto<\/strong> (ore 21.30) appuntamento con la cantante, tamburellista, danzatrice e ricercatrice Anna Cinzia Villani che, affiancata da MacuranOrchestra, proporr\u00e0 i brani del progetto Fimmana mare e focu (Anima Mundi, 2012). Fimmana, mare e focu! racconta la donna e le sue tante anime. Ma lo fa da una prospettiva insolita rispetto ai versi del repertorio tradizionale, che per la figura femminile adottano quasi sempre il punto di vista dell\u2019uomo che la descrive come dea irraggiungibile, quando \u00e8 vista attraverso gli occhi dell\u2019innamorato, o invece come vipera, quando l\u2019amore non ricambiato procura profonde sofferenze. Anche la donna canta poco di s\u00e9 e del suo animo e quando lo fa \u00e8 per lo pi\u00f9 in relazione alla dimensione quotidiana e pratica della vita familiare e del lavoro nei campi, lasciando nell&#8217;ombra la sua vita interiore, i suoi desideri pi\u00f9 nascosti. Fimmana, mare e focu! nasce invece da una lunga ricerca volta a individuare i testi tradizionali in cui la donna parla in prima persona delle sue emozioni (\u201cLu desideriu miu cu bessu cozza\u201d, \u201cFarnaru farnareddhu\u201d), o che raccontano le sue tante vite in una sola di figlia, moglie, madre, nuora, suocera (\u201cFimmana, mare e focu!\u201d, \u201cPizzica di Copertino\u201d). L&#8217;album segna la maturit\u00e0 artistica della Villani, che qui si fa anche autrice di alcune liriche (\u201cLuntananza\u201d, \u201cTridici stelle\u201d) e melodie (\u201cFarnaru farnareddhu\u201d) e che, accostando alcuni proverbi salentini, elabora il testo di \u201cFimmana, mare e focu!\u201d. Accanto a lei la MacuranOrchestra, che mette assieme protagonisti delle scena tradizionale, world e jazz. La particolare combinazione porta ad arrangiamenti curati nei dettagli, che conservano la forza vitale della musica popolare, con le sue sonorit\u00e0 aspre e talvolta graffiate, ma la arricchiscono con i colori, le idee ritmiche e le armonizzazioni del world jazz. L&#8217;apertura \u00e8 un sentito omaggio al compianto Piero Milesi. \u201c\u00ccjo pucan\u00e8\u201d, brano dal sapore molto diverso dal resto del disco, il cui testo \u00e8 stato scritto da Gianni De Santis, fu arrangiato dal maestro Milesi per la voce della Villani e divenne la sigla di apertura de La Notte della Taranta del 2001. Il packaging, in carta riciclata, ospita in copertina un particolare di Scarpette rosse (2006), un&#8217;opera di carta di Teresa Ciulli (teresaciulli.blogspot.com), mentre il libretto interno di sedici pagine contiene le traduzioni in italiano e in inglese di tutti i testi. Il nuovo disco Fimmana, mare e focu! racconta la donna e le sue tante anime. Ma lo fa da una prospettiva insolita rispetto ai versi del repertorio tradizionale, che per la figura femminile adottano quasi sempre il punto di vista dell\u2019uomo che la descrive come dea irraggiungibile, quando \u00e8 vista attraverso gli occhi dell\u2019innamorato, o invece come vipera, quando l\u2019amore non ricambiato procura profonde sofferenze.<\/p>\n<p>Tutte le domeniche di agosto (ore 19.00) i visitatori protanno assistere anche a Mamma Li Turchi, opera per ombre e cuntastorie di e con Francesco Ferramosca. Nello spettacolo di ombre, in una girandola di turcherie condite dal salace dialetto dei rudi abitanti dell&#8217;antico Salento, rivive la leggendaria epopea turco-salentina che tante tracce ha lasciato nella nostra cultura. Lo spettacolo parte da un lontano fatto storico \u2013 la presa di Otranto da parte dei Turchi nel 1480 \u2013 e da musiche, testi, canti di pianto e d\u2019amore dell\u2019antico Salento, uniti in un solo percorso tra presente e passato. Cos\u00ec un reputo (o pianto funebre), una filastrocca popolare, una nenia, trovano un nuovo spazio culturale, vitale e attuale. La memoria, e in particolare la memoria di un fatto di sangue, a cosa pu\u00f2 servire? A confrontarci con la storia dei nostri giorni e attingervi nuova dignit\u00e0 ed energia. A renderci conto, se mai ve ne fosse bisogno, che l\u00e0 dove esiste sopraffazione e morte, non si persegue soltanto la distruzione dell\u2019uomo ma si innesca la terribile spirale della violenza. Lo spettacolo termina con il martirio degli otrantini sconfitti: questi morti non chiudono un episodio del passato ma aprono i dubbi sulla consapevolezza del futuro. Cio\u00e8 del nostro presente. Lo spettacolo \u00e8 ispirato e influenzato dal romanzo \u201cL\u2019ora di tutti\u201d di Maria Corti.<\/p>\n<p>\u201cVista dal mare, Otranto appare ancora una fortezza, con i bastioni a picco sull\u2019acqua, ma dietro la vuota abbondanza di mura e torrioni, un prodigio di viuzze bianche in salita, in discesa, di casette bianche, di palazzotti tufacei. In queste viuzze i fatti della storia sono rimbalzati, come pomi maturi, da un secolo all\u2019altro, e giunti fino a noi: qui le palle delle bombarde turche, scagliate cinquecento anni fa, reggono i gradini d\u2019accesso alle case o adornano la soglia al \u2018salone\u2019 del barbiere, all\u2019ufficio postale, situate ai due lati dell\u2019ingresso\u201d, prendendo spunto da questo breve passaggio di Maria Corti sono state pensate e realizzate le palle delle bombarde, simbolo di attacco ma anche di difesa, che sono diventate parte integrante dell\u2019arredo urbano della Citt\u00e0 di Otranto. Nel 2013, anno della canonizzazione degli Ottocento Martiri di Otranto, le palle delle bombarde sono la sintesi di un\u2019esemplare storia di rinascita che parte dal lontano 1480. Nel bookshop si trover\u00e0 una tiratura limitata di 30 esemplari in ferro battuto con lo stemma del Castello Aragonese.<\/p>\n<p>Il Castello Aragonese di Otranto \u00e8 un contenitore culturale gestito dall\u2019Agenzia di Comunicazione Orione di Maglie e dalla Societ\u00e0 Cooperativa Sistema Museo di Perugia, con la direzione artistica dell\u2019architetto Raffaela Zizzari.<\/p>\n<p>La mostra \u00e8 aperta tutti i giorni.<\/p>\n<p>Orari: luglio e agosto 10-24; settembre 10-21.<\/p>\n<p>Ticket d\u2019ingresso: intero \u20ac 7,00; ridotto \u20ac 4,00 (6-14 anni, oltre 65 anni, scolaresche, diversamente abili e relativi accompagnatori, gruppi superiori a 20 unit\u00e0, convenzioni attive). Titolari Otranto Card: intero \u20ac 6,00.<\/p>\n<p>Audioguida: singola \u20ac 4,00; doppia \u20ac 6,00.<\/p>\n<p>Visita guidata di gruppo su prenotazione (in italiano, inglese o francese)<\/p>\n<p>\u2022 solo mostra: gruppi 80,00 euro + ticket d\u2019ingresso; scuole 60,00 euro + ticket d\u2019ingresso<\/p>\n<p>\u2022 mostra + castello: gruppi 100,00 euro + ticket d\u2019ingresso; scuole 80,00 euro + ticket d\u2019ingresso.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/06\/fimmana-mare-e-focu\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/06\/fimmana-mare-e-focu\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Prosegue con successo al Castello Aragonese di Otranto (Le) la mostra \u201cGiorgio de Chirico &#8211; Mistero e poesia\u201d a cura di Franco Calarota che in meno di due mesi di apertura ha superato abbondantemente le 15 mila presenze. Dopo aver accolto oltre 200mila visitatori con le mostre di Joan Mir\u00f2, Pablo Picasso, Salvador Dal\u00ec e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19454,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19453"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19453"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19453\/revisions"}],"predecessor-version":[{"id":19456,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19453\/revisions\/19456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19454"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=19453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=19453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=19453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}