{"id":19457,"date":"2013-08-06T10:08:27","date_gmt":"2013-08-06T10:08:27","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=19457"},"modified":"2013-08-06T10:08:27","modified_gmt":"2013-08-06T10:08:27","slug":"ritorna-a-grande-richiesta-indiefest-2013","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/06\/ritorna-a-grande-richiesta-indiefest-2013\/","title":{"rendered":"RITORNA A GRANDE RICHIESTA INDIEFEST 2013"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/indiefest.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/indiefest-211x300.jpg\" alt=\"\" width=\"211\" height=\"300\" class=\"alignleft size-medium wp-image-19458\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/indiefest-211x300.jpg 211w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/indiefest.jpg 706w\" sizes=\"(max-width: 211px) 100vw, 211px\" \/><\/a>Gioved\u00ec 8 e Venerd\u00ec 9 Agosto<\/strong> 2013 torna Indiefest 2013 il festival musicale indipendente promosso da Unreal Movement, ospitato nella pittoresca location dell&#8217; Ostello della Giovent\u00f9 (San Cataldo di Lecce) Giunto alla sua settima edizione l&#8217;Indiefest continua a dar voce al ricchissimo circuito musicale indipendente, prediligendo i canali di promozione (concerti, internet, autoproduzioni) che restano al di fuori di logiche e dinamiche da mercato globale. L\u2019obiettivo primario \u00e8 quello di ricreare le atmosfere tipiche dei grandi eventi, riportando in luce la musica dal vivo, la musica suonata prima nelle cantine e poi sui grandi palchi. E\u2019 un evento che celebra soprattutto i talenti locali che non hanno un\u2019adeguata vetrina per potersi esibire, in quanto nel nostro territorio mancano le strutture necessarie a poter accogliere la musica nella sua forma pi\u00f9 naturale: il Live. I musicisti che partecipano al festival si preoccupano maggiormente della loro espressione artistica piuttosto che delle considerazioni commerciali. Inizialmente il festival ha avuto risonanza a livello nazionale e ha promosso principalmente gruppi emergenti italiani.<\/p>\n<p>Negli anni sono aumentate le richieste di partecipazione di bands provenienti da tutta Italia e oggi finalmente, in una nuova e spaziosa location immersa nel verde, a pochi metri dal mare, Indiefest \u00e8 pronto ad accogliere ospiti di caratura internazionale che ci regaleranno una giornata intera all&#8217;insegna della buona musica. Peculiarit\u00e0 di questa edizione \u00e8 la presenza di alcune band composte da veterani del genere, personaggi, ma soprattutto musicisti che hanno caratterizzato la scena musicale alternativa dagli anni 90 ad oggi. Il termine Indie o Indipendente \u00e8 spesso confuso con un genere musicale, il cosiddetto alternative rock\u201f, mentre in realt\u00e0 denota un\u201fattitudine nei confronti del fare musica. L&#8217;origine del movimento va ricercata nella filosofia Settantasettina del \u201cfai-da-te\u201d.<\/p>\n<p>Gli artisti che gravitano in questo circuito hanno spesso uno sguardo internazionalista e fanno affidamento sulla stampa di settore, sui festival o sui locali dove si suona live, sulla collaborazione fra bands e sul passaparola tra appassionati e addetti ai lavori. Molti musicisti che finiscono per approdare al grande pubblico hanno prima militato nel circuito indipendente, appunto, districandosi all&#8217;interno di un network che, dagli anni Ottanta fino ai giorni nostri, ha nutrito l\u201fevoluzione di rock e suoi \u201cderivati\u201d sfornando talenti e spesso indirizzando il gusto degli ascoltatori. Anche l&#8217;Indiefest, ad esempio, ha ospitato artisti che hanno successivamente incontrato un seguito pi\u00f9 vasto oltre all&#8217;ebbrezza di un contratto con colossi discografici. Questi musicisti, per\u00f2, piuttosto che seguire calcoli commerciali, si preoccupano della qualit\u00e0 della loro musica e della possibilit\u00e0 di esibirsi dal vivo. Esistono infatti numerosi artisti e festival che si tirano volontariamente fuori da tali dinamiche o che continuano a dialogare con il network in cui hanno mosso i primi passi. In quest&#8217;ottica, l\u201fevento far\u00e0 riflettere su cosa sia la musica stessa: se soltanto un elite di ricchi musicisti, impresari e marchi oppure anche passione, ideali, contenuti, ricerca e ovviamente talento.<\/p>\n<p>Questo \u00e8 lo spirito dell&#8217;Indiefest, lo spirito di chi viene ad esibirsi, di chi ci lavora e di chi viene a trascorrere una giornata all&#8217;insegna del divertimento e della buona musica. Un progetto ambizioso che cresce di anno in anno, puntando sulle proprie risorse e su tutti gli artisti, musicisti, associazioni e persone che condividono questa visione e che rendono possibile la realizzazione di questo evento unico ed originale nel suo genere.<\/p>\n<p>Quest&#8217;anno il festival ha deciso di avvalersi del preziosissimo supporto di alcune delle realt\u00e0 pi\u00f9 significative presenti nel nostro territorio come:<\/p>\n<p>CICLOFFICINA che ha come obiettivo quello di promuovere l&#8217;utilizzo della bicicletta come mezzo di trasporto, di aumentare il recupero delle biciclette altrimenti destinate alla spazzatura e di facilitare il recupero della manualit\u00e0. Un luogo per moltiplicare uso, conoscenze, visibilit\u00e0, consapevolezza dell&#8217;utilizzo della bici come mezzo di trasporto urbano e non.<\/p>\n<p>RADIOFLO una webradio per tutti quelli che hanno il muso stampato sul monitor per met\u00e0 della giornata .Basta digitare www.radioflo.it e ti sembrer\u00e0 di essere ad un club, o sulla spiaggia, o per strada Tante parole a vanvera in totale libert\u00e0, ma anche un flusso di musica mozzafiato. Dal trash all&#8217;indie introvabile, dal divertentismo al reggae, dalla dance all&#8217;hip hop, dai classici a tutte le nuove uscite.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/06\/ritorna-a-grande-richiesta-indiefest-2013\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/06\/ritorna-a-grande-richiesta-indiefest-2013\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Gioved\u00ec 8 e Venerd\u00ec 9 Agosto 2013 torna Indiefest 2013 il festival musicale indipendente promosso da Unreal Movement, ospitato nella pittoresca location dell&#8217; Ostello della Giovent\u00f9 (San Cataldo di Lecce) Giunto alla sua settima edizione l&#8217;Indiefest continua a dar voce al ricchissimo circuito musicale indipendente, prediligendo i canali di promozione (concerti, internet, autoproduzioni) che restano [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19458,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19457"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19457"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19457\/revisions"}],"predecessor-version":[{"id":19460,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19457\/revisions\/19460"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19458"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=19457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=19457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=19457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}