{"id":19487,"date":"2013-08-14T07:33:58","date_gmt":"2013-08-14T07:33:58","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=19487"},"modified":"2013-08-14T10:24:46","modified_gmt":"2013-08-14T10:24:46","slug":"xiv-edizione-di-gusto-dopa-al-sole","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/14\/xiv-edizione-di-gusto-dopa-al-sole\/","title":{"rendered":"XIV EDIZIONE DI GUSTO DOPA AL SOLE"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/BodyPart.png\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/BodyPart-300x151.png\" alt=\"\" width=\"300\" height=\"151\" class=\"alignleft size-medium wp-image-19488\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/BodyPart-300x151.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/BodyPart.png 695w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Luned\u00ec 12 e venerd\u00ec 16 agosto<\/strong> torna al Parco Gondar di Gallipoli, in provincia di Lecce, il Gusto dopa al sole, il pi\u00f9 importante appuntamento italiano dedicato a linguaggi musicali e forme artistiche di ispirazione black e urban giunto quest&#8217;anno alla quattordicesima edizione.<\/p>\n<p>Ad aprire il festival il 12 agosto Snoop Dogg aka Snoop Lion, re indiscusso della scena hip-hop mondiale con oltre dodici milioni di dischi venduti e numerosi riconoscimenti ottenuti dopo pi\u00f9 di vent&#8217;anni di carriera. Un artista in grado di allargare i suoi orizzonti irrompendo con il suo ultimo album \u201cReincarnated\u201d nel mondo della musica reggae. Ad aprire la serata sullo stesso palco ci saranno anche Clementino, Dj Tayone, Dj War, Mad Dop, Lion D, Jah Sun, Bizzarri Sound.<\/p>\n<p>A seguire il 16 Agosto l\u2019orgoglio italiano della musica reggae nel mondo, Alborosie, primo artista \u201cbianco\u201d della storia in grado di aggiudicarsi nel 2011 il prestigioso M.O.B.O. Awards, il massimo riconoscimento mondiale attribuito agli artisti reggae di spicco nella black music. Nel nuovo tour Alborosie presenta il suo ultimo album \u201cSound the system\u201d. Nella stessa serata si alterneranno Apres la classe, Boom boom vibration, Dj Gruff, Kayakilla, Dj Skizo, Ena Ghema.<\/p>\n<p>Gusto Dopa Al Sole \u00e8 una totale immersione nella cultura musicale di strada attraverso un fitto calendario di concerti, contest e sound system, oggi questo Festival \u00e8 diventato un evento internazionale imperdibile per tutto il pubblico dell&#8217;estate salentina. Le prime edizioni, nel corso degli anni &#8217;90, sono state un punto di incontro fondamentale per il Reggae e hip hop italiano. Da l\u00ec, dal Velodromo Degli Ulivi di Monteroni, \u00e8 iniziata un&#8217;avventura che ha portato nel corso degli anni a diventare un vero e proprio festival itinerante &#8211; Baia di Gallipoli, Parco Man\u00e0 (Vernole), Aeroporto Lepore (San Cataldo) e Masseria Torcito (Cannole), dove si sono svolte le ultime due edizioni.<\/p>\n<p><strong>Programma<\/strong><\/p>\n<p><strong>12 agosto<\/strong><\/p>\n<p>Snoop Dogg aka Snoop Lion<\/p>\n<p>Clementino &#8211; dj Tayone &#8211; dj War &#8211; Mad Dopa &#8211; Lion D &#8211; Jah Sun &#8211; Bizzarri Sound<\/p>\n<p>Botteghino: 30 \u20ac<\/p>\n<p>Prevendita: 25 \u20ac + dir. prev.<\/p>\n<p><strong>16 agosto<\/strong><\/p>\n<p>Alborosie &amp; the Shengen Clan<\/p>\n<p>Apres la classe &#8211; Boom Boom Vibration &#8211; Dj Gruff &#8211; Kayakilla &#8211; dj Skizo &#8211; Ena Ghema<\/p>\n<p>Botteghino: 20 \u20ac<\/p>\n<p>Prevendita: 15 \u20ac + dir. prev.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/14\/xiv-edizione-di-gusto-dopa-al-sole\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/14\/xiv-edizione-di-gusto-dopa-al-sole\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Luned\u00ec 12 e venerd\u00ec 16 agosto torna al Parco Gondar di Gallipoli, in provincia di Lecce, il Gusto dopa al sole, il pi\u00f9 importante appuntamento italiano dedicato a linguaggi musicali e forme artistiche di ispirazione black e urban giunto quest&#8217;anno alla quattordicesima edizione. Ad aprire il festival il 12 agosto Snoop Dogg aka Snoop Lion, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19488,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19487"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19487"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19487\/revisions"}],"predecessor-version":[{"id":19490,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19487\/revisions\/19490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19488"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=19487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=19487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=19487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}