{"id":195104,"date":"2022-02-15T09:48:46","date_gmt":"2022-02-15T08:48:46","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=195104"},"modified":"2022-02-15T09:48:46","modified_gmt":"2022-02-15T08:48:46","slug":"nostalgia-della-comicita-popolare-di-toto","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/02\/15\/nostalgia-della-comicita-popolare-di-toto\/","title":{"rendered":"NOSTALGIA DELLA COMICITA&#8217; POPOLARE DI TOTO&#8217;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-195105 size-full\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/signori2.jpg\" alt=\"\" width=\"500\" height=\"249\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/signori2.jpg 500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/signori2-300x149.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>di <strong>Elena Vada<\/strong>\u00a0______<\/p>\n<p>Il\u00a015 Febbraio 1898,\u00a0nasceva a\u00a0Napoli\u00a0uno degli artisti pi\u00f9 importanti\u00a0 nella storia italiana del teatro e del cinema. Un grande attore e non solo una maschera, raccolta e riserva senza fine, di mimica ed espressioni, che stanno stipati nel cuore di tutti i napoletani e di molti italiani. Sicuramente nel mio.<\/p>\n<p>\u00c8 il compleanno di\u00a0Antonio Griffo Focas Flavio Angelo Ducas Comneno Porfirogenito Gagliardi de Curtis di Bisanzio.. in arte Tot\u00f2!<\/p>\n<p>&#8220;Signori si nasce e io lo nacqui, modestamente!\u201d, recita la celebre battuta del film &#8220;Signori si nasce&#8221;<\/p>\n<p>Ha lavorato al fianco di grandi artisti come Pasolini, De Sica, Steno e Rossellini (ricordando anche la lista delle grandi pellicole firmate da questi maestri), ma anche in inconfondibili parodie. Ricordiamo gli inizi nell&#8217;avanspettacolo, nella rivista e poi a teatro.<\/p>\n<p>Padrone o servo, nobile o barbone, furbo o sprovveduto, triste o felice: un artista capace di tutto, favorito da una versatilit\u00e0 artistica unica.<\/p>\n<p>Molte scene e frasi cult, dei suoi film,\u00a0 sono diventate iconiche come quella del \u201c&#8230; E io pago!\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Sapete cosa mi manca di Tot\u00f2? Il modo che ci dava di ridere pulito, ingenuo, ironico e spensierato. Mi manca quell\u2019umorismo sano, a volte metafora di ci\u00f2 che siamo nella vita.<\/p>\n<p>Oggi\u00a0la risata \u00e8, spesso, troppo facile, grossolana,\u00a0 volgare, oltre che banale, scontata, ovvia e pesante.<\/p>\n<p>Continuer\u00f2 a vedere e rivedere, i tuoi film&#8230; impossibile smettere di guardarli, e pure di sorridere. Grazie.<\/p>\n<p>Tot\u00f2 mi manchi, CI MANCHI!<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/02\/15\/nostalgia-della-comicita-popolare-di-toto\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/02\/15\/nostalgia-della-comicita-popolare-di-toto\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Elena Vada\u00a0______ Il\u00a015 Febbraio 1898,\u00a0nasceva a\u00a0Napoli\u00a0uno degli artisti pi\u00f9 importanti\u00a0 nella storia italiana del teatro e del cinema. Un grande attore e non solo una maschera, raccolta e riserva senza fine, di mimica ed espressioni, che stanno stipati nel cuore di tutti i napoletani e di molti italiani. Sicuramente nel mio. \u00c8 il compleanno [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":195105,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/195104"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=195104"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/195104\/revisions"}],"predecessor-version":[{"id":195106,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/195104\/revisions\/195106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/195105"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=195104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=195104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=195104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}