{"id":195264,"date":"2022-02-17T14:43:01","date_gmt":"2022-02-17T13:43:01","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=195264"},"modified":"2022-02-17T14:53:24","modified_gmt":"2022-02-17T13:53:24","slug":"la-consulta-da-il-via-libera-a-cinque-referendum-sulla-giustizia-ecco-spiegato-di-che-cosa-si-tratta","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/02\/17\/la-consulta-da-il-via-libera-a-cinque-referendum-sulla-giustizia-ecco-spiegato-di-che-cosa-si-tratta\/","title":{"rendered":"LA CONSULTA DA&#8217; IL VIA LIBERA A CINQUE REFERENDUM SULLA GIUSTIZIA. ECCO SPIEGATO DI CHE COSA SI TRATTA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-195267 size-full\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/1627404486-3099609-large.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/1627404486-3099609-large.jpg 1200w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/1627404486-3099609-large-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/1627404486-3099609-large-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/02\/1627404486-3099609-large-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>di <strong>Angelo De Pascalis\u00a0<\/strong>\u00a0\u00a0_______<\/p>\n<p>La Consulta, nella giornata di ieri, ha ammesso cinque quesiti referendari proposti da Lega e Radicali in tema di giustizia \u201cperch\u00e9 le rispettive richieste non rientrano in alcuna delle ipotesi per le quali l\u2019ordinamento costituzionale esclude il ricorso all\u2019istituto referendario\u201d.<\/p>\n<p>\u00c8 stato respinto, invece, quello sulla responsabilit\u00e0 diretta dei magistrati, per il quale l\u2019ordinamento costituzionale esclude il ricorso all\u2019istituto referendario.<\/p>\n<p>Gli elettori pertanto saranno chiamati ad esprimere il proprio parere, molto probabilmente, in un periodo compreso tra il 15 aprile e il 15 giugno.<\/p>\n<p>&nbsp;<\/p>\n<p>Per quanto riguarda il primo &#8211; Legge Severino &#8211;\u00a0i cittadini, dovranno pronunciarsi\u00a0sull\u2019abrogazione del decreto legislativo del 2012 che prevede l\u2019incandidabilit\u00e0,\u00a0ineleggibilit\u00e0 e la decadenza per parlamentari, rappresentanti di governo, consiglieri regionali, sindaci e amministratori locali in caso di condanna definitiva a pi\u00f9 di due anni di reclusione e la sospensione, per certi reati, dopo la sentenza di primo grado. L\u2019obiettivo di Lega e Radicali \u00e8 quello di abrogare le norme che consentono la sospensione degli amministratori locali a seguito di condanne non definitive per associazione mafiosa o reati contro la pubblica amministrazione.<\/p>\n<p>&nbsp;<\/p>\n<p>Per il referendum sui limiti all\u2019applicazione delle misure cautelari i promotori chiedono che venga abolita parzialmente la possibilit\u00e0 che ha il giudice di disporre la misura cautelare della custodia in carcere nel corso delle indagini al meno che un soggetto sia inquisito per reati che prevedono l\u2019uso della violenza o delle armi, oppure legato alla criminalit\u00e0 organizzata e all\u2019eversione.<\/p>\n<p>&nbsp;<\/p>\n<p>Con il terzo quesito:\u00a0separazione delle funzioni dei magistrati si vuole abrogare la legge che consente agli stessi togati di passare pi\u00f9 volte dalle funzioni giudicanti a quelle requirenti e viceversa.<\/p>\n<p>I proponenti, invece, ritengono che i\u00a0magistrati\u00a0dovranno scegliere all&#8217;inizio\u00a0della\u00a0carriera la\u00a0funzione\u00a0giudicante o requirente, e mantenere sempre quel ruolo.<\/p>\n<p>&nbsp;<\/p>\n<p>Il quarto referendum, mira all\u2019eliminazione delle liste di presentatori per l&#8217;elezione dei togati del Csm, ovvero si vuole abolire la raccolta delle almeno venticinque firme di colleghi a sostegno del magistrato che intende presentarsi per essere eletti nel Csm.<\/p>\n<p>&nbsp;<\/p>\n<p>Il quinto quesito &#8211; Equa valutazione dei magistrati &#8211; (Consigli giudiziari) propone di abrogare il Decreto Legislativo 27 gennaio 2006, n. 25 e successive modifiche in base al quale solo i magistrati, hanno il compito di giudicare gli altri magistrati, mentre un terzo dell\u2019organismo composto da avvocati e professori universitari in materie giuridiche, \u00e8 escluso dalle discussioni e dalle votazioni dei Consigli.<\/p>\n<p>&nbsp;<\/p>\n<p>I referendum per essere validi dovranno raggiungere il quorum del 50% pi\u00f9 uno degli aventi diritto al voto. Tuttavia, se prima della convocazione degli elettori il Parlamento abroga le norme oggetto della consultazione le operazioni relative non si svolgeranno. Oppure il referendum sar\u00e0 rinviato in caso di scioglimento anticipato delle Camere.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/02\/17\/la-consulta-da-il-via-libera-a-cinque-referendum-sulla-giustizia-ecco-spiegato-di-che-cosa-si-tratta\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/02\/17\/la-consulta-da-il-via-libera-a-cinque-referendum-sulla-giustizia-ecco-spiegato-di-che-cosa-si-tratta\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Angelo De Pascalis\u00a0\u00a0\u00a0_______ La Consulta, nella giornata di ieri, ha ammesso cinque quesiti referendari proposti da Lega e Radicali in tema di giustizia \u201cperch\u00e9 le rispettive richieste non rientrano in alcuna delle ipotesi per le quali l\u2019ordinamento costituzionale esclude il ricorso all\u2019istituto referendario\u201d. \u00c8 stato respinto, invece, quello sulla responsabilit\u00e0 diretta dei magistrati, per [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":195267,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/195264"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=195264"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/195264\/revisions"}],"predecessor-version":[{"id":195268,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/195264\/revisions\/195268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/195267"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=195264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=195264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=195264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}