{"id":196004,"date":"2022-03-02T16:13:39","date_gmt":"2022-03-02T15:13:39","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=196004"},"modified":"2022-03-02T18:35:47","modified_gmt":"2022-03-02T17:35:47","slug":"196004","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/02\/196004\/","title":{"rendered":"ANNUNCIATO UN RESTYLING TOTALE DELLA STAZIONE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-196005 size-full\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/sta.png\" alt=\"\" width=\"875\" height=\"592\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/sta.png 875w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/sta-300x203.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/sta-768x520.png 768w\" sizes=\"(max-width: 875px) 100vw, 875px\" \/>(e.l.) ______\u00a0\u201c<i>\u00c8 un risultato di valore storico che raggiungiamo insieme a Rete Ferroviaria Italia: costruita alla fine degli anni Sessanta dell&#8217;Oottocento, la stazione di Lecce non veniva interessata da un intervento di riqualificazione di questa portata dagli anni &#8217;50, dunque da pi\u00f9 di 70 anni. Sar\u00e0 una stazione pi\u00f9 accogliente, accessibile, funzionale, all\u2019altezza delle ambizioni di una citt\u00e0 come Lecce dal punto di vista turistico e capace di rispondere meglio ai bisogni dei cittadini leccesi e salentini che la attraversano ogni giorno per viaggio o lavoro. Il progetto di Rete Ferroviaria Italiana si inserisce, come un tassello fondamentale, tra quelli che il Comune sta realizzando con il progetto di ribaltamento e la riqualificazione di piazzale Massari e Viale Oronzo Quarta. Grazie a un lavoro puntuale degli uffici i tre progetti sono stati allineati per risultare un unicum a servizio della modernizzazione della pi\u00f9 importante infrastruttura di mobilit\u00e0 della citt\u00e0<\/i>\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Cos\u00ec, questo pomeriggio, il sindaco di Lecce\u00a0<b>Carlo Salvemini\u00a0 \u00a0<\/b>per la riqualificazione della stazione ferroviaria di Lecce, finanziato con 14 milioni di euro\u00a0 dal Piano Nazionale Ripresa Resilienza del goerno.<\/p>\n<p>La speranza \u00e8 che ora i lavori, annunciati e ipotizzati da anni, iniziati e poi bloccati, possano riprendere e concludersi in tempi ragionevoli.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/02\/196004\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/02\/196004\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______\u00a0\u201c\u00c8 un risultato di valore storico che raggiungiamo insieme a Rete Ferroviaria Italia: costruita alla fine degli anni Sessanta dell&#8217;Oottocento, la stazione di Lecce non veniva interessata da un intervento di riqualificazione di questa portata dagli anni &#8217;50, dunque da pi\u00f9 di 70 anni. Sar\u00e0 una stazione pi\u00f9 accogliente, accessibile, funzionale, all\u2019altezza delle ambizioni [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":196005,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/196004"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=196004"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/196004\/revisions"}],"predecessor-version":[{"id":196008,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/196004\/revisions\/196008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/196005"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=196004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=196004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=196004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}