{"id":196616,"date":"2022-03-15T13:55:11","date_gmt":"2022-03-15T12:55:11","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=196616"},"modified":"2022-03-15T15:13:40","modified_gmt":"2022-03-15T14:13:40","slug":"camminata-organizzata-per-disabili-sensoriali","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/15\/camminata-organizzata-per-disabili-sensoriali\/","title":{"rendered":"CAMMINATA ORGANIZZATA PER DISABILI SENSORIALI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-196617 size-large\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/275565407_493850415605944_4639939787271817489_n-1024x462.jpg\" alt=\"\" width=\"1024\" height=\"462\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/275565407_493850415605944_4639939787271817489_n-1024x462.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/275565407_493850415605944_4639939787271817489_n-300x135.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/275565407_493850415605944_4639939787271817489_n-768x346.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/275565407_493850415605944_4639939787271817489_n.jpg 1420w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Riceviamo e volentieri pubblichiamo.\u00a0 Dario Sorgato, presidente della Onlus\u00a0 NoisyVision, ci manda il seguente comunicato.<\/p>\n<p>______<\/p>\n<div class=\"ydp47fe48bbsignature\">\n<p dir=\"ltr\">Dal 24 al 29 Marzo un gruppo integrato di persone alcune delle quali con disabilit\u00e0 sensoriali (ciechi, ipovedenti, ipoudenti) camminer\u00e0 da Torre Sant\u2019Andrea a Santa Maria di Leuca.<\/p>\n<p dir=\"ltr\">L\u2019iniziativa \u00e8 realizzata in collaborazione da due realt\u00e0 non profit NoisyVision Onlus e la Compagnia dei Cammini.<\/p>\n<p dir=\"ltr\">NoisyVision si occupa da diversi anni di cammini inclusivi, ovvero aperti a tutti, indipendentemente dalle eventuali disabilit\u00e0.<\/p>\n<p dir=\"ltr\">La Compagnia dei Cammini organizza dozzine di viaggi a piedi in tutto il mondo da oltre 10 anni.<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\">Questo sar\u00e0 il primo cammino di questa nuova collaborazione.<\/p>\n<p dir=\"ltr\">\u201cAbbiamo scelto di cominciare dal Sud -spiega Dario Sorgato, fondatore di NoisyVision Onlus &#8211;\u00a0 per portare anche in altre regioni d\u2019Italia il nostro messaggio inclusivo, dopo diverse esperienze in Centro e Nord Italia\u201d<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\">\u201cCamminare insieme, in presenza di persone con disabilit\u00e0 visive non significa che chi vede dovr\u00e0 essere costantemente a loro disposizione e attenta alle loro esigenze \u2013 continua Sorgato, fondatore di NoisyVision -.\u00a0 Per quanto ci siano alcuni accorgimenti di base, accompagnare chi vede poco o nulla \u00e8 molto pi\u00f9 semplice e naturale di quanto si possa immaginare. E lo scambio di esperienze e di sensazioni \u00e8 molto arricchente per entrambi e per il gruppo, che si fa ancor pi\u00f9 coeso\u201d.<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\">La scoperta della natura, del territorio, della cultura attraverso i viaggi a passo lento \u00e8 uno dei modi pi\u00f9 sostenibili per fare turismo. Se contemporaneamente si cerca di valorizzare la diversit\u00e0 e di permettere a persone disabili di camminare in lucidezza, il valore per i partecipanti e per le comunit\u00e0 locali \u00e8 ancora maggiore.<\/p>\n<div dir=\"ltr\" data-setdir=\"false\">Info al\u00a0tel .\u00a0049 8258141<\/div>\n<div><\/div>\n<\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/15\/camminata-organizzata-per-disabili-sensoriali\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/15\/camminata-organizzata-per-disabili-sensoriali\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo.\u00a0 Dario Sorgato, presidente della Onlus\u00a0 NoisyVision, ci manda il seguente comunicato. ______ Dal 24 al 29 Marzo un gruppo integrato di persone alcune delle quali con disabilit\u00e0 sensoriali (ciechi, ipovedenti, ipoudenti) camminer\u00e0 da Torre Sant\u2019Andrea a Santa Maria di Leuca. L\u2019iniziativa \u00e8 realizzata in collaborazione da due realt\u00e0 non profit NoisyVision [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":196617,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/196616"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=196616"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/196616\/revisions"}],"predecessor-version":[{"id":196628,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/196616\/revisions\/196628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/196617"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=196616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=196616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=196616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}