{"id":197030,"date":"2022-03-21T13:00:45","date_gmt":"2022-03-21T12:00:45","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=197030"},"modified":"2022-03-21T19:20:30","modified_gmt":"2022-03-21T18:20:30","slug":"inquinamento-acustico-lecce-al-secondo-posto","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/21\/inquinamento-acustico-lecce-al-secondo-posto\/","title":{"rendered":"\u201cInquinamento acustico: Lecce al secondo posto\u201d"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-197031\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/inquinamento-acustico.jpg\" alt=\"\" width=\"442\" height=\"300\" \/><\/p>\n<p>Riceviamo e volentieri pubblichiamo. Il consigliere comunale della \u201cLista Congedo Sindaco\u201d Andrea Pasquino ci\u00a0 manda il seguente comunicato\u00a0______<\/p>\n<p>\u201cInquinamento acustico: Lecce al secondo posto fra le citt\u00e0 italiane\u201d.<\/p>\n<p>Risulta essere Milano la citt\u00e0 pi\u00f9 rumorosa d\u2019Italia &#8211; con un livello medio di decibel pari a 65,31 -seguita da Lecce con una media di 65,24 dB e da Verona con una media di 61dB.<\/p>\n<p>&nbsp;<\/p>\n<p>Un risultato non certo rassicurante per i cittadini leccesi, che seppur consapevoli di quanto fosse rumorosa la propria citt\u00e0, non immaginavano di vederla classificata al secondo posto tra le citt\u00e0 italiane con maggior inquinamento acustico.i. decibel \u00e8 pari a 65.31<\/p>\n<p>Il dato emerge da una ricerca condotta da Amplifon, attraverso l\u2019applicazione \u201cListen Responsibly\u201d, con l\u2019obiettivo di scoprire quale fossero le citt\u00e0 italiane pi\u00f9 rumorose.<\/p>\n<p>&nbsp;<\/p>\n<p>Situazione certamente da non sottovalutare se si pensa ai rischi rilevati dall\u2019Organizzazione Mondiale della Sanit\u00e0, secondo la quale, pi\u00f9 di un miliardo di persone fra i 12 e i 35 anni rischia problemi di udito a causa dell\u2019esposizione incontrollata a fonti di rumore eccessivo.<\/p>\n<p>Tra le cause principali che hanno portato la nostra citt\u00e0 in questo triste podio vi \u00e8 l\u2019elevato traffico veicolare cittadino e quello proveniente dalla provincia.<\/p>\n<p>Infatti come indicato nel rapporto dell\u2019AEA (Agenzia Europea dell\u2019Ambiente) \u201cil rumore in Europa \u2013 2020\u201d il traffico veicolare \u00e8 la principale fonte di inquinamento acustico in Europa.<\/p>\n<p>Traffico veicolare ormai fuori controllo nella nostra citt\u00e0, aumentato drasticamente negli ultimi anni, soprattutto a causa della carenza di parcheggi e per scelte sbagliate in tema di mobilit\u00e0 poste in essere dall\u2019attuale amministrazione.<\/p>\n<p>Si \u00e8 passati da 8.679 stalli nel 2007 ai 6907 stalli nel 2020 (anno peggiore per la viabilit\u00e0 automobilistica). Il risultato, almeno nelle ore di punta, \u00e8 sotto gli occhi di tutti: corsie preferenziali quasi sempre vuote, strade paralizzate e automobili incolonnate sulle principali arterie con i clacson impazziti e con tempi di percorrenza diventati insostenibili. Situazione che ha forti ripercussioni non solo sul fronte dell\u2019inquinamento acustico, ma anche sulla qualit\u00e0 dell\u2019aria che respiriamo e, non da meno, sulla qualit\u00e0 stessa di vita dei cittadini.<\/p>\n<p>&nbsp;<\/p>\n<p>Mi auguro che questo deludente e preoccupante risultato faccia riflettere l\u2019attuale amministrazione sulle sbagliate politiche messe in atto in materia di regolazione dei flussi di mobilit\u00e0 nella citt\u00e0 di Lecce, frutto di scelte estemporanee senza alcuna visione programmatica.<\/p>\n<p>\u00c8 necessario ed urgente porre in essere dei provvedimenti per contenere i rumori in citt\u00e0 ed avviare da subito un sistema integrato di mobilit\u00e0 che consideri i parcheggi, i trasporti pubblici, i mezzi di mobilit\u00e0 alternativa e le automobili componenti di un unico sistema di mobilit\u00e0.\u00a0______<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;APPROFONDIMENTO nel nostro articolo del 30 aprile 2016<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"U4ZwkfrGhV\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/04\/30\/inquinamento-acustico-a-nardo\/\">INQUINAMENTO ACUSTICO A NARDO&#8217;<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/04\/30\/inquinamento-acustico-a-nardo\/embed\/#?secret=U4ZwkfrGhV\" data-secret=\"U4ZwkfrGhV\" width=\"500\" height=\"282\" title=\"&#8220;INQUINAMENTO ACUSTICO A NARDO&#8217;&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/21\/inquinamento-acustico-lecce-al-secondo-posto\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/21\/inquinamento-acustico-lecce-al-secondo-posto\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Il consigliere comunale della \u201cLista Congedo Sindaco\u201d Andrea Pasquino ci\u00a0 manda il seguente comunicato\u00a0______ \u201cInquinamento acustico: Lecce al secondo posto fra le citt\u00e0 italiane\u201d. Risulta essere Milano la citt\u00e0 pi\u00f9 rumorosa d\u2019Italia &#8211; con un livello medio di decibel pari a 65,31 -seguita da Lecce con una media di 65,24 dB [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/197030"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=197030"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/197030\/revisions"}],"predecessor-version":[{"id":197032,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/197030\/revisions\/197032"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=197030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=197030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=197030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}