{"id":197033,"date":"2022-03-21T19:18:44","date_gmt":"2022-03-21T18:18:44","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=197033"},"modified":"2022-03-21T19:25:48","modified_gmt":"2022-03-21T18:25:48","slug":"ho-preso-tutte-le-varianti-del-mondo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/21\/ho-preso-tutte-le-varianti-del-mondo\/","title":{"rendered":"&#8216;Ho  preso tutte le varianti del mondo&#8217;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-197035 size-full\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/crosetto-meloni5.jpg\" alt=\"\" width=\"1400\" height=\"933\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/crosetto-meloni5.jpg 1400w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/crosetto-meloni5-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/crosetto-meloni5-1024x682.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/crosetto-meloni5-768x512.jpg 768w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/><\/p>\n<p>(g.p.) ______ L&#8217; onorevole Guido Crosetto, 59 anni, di Cuneo, imprenditore, fondatore di Fratelli d&#8217;Italia\u00a0(immancabile a ogni congresso la sua personale celebrazione di Giorgia Meloni, sollevata per aria dalle sue braccia di gigante buono), dimissionario da deputato per poter fare il presidente della Federazione Aziende Italiane per l&#8217;Aerospazio, la Difesa e la Sicurezza, spesso ospite dei talk show televisivi, ebbe il suo vero quarto d&#8217;ora di celebrit\u00e0 lo scorso\u00a0\u00a026 gennaio, quando venne scelto da Fratelli d&#8217;Italia come candidato di bandiera al III scrutinio delle\u00a0elezione del Presidente della Repubblica, e ricevette 114 voti, 51 in pi\u00f9 dei grandi elettori del partito.<\/p>\n<p>Ora, ne ha un altro, anche se questo assai spiacevole, da due giorni, da quando ha postato un messaggio su Twitter, che soprattutto oggi \u00e8 diventato virale e sta scatenando innumerevoli\u00a0 \u00a0reazioni, ripreso e variamente\u00a0 commentato anche da molti organi di informazione.<\/p>\n<p>E se questa non \u00e8 sfiga, dimmi tu cos&#8217;\u00e8&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-197034 size-full\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/274953339_1105136820279183_949992632693142261_n.jpg\" alt=\"\" width=\"526\" height=\"699\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/274953339_1105136820279183_949992632693142261_n.jpg 526w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/274953339_1105136820279183_949992632693142261_n-226x300.jpg 226w\" sizes=\"(max-width: 526px) 100vw, 526px\" \/><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/21\/ho-preso-tutte-le-varianti-del-mondo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/21\/ho-preso-tutte-le-varianti-del-mondo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.p.) ______ L&#8217; onorevole Guido Crosetto, 59 anni, di Cuneo, imprenditore, fondatore di Fratelli d&#8217;Italia\u00a0(immancabile a ogni congresso la sua personale celebrazione di Giorgia Meloni, sollevata per aria dalle sue braccia di gigante buono), dimissionario da deputato per poter fare il presidente della Federazione Aziende Italiane per l&#8217;Aerospazio, la Difesa e la Sicurezza, spesso ospite [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":197035,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/197033"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=197033"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/197033\/revisions"}],"predecessor-version":[{"id":197038,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/197033\/revisions\/197038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/197035"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=197033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=197033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=197033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}