{"id":197103,"date":"2022-03-23T16:31:21","date_gmt":"2022-03-23T15:31:21","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=197103"},"modified":"2022-03-23T16:58:38","modified_gmt":"2022-03-23T15:58:38","slug":"svolta-nelle-indagini-del-delitto-di-via-poma-trentadue-anni-dopo-spuntano-anche-in-questaltro-mistero-italiano-irrisolto-le-ombre-della-banda-della-magliana-e-dei-servizi-segreti","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/23\/svolta-nelle-indagini-del-delitto-di-via-poma-trentadue-anni-dopo-spuntano-anche-in-questaltro-mistero-italiano-irrisolto-le-ombre-della-banda-della-magliana-e-dei-servizi-segreti\/","title":{"rendered":"SVOLTA NELLE INDAGINI SUL DELITTO DI VIA POMA, TRENTADUE ANNI DOPO  SPUNTANO ANCHE IN QUEST&#8217;ALTRO MISTERO ITALIANO IRRISOLTO LE OMBRE DELLA BANDA DELLA MAGLIANA, DEI SERVIZI SEGRETI E DEL VATICANO. INSOMMA, PER SIMONETTA CESARONI SI DELINEANO GLI STESSI SCENARI DEL CASO DI EMANUELA ORLANDI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-large wp-image-197104\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/6579496_21215448_simonetta_cesaroni-1024x562.jpg\" alt=\"\" width=\"1024\" height=\"562\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/6579496_21215448_simonetta_cesaroni-1024x562.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/6579496_21215448_simonetta_cesaroni-300x165.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/6579496_21215448_simonetta_cesaroni-768x421.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/6579496_21215448_simonetta_cesaroni.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>di <strong>Flora Fina<\/strong> ______<\/p>\n<p>&nbsp;<\/p>\n<p>Il caso di Simonetta Cesaroni, passato alla storia come il \u201c Delitto di Via Poma \u201d si riapre improvvisamente in questi giorni,\u00a0 dopo trentadue anni di estenuante attesa e un fitto alone di mistero che avvolge ancora la vicenda.<\/p>\n<p>&nbsp;<\/p>\n<p>Era il pomeriggio del 7 agosto 1990, e la giovane ventunenne fu ritrovata svestita &#8211; con ventinove coltellate distribuite su tutto il corpo &#8211;\u00a0 nel suo ufficio presso il quale era segretaria per conto della Reli Sas (uno studio commerciale) e che aveva tra i suoi clienti la A.I.A.G. (Associazione Italiana Alberghi della Giovent\u00f9) ; l\u2019arma del delitto \u2013 probabilmente un tagliacarte &#8211; non fu mai ritrovata, come anche l\u2019assassino, pi\u00f9 volte temporaneamente individuato e poi scagionato, ricercato prima in Pietrino Vanacore, portiere dello stabile, e successivamente nella figura di Raniero Brusco, il fidanzato della vittima.<\/p>\n<p>Simonetta viveva con la famiglia nel quartiere di Cinecitt\u00e0, nella zona sud di Roma e, nello specifico, adiacente al parco Centocelle.<\/p>\n<p>La giovane era diplomata in lingue straniere, padroneggiava bene sia il francese che l\u2019inglese, e riusc\u00ec ad ottenere un diploma come ragioniera contabile per inserirsi immediatamente nel mondo del lavoro: in poche parole conduceva una vita regolare, lineare.<\/p>\n<p>Descritta come una ragazza estremamente prudente, Simonetta trascorreva il tempo libero in compagnia dei suoi amici, fra lo sport e le serate in discoteca la sera.<\/p>\n<p>Tuttavia al tempo delle indagini restavano ancora molti nervi scoperti sulla questione: un elemento che salt\u00f2 subito all\u2019attenzione degli inquirenti fu il fatto che Simonetta lavorasse in un ufficio aperto al pubblico solo ed esclusivamente di mattina. Di pomeriggio l\u2019unica a lavorare nella sede era proprio Simonetta, che aveva avuto specifiche istruzioni di non aprire, categoricamente, a nessuno.<\/p>\n<p>La ragazza, per\u00f2, quel pomeriggio apr\u00ec le porte del suo ufficio, a chi, dopo tantissimo tempo, non ci \u00e8 dato saperlo.<\/p>\n<p>&nbsp;<\/p>\n<p>Ma non solo: a rendere la vicenda ancora pi\u00f9 intricata e scottante, furono &#8211; e sono tuttora &#8211; tanti \u00a0gli elementi, riguardanti in primis il suicidio del primo sospettato, Vanacore, che a distanza di vent\u2019anni dal delitto decise di porre fine alla sua vita, in circostanze molto sospette, lasciando un bigliettino autografo con su scritto \u201c 20 anni di sofferenze e di sospetti ti portano al suicidio \u201d proprio pochi giorni prima di deporre all&#8217;udienza del processo per l&#8217;omicidio della ragazza a carico di Raniero Busco.<\/p>\n<p>&nbsp;<\/p>\n<p>E poi, altri elementi fortemente dissonanti intorbidiscono le acque profonde di questo delitto italiano.<\/p>\n<p>&nbsp;<\/p>\n<p>Il 30 gennaio 1995 infatti, arriva in Procura, a Roma, una lettera anonima, che suggerisce di indagare sulla pista del Videotel: una conversazione alla quale si poteva accedere con il computer all&#8217;inizio degli anni Novanta, attraverso un servizio simile all&#8217;odierno Internet. La pista, battuta per alcuni anni dagli inquirenti, suggeriva l&#8217;ipotesi che Simonetta avesse fatto uso del computer dell&#8217;ufficio di via Poma per entrare in contatto, attraverso la rete, con altri utenti.<\/p>\n<p>Ed \u00e8 cos\u00ec, che casualmente, poteva aver conosciuto il suo assassino, al quale lei aveva dato un appuntamento per quel pomeriggio del 7 agosto 1990.<\/p>\n<p>&nbsp;<\/p>\n<p>Venne archiviata anche la posizione di Salvatore Volponi, il datore di lavoro della ragazza.<\/p>\n<p>Un anno dopo venne inviato un avviso di garanzia a Federico Valle, nipote dell\u2019architetto Cesare Valle, che abitava nel palazzo di via Poma. Un testimone sosteneva che nella notte era rientrato in casa sporco di sangue. Il gip tuttavia lo prosciolse per non aver commesso il fatto.<\/p>\n<p>Un giallo estremamente complesso questo, che si sviluppa su altri piani alternativi, come ad esempio, la vicenda dello stalker telefonico, che puntualmente contattava la vittima: quest\u2019ultima per\u00f2, molto riservata, \u00a0non aveva comunicato la sede di lavoro neanche ai suoi familiari.<\/p>\n<p>&nbsp;<\/p>\n<p>Da non sottovalutare poi, il filone d\u2019inchiesta riguardante le presunte operazioni illecite che, nel corso dei primi anni Novanta, sarebbero state compiute da alcuni soggetti appartenenti ai servizi segreti nell&#8217;ambito della cooperazione allo sviluppo e in particolare in Somalia: Simonetta Cesaroni, incaricata di stipulare contratti per conto di alcune societ\u00e0 al di fuori della sua normale professione, sarebbe stata a conoscenza di queste attivit\u00e0 illecite.<\/p>\n<p>&nbsp;<\/p>\n<p>Agli occhi degli inquirenti salt\u00f2 perci\u00f2 subito all\u2019occhio una constatazione riguardante l\u2019omicidio, probabilmente voluto della Banda della Magliana ed effettuato materialmente dai servizi segreti italiani con la complicit\u00e0 del Vaticano.<\/p>\n<p>&nbsp;<\/p>\n<p>Era un\u2019ipotesi nota infatti, che Simonetta Cesaroni avesse scoperto quasi per caso negli archivi della stessa A.I.A.G. degli importantissimi e segretissimi documenti che testimoniavano dei presunti favori fatti dalla stessa A.I.A.G. e altri enti edili a favore della Banda della Magliana con il benestare del Vaticano, territorio in cui vi erano alcuni edifici &#8220;prestati&#8221; alla banda, con la complicit\u00e0 dei servizi segreti: proprio questa pista in un primo momento poteva essere la pi\u00f9 affidabile, \u00a0soprattutto nel momento in cui alcuni testimoni dissero di aver notato poco dopo l&#8217;omicidio tre uomini \u00a0&#8211; mai identificati &#8211; esattamente sotto la palazzina di Cesaroni, e che per il loro modo di fare e per il loro abbigliamento potevano essere membri dei servizi segreti.<\/p>\n<p>&nbsp;<\/p>\n<p>Non trascorse moltissimo tempo prima di constatare ufficialmente che i legami tra la Banda della Magliana e i servizi segreti fossero stretti, quasi indissolubili.<\/p>\n<p>&nbsp;<\/p>\n<p>Le innumerevoli ipotesi per\u00f2, nel giro di tutti questi anni, sono state lentamente abbandonate, forse perch\u00e9 poco plausibili, forse perch\u00e9 si tratta di un mistero irrisolvibile, troppo complesso ed articolato.<\/p>\n<p>&nbsp;<\/p>\n<p>Tuttavia, le lunghe fasi di indagine e l\u2019altrettanto lunga fase giudiziaria senza soluzione, trovano nel nostro presente una possibile spiegazione e dunque una nuova pista: un sospettato ascoltato nell\u2019estate del lontano 1990, il cui alibi, a distanza di pi\u00f9 di un trentennio non sarebbe pi\u00f9 valido. Ciononostante, la famiglia della vittima mantiene il massimo riserbo sulla vicenda, trincerandosi in un silenzio assoluto, in attesa di novit\u00e0 concrete e palpabili.<\/p>\n<p>&nbsp;<\/p>\n<p>La svolta, \u00e8 arrivata proprio ieri, con la riapertura di una commissione d\u2019inchiesta parlamentare: questa la proposta fatta dai deputati del Partito democratico Roberto Morassut, Michele Bordo e Walter Verini a luglio 2021, mesi prima che la Procura di Roma decidesse di riaprire il caso.<\/p>\n<p>Ad oggi difatti, anche\u00a0 la procura di Roma ha aperto una nuova indagine sul caso, coordinata dalla pm Ilaria Cal\u00f2, lo stesso magistrato che sostenne l\u2019accusa contro Raniero Busco, l\u2019ex fidanzato della vittima condannato a 24 anni nel 2011 e assolto nei due gradi successivi di giudizio.<\/p>\n<p>La speranza, resta pertanto quella di far luce su uno dei misteri irrisolti pi\u00f9 importanti d\u2019Italia: \u00a0un efferato e violento omicidio quello di Simonetta, percossa prima violentemente alla testa \u2013 colpo che le causer\u00e0 un profondo trauma cranico che la far\u00e0 svenire &#8211;\u00a0 e poi raggiunta da ben ventinove pugnalate inferte senza indugio e con una violenza inaudita al viso, sul corpo, sul seno e sul ventre.<\/p>\n<p>Perci\u00f2, il primo passo a distanza di trenta anni, resta uno solo e soltanto: sciogliere i nodi di questa matassa aggrovigliata, per venire\u00a0 finalmente a capo dell\u2019identit\u00e0 del violento omicida che si nasconde impunito da tanto, troppo tempo; un uomo per il momento ancora senza volto che ha strappato la vita a Simonetta nel fiore dei suoi anni.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/23\/svolta-nelle-indagini-del-delitto-di-via-poma-trentadue-anni-dopo-spuntano-anche-in-questaltro-mistero-italiano-irrisolto-le-ombre-della-banda-della-magliana-e-dei-servizi-segreti\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/23\/svolta-nelle-indagini-del-delitto-di-via-poma-trentadue-anni-dopo-spuntano-anche-in-questaltro-mistero-italiano-irrisolto-le-ombre-della-banda-della-magliana-e-dei-servizi-segreti\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Flora Fina ______ &nbsp; Il caso di Simonetta Cesaroni, passato alla storia come il \u201c Delitto di Via Poma \u201d si riapre improvvisamente in questi giorni,\u00a0 dopo trentadue anni di estenuante attesa e un fitto alone di mistero che avvolge ancora la vicenda. &nbsp; Era il pomeriggio del 7 agosto 1990, e la giovane [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":197104,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/197103"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=197103"}],"version-history":[{"count":7,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/197103\/revisions"}],"predecessor-version":[{"id":197114,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/197103\/revisions\/197114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/197104"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=197103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=197103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=197103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}