{"id":197115,"date":"2022-03-23T19:40:46","date_gmt":"2022-03-23T18:40:46","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=197115"},"modified":"2022-03-24T19:53:58","modified_gmt":"2022-03-24T18:53:58","slug":"dossier-massimo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/23\/dossier-massimo\/","title":{"rendered":"LA STORIA DI MASSIMO D&#8217;ALEMA MEDIATORE DELLE ARMI ALLA COLOMBIA COMINCIA QUI DAL NOSTRO SALENTO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-197123\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/12\/images.jpg\" alt=\"\" width=\"534\" height=\"400\" \/><\/p>\n<p>di <strong>Giuseppe Puppo<\/strong>\u00a0______<\/p>\n<p>Questa mattina si \u00e8 appreso da indiscrezioni giornalistiche attendibili che la Procura della Repubblica di Napoli ha aperto un fascicolo di indagine sul tentativo di vendita di armamenti &#8211; navi, sommergibili e aerei &#8211; prodotti dalle aziende italiane Fincantieri e Leonardo alla Colombia. La\u00a0 vicenda \u00e8 stata rivelata nelle ultime tre settimane, con dovizia di particolari, dal quotidiano La Verit\u00e0, in primis per quanto concerne il coinvolgimento dell&#8217;ex premier, prima Pci, poi Ds, ora esponente di Articolo Uno, Massimo D&#8217;Alema.<\/p>\n<p>I magistrati napoletani indagano dopo un esposto presentato dall&#8217;Assemblea Parlamentare del Mediterraneo, un&#8217;organizzazione di politici ed associazioni di cooperazione internazionale, che ha sede appunto a Napoli e che ha sconfessato i sedicenti mediatori nell&#8217;affare che l&#8217;hanno chiamata in causa, producendo documenti che sarebbero falsi.<\/p>\n<p>L&#8217;ipotesi di reato \u00e8 appunto falso, e di truffa e sostituzione di persona.<\/p>\n<p>&nbsp;<\/p>\n<p>Contemporaneamente alla notizia della magistratura, in queste ore, la presidenza del Senato ha dato il via libera alle audizioni per chiarire l\u2019intrigo della trattativa per la vendita di armi alla\u00a0 Colombia in sede di commissione -Difesa, del Senato appunto.<\/p>\n<p>Saranno sentiti direttamente i protagonisti.<\/p>\n<p>&nbsp;<\/p>\n<p>Come \u00e8 noto, la trattativa non \u00e8 andata in porto, trattandosi anche di navi \u00e8 proprio il caso di dirlo.<\/p>\n<p>C&#8217;era gi\u00e0 un canale ufficiale fra governo italiano e governo colombiano, quando il mese scorso spunt\u00f2 fuori l&#8217;interessamento di Massimo D&#8217;Alema, che si accredit\u00f2 come incaricato di facilitare l&#8217;affare presso l&#8217;ambasciatore e l&#8217;esecutivo colombiani.<\/p>\n<p>Il tentativo di mediazione sostitutiva, o parallela, ancora non \u00e8 chiaro, fu comunque portato a conoscenza, scoperto e bloccato dal sottosegretario alla Difesa del governo Draghi Giorgio Mul\u00e8, partito di appartenenza Forza Italia.<\/p>\n<p>A suo dire, mentre a dire di D&#8217;Alema sia pure indirettamente gli fu fatto sapere da lui di poter andare avanti.<\/p>\n<div class=\"c-article-section j-article-section l-spacing-m\">\n<p>Comunque sia \u00e8 a questo punto che D&#8217;Alema aveva messo fretta agli altri mediatori, aveva sollecitato a sbrigarsi a chiudere e aveva ipotizzato un margine di utile per la mediazione, da dividersi fra di loro, di ottanta milioni di euro, questo come da intercettazioni telefoniche pubblicate sui giornali, rispetto\u00a0 ad un affare del valore di quattro miliardi di euro.<\/p>\n<p>&nbsp;<\/p>\n<p>Sostiene D&#8217;Alema &#8211; \u00e8 la sua, di verit\u00e0 &#8211; di essersi mosso su richiesta di esponenti colombiani, di essersi limitato a dare loro consigli legali e amministrativi, di aver consigliato il coinvolgimento di uno studio legale americano, di aver fatto tutto questo senza nessuna prospettiva di interesse personale, ma solo per favorire commesse per aziende italiane.<\/p>\n<p>Rimangono, certo, al netto degli aspetti giudiziari, le questioni politiche e quelle morali, di un ex presidente del consiglio, esponente storico della sinistra, in seguito pure presidente del comitato parlamentare di controllo dei servizi segreti, che si mette a fare, fra gli altri suoi affari del tutto leciti, diversificati in diversi settori, anche il mercante di armi, o il facilitatore di mercanti di armi, strumenti di distruzione e di morte, perdi pi\u00f9 ceduti ad un regime diciamo &#8216;discusso&#8217;, diciamo &#8216;discutibile&#8217; come quello colombiano.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p>Di tutta questa intricata vicenda, comunque sia, a noi in redazione di leccecronaca.it ha colpito un solo\u00a0 aspetto, rimasto nascosto dagli altri,<\/p>\n<p><strong>Il fatto che anche questa vicenda dei giorni nostri di affari legata a Massimo D&#8217;Alema abbia radici qui nel nostro Salento.<\/strong><\/p>\n<p>Incredibile, ma pare che sia cos\u00ec.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-197124 size-full\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/12\/bunadue.jpg\" alt=\"\" width=\"800\" height=\"591\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/12\/bunadue.jpg 800w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/12\/bunadue-300x222.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/12\/bunadue-768x567.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Di nuovo, dopo tutti gli affari di D&#8217;Alema e dei suoi uomini salentini, del suo partito e di Forza Italia, che vanno dalla sanit\u00e0, ai gasdotti, e che abbiamo gi\u00e0 raccontato\u00a0 in dettaglio in un&#8217;inchiesta in tre puntate nel 2016<\/p>\n<ul>\n<li>I progenitori del gasdotto Tap e l&#8217;avvocato difensore del consorzio, 13 maggio 2016<\/li>\n<li>Il cerchio magico e il suo arcobaleno, 14 maggio 2016<\/li>\n<li>Il tip tap del cerchio magico con Silvio, 15 maggio 2016\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Acqua passata, si dir\u00e0, ed \u00e8 vero.\u00a0 Infatti, stiamo sul pezzo, guardiamo al presente.<\/li>\n<\/ul>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-197125 size-full\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/12\/mda.jpg\" alt=\"\" width=\"600\" height=\"399\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/12\/mda.jpg 600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/12\/mda-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Ma sar\u00e0 solo un caso, adesso,nel 2022, che la storia delle armi italiane proposte alla Colombia con il coinvolgimento di D&#8217;alema parta proprio dal Salento?<\/p>\n<p>Cercheremo di raccontarla nei prossimi giorni. Il tempo di raccogliere le informazioni in nostro possesso, di verificarle, e di esporle, ove risultassero attendibili, ai nostri lettori.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"s-native-sponsored\"><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/23\/dossier-massimo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/23\/dossier-massimo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Giuseppe Puppo\u00a0______ Questa mattina si \u00e8 appreso da indiscrezioni giornalistiche attendibili che la Procura della Repubblica di Napoli ha aperto un fascicolo di indagine sul tentativo di vendita di armamenti &#8211; navi, sommergibili e aerei &#8211; prodotti dalle aziende italiane Fincantieri e Leonardo alla Colombia. La\u00a0 vicenda \u00e8 stata rivelata nelle ultime tre settimane, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":197123,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/197115"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=197115"}],"version-history":[{"count":8,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/197115\/revisions"}],"predecessor-version":[{"id":197160,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/197115\/revisions\/197160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/197123"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=197115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=197115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=197115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}