{"id":197227,"date":"2022-03-25T15:17:22","date_gmt":"2022-03-25T14:17:22","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=197227"},"modified":"2022-03-25T18:30:12","modified_gmt":"2022-03-25T17:30:12","slug":"abusi-su-minore-un-arresto-a-taranto","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/25\/abusi-su-minore-un-arresto-a-taranto\/","title":{"rendered":"ABUSI SU MINORE, UN ARRESTO A TARANTO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-197236\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/1494775822-polizia-notte.jpg\" alt=\"\" width=\"718\" height=\"400\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/1494775822-polizia-notte.jpg 1011w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/1494775822-polizia-notte-300x167.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/03\/1494775822-polizia-notte-768x428.jpg 768w\" sizes=\"(max-width: 718px) 100vw, 718px\" \/><\/p>\n<p>(e.l.) ______\u00a0 \u00a0Un uomo di 53 anni della provincia di Taranto \u00e8 stato arrestato questa mattina dagli agenti della Polizia di Stato\u00a0 su ordinanza del gip del Tribunale. Si trova ora ai domiciliari, come disposto dall&#8217;autorit\u00e0 giudiziaria. L&#8217;accusa \u00e8 di violenza sessuale nei confronti di un minorenne, indotto in pi\u00f9 occasioni ad avere rapporti con lui.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/25\/abusi-su-minore-un-arresto-a-taranto\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/25\/abusi-su-minore-un-arresto-a-taranto\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______\u00a0 \u00a0Un uomo di 53 anni della provincia di Taranto \u00e8 stato arrestato questa mattina dagli agenti della Polizia di Stato\u00a0 su ordinanza del gip del Tribunale. Si trova ora ai domiciliari, come disposto dall&#8217;autorit\u00e0 giudiziaria. L&#8217;accusa \u00e8 di violenza sessuale nei confronti di un minorenne, indotto in pi\u00f9 occasioni ad avere rapporti con [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":197237,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/197227"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=197227"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/197227\/revisions"}],"predecessor-version":[{"id":197238,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/197227\/revisions\/197238"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/197237"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=197227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=197227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=197227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}