{"id":19742,"date":"2013-08-28T07:11:43","date_gmt":"2013-08-28T07:11:43","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=19742"},"modified":"2013-08-28T07:11:43","modified_gmt":"2013-08-28T07:11:43","slug":"svicat-rugby-asd-robuschi-si-presenta-entusiasmo-e-voglia-di-fare","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/28\/svicat-rugby-asd-robuschi-si-presenta-entusiasmo-e-voglia-di-fare\/","title":{"rendered":"SVICAT RUGBY ASD, ROBUSCHI SI PRESENTA : &#8220;ENTUSIASMO E VOGLIA DI FARE&#8221;"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/Riccardo-Robuschi.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/Riccardo-Robuschi-300x274.jpg\" alt=\"\" width=\"300\" height=\"274\" class=\"alignleft size-medium wp-image-19743\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/Riccardo-Robuschi-300x274.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/Riccardo-Robuschi.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u201cInizio questa nuova avventura con tanto entusiasmo e tanta voglia di fare\u201d. Sono queste le prime parole da evergreen di Riccardo Robuschi, estremo sudafricano ma di formazione italiana prelevato dal San Don\u00e0 di Piave. Il nuovo acquisto della Svicat ha parlato anche dei suoi nuovi compagni: \u201cE\u2019 importante che ci sia ancora l\u2019ossatura della squadra che ha vinto lo scorso anno; sono rimasto impressionato dalla fisicit\u00e0 di alcuni miei compagni di squadra. Percepisco tanto entusiasmo sia dentro che fuori lo spogliatoio, e proprio questo deve essere la nostra arma in pi\u00f9. Sono felice di trovare qui Coach Fedrigo, possiamo solo migliorare con lui\u201d.<\/p>\n<p>Un ultimo pensiero, poi, rivolto al Campionato di Serie B: \u201cCosa ne penso del calendario? Dispiace giocare la prima fuori casa, ma comunque dobbiamo affrontarle tutte. Sar\u00e0 un campionato duro, molto fisico e con trasferte lunghissime. Abbiamo i mezzi per fare bene\u201d.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/28\/svicat-rugby-asd-robuschi-si-presenta-entusiasmo-e-voglia-di-fare\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/28\/svicat-rugby-asd-robuschi-si-presenta-entusiasmo-e-voglia-di-fare\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u201cInizio questa nuova avventura con tanto entusiasmo e tanta voglia di fare\u201d. Sono queste le prime parole da evergreen di Riccardo Robuschi, estremo sudafricano ma di formazione italiana prelevato dal San Don\u00e0 di Piave. Il nuovo acquisto della Svicat ha parlato anche dei suoi nuovi compagni: \u201cE\u2019 importante che ci sia ancora l\u2019ossatura della squadra [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19743,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19742"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19742"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19742\/revisions"}],"predecessor-version":[{"id":19745,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19742\/revisions\/19745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19743"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=19742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=19742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=19742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}