{"id":19835,"date":"2013-08-31T07:43:32","date_gmt":"2013-08-31T07:43:32","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=19835"},"modified":"2013-08-31T07:43:32","modified_gmt":"2013-08-31T07:43:32","slug":"aiuole-posacenere-e-piante-pattumiera","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/31\/aiuole-posacenere-e-piante-pattumiera\/","title":{"rendered":"AIUOLE  POSACENERE E PIANTE PATTUMIERA"},"content":{"rendered":"\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 20%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\t\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-19835 gallery-columns-5 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/31\/aiuole-posacenere-e-piante-pattumiera\/via-imp-adriano-aiuole-1\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/via-Imp-Adriano-aiuole-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/31\/aiuole-posacenere-e-piante-pattumiera\/via-imp-adriano-aiuole-2\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/via-Imp-Adriano-aiuole-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/31\/aiuole-posacenere-e-piante-pattumiera\/via-imp-adriano-aiuole-3-jpg\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/via-Imp-Adriano-aiuole-3.jpg-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/31\/aiuole-posacenere-e-piante-pattumiera\/via-imp-adriano-aiuole-4\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/via-Imp-Adriano-aiuole-4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/31\/aiuole-posacenere-e-piante-pattumiera\/via-imp-adriano-aiuole-5\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/via-Imp-Adriano-aiuole-5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/31\/aiuole-posacenere-e-piante-pattumiera\/via-imp-adriano-aiuole-6\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/08\/via-Imp-Adriano-aiuole-6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>Le fotografie sono inequivocabili: aiuole trasformate in posacenere e porta piante scambiati per pattumiera in via Imperatore Adriano a Lecce. Ancora una volta sono i cittadini a segnalare a Giovanni D\u2019Agata, presidente dello \u201cSportello dei Diritti\u201d, lo scempio cui si \u00e8 costretti ad assistere se si percorre la centralissima via, e che quindi, va ad incidere profondamente sul decoro del centro urbano.<\/p>\n<p>Questa volta, dunque, \u00e8 la centralissima via Imperatore Adriano e non la periferia ad essere al centro delle legittime polemiche dei cittadini, dove le piccole aiuole poste al di sotto degli alberi di \u201cPrunus cerasi fera\u201d situati ai lati della pubblica via, risultano essere in evidente stato di abbandono tanto da essere divenute dei portaceneri per mozziconi di sigarette, insieme a porta piante scambiate per pattumiera dove alcuni passanti li hanno trasformati in comodi cestini portarifiuti di carte, cartacce e pacchetti di sigarette che sono finiti nel vano che dovrebbe ospitare l\u2019addobbo floreale.<\/p>\n<p>\u00c8 ovvio che la responsabilit\u00e0 di questa situazione sia attribuibile ai comportamenti di soggetti incuranti delle bench\u00e9 minime regole della civile convivenza, figuriamoci della tutela ambientale, ma insieme a coloro che ci hanno denunciato lo scempio richiediamo l\u2019immediata pulizia delle aiuole anche perch\u00e9, purtroppo, la permanente incuranza dell\u2019amministrazione comunale \u00e8 causa di comportamenti emulativi negativi.<\/p>\n<p>Ricordiamo, inoltre, che gettare per terra un mozzicone di sigaretta pu\u00f2 costare caro: \u00e8 prevista, infatti, una sanzione amministrativa pecuniaria di 500 euro per coloro che, seppur raramente, vengono beccati a ripetere questo gesto incivile.<\/p>\n<p><strong>GIOVANNI D&#8217;AGATA\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/31\/aiuole-posacenere-e-piante-pattumiera\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/08\/31\/aiuole-posacenere-e-piante-pattumiera\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Le fotografie sono inequivocabili: aiuole trasformate in posacenere e porta piante scambiati per pattumiera in via Imperatore Adriano a Lecce. Ancora una volta sono i cittadini a segnalare a Giovanni D\u2019Agata, presidente dello \u201cSportello dei Diritti\u201d, lo scempio cui si \u00e8 costretti ad assistere se si percorre la centralissima via, e che quindi, va ad [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19835"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19835"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19835\/revisions"}],"predecessor-version":[{"id":19842,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19835\/revisions\/19842"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=19835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=19835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=19835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}