{"id":198735,"date":"2022-04-28T08:20:25","date_gmt":"2022-04-28T06:20:25","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=198735"},"modified":"2022-04-28T16:52:45","modified_gmt":"2022-04-28T14:52:45","slug":"per-fratelli-ditalia-sempre-piu-centralita-politica","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/04\/28\/per-fratelli-ditalia-sempre-piu-centralita-politica\/","title":{"rendered":"&#8220;Per Fratelli d&#8217;Italia sempre pi\u00f9 centralit\u00e0 politica&#8221;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-198736\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/04\/274271272_379178074029455_2860096994979111291_n.jpg\" alt=\"\" width=\"692\" height=\"692\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/04\/274271272_379178074029455_2860096994979111291_n.jpg 692w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/04\/274271272_379178074029455_2860096994979111291_n-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/04\/274271272_379178074029455_2860096994979111291_n-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/04\/274271272_379178074029455_2860096994979111291_n-60x60.jpg 60w\" sizes=\"(max-width: 692px) 100vw, 692px\" \/><\/p>\n<p>Riceviamo e volentieri pubblichiamo. Il coordinatore provinciale di Fratelli d&#8217;Italia di Lecce Saverio Congedo ci manda il seguente comunicato\u00a0\u00a0______<\/p>\n<p>&nbsp;<\/p>\n<p>Prosegue la fase\u00a0riorganizzativa\u00a0di Fratelli d\u2019Italia in provincia di Lecce con la nomina\u00a0o la conferma dei coordinatori cittadini di quaranta comuni della provincia. Nei comuni con pi\u00f9 di 15.000 abitanti &#8211; Nard\u00f2, Gallipoli, Copertino, Tricase e Casarano &#8211; il Partito ha ritenuto di indicare quali rappresentanti di Fratelli d\u2019Italia sul territorio figure di esperienza e competenza al fine di fornire punti di riferimento autorevoli ai tanti militanti e iscritti, in una prospettiva di allargamento della\u00a0base sociale ed elettorale.\u00a0Nei prossimi giorni si proceder\u00e0 all\u2019individuazione dei coordinatori degli altri comuni per completare lo scacchiere organizzativo provinciale di Fratelli d\u2019Italia.<\/p>\n<p>Queste scelte di carattere organizzativo, cos\u00ec come la\u00a0definizione della linea politica,\u00a0sono frutto del lavoro svolto insieme alle principali figure istituzionali del territorio come l\u2019On. Raffaele Fitto e il consigliere regionale Antonio Gabellone, in un clima di condivisione con i vertici nazionali e regionali, pre-condizione che costituisce un punto di forza per valorizzare al meglio le potenzialit\u00e0 di Fratelli d\u2019Italia.<\/p>\n<p>L\u2019obiettivo \u00e8 quello di dare al Partito\u00a0sempre maggiore\u00a0protagonismo e centralit\u00e0 politica in sintonia con l\u2019impegno che Fratelli d\u2019Italia, guidato dalla sua leader Giorgia Meloni, sta profondendo a tutti i livelli raccogliendo fiducia e apprezzamenti diffusi, come testimonia il livello di gradimento fra gli italiani che ne\u00a0 fa il primo partito della nazione. &#8220;La crescita di FdI -commenta il coordinatore regionale, on. Marcello Gemmato- \u00e8 sempre pi\u00f9 tangibile, lo stesso mi sento di dire per l&#8217;attrattivit\u00e0 della linea politica e del presidente Giorgia Meloni. Il duro lavoro di questi anni sta portando buoni frutti e sono certo che i nuovi coordinatori cittadini della provincia di Lecce sapranno essere bandiera di Partito&#8221;.<\/p>\n<p>Ai coordinatori cittadini il ringraziamento per aver accettato questo impegno gravoso e gli auguri di buon lavoro.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Di seguito l\u2019elenco delle nomine nei diversi comuni:<\/b><\/p>\n<p>1. Aradeo: ARCUTI Walter<\/p>\n<p>2. Arnesano: MEZZANZANICA Massimiliano<\/p>\n<p>3. Bagnolo: MARIANO Sonia<\/p>\n<p>4.\u00a0Botrugno: BIASCO Giovanni<\/p>\n<p>5. Calimera: MONTINARO Andrea<\/p>\n<p>6.\u00a0Casarano: STEFANO Gianni<\/p>\n<p>7.\u00a0Castri di Lecce: GIANNONE Marco<\/p>\n<p>8.\u00a0\u00a0Castrignano Capo: VITALI Luigi<\/p>\n<p>9.\u00a0 Cavallino: RIZZO Isabella<\/p>\n<p>10.\u00a0Copertino: BASILE Dino<\/p>\n<p>11.\u00a0Cutrofiano: MASCIULLO Lillino<\/p>\n<p>12.\u00a0Gagliano: SERGI Giacomo<\/p>\n<p>13.\u00a0Galatina:\u00a0<b>CONGEDO\u00a0<\/b><b>Saverio<\/b><\/p>\n<p>14.\u00a0Galatone: VETRACCA Antonio<\/p>\n<p>15.\u00a0Gallipoli: CONGEDO Saverio<\/p>\n<p>16.\u00a0Giurdignano:\u00a0DE GIUSEPPE\u00a0Cristian<\/p>\n<p>17.\u00a0Guagnano: CATAROZZOLO Bruno<\/p>\n<p>18.\u00a0Leverano: POLITANO Giuseppe<\/p>\n<p>19.\u00a0Lizzanello: CUCURACHI Massimiliano<\/p>\n<p>20.\u00a0Maglie: SARICONI Luca<\/p>\n<p>21. Matino: SABATO Alberto<\/p>\n<p>22. Melendugno: STABILE Renato<\/p>\n<p>23.\u00a0Melissano: CAPUTO Lorenzo<\/p>\n<p>24.\u00a0Minervino: RUGGERI Tonino<\/p>\n<p>25. Monteroni: MANCARELLA\u00a0Diego<\/p>\n<p>26.\u00a0Nard\u00f2: GABELLONE Antonio<\/p>\n<p>27. Nociglia: PATALEO Luana<\/p>\n<p>28.\u00a0Otranto:\u00a0BRUNI\u00a0Francesco<\/p>\n<p>29.\u00a0Porto Cesareo: POTENZA Gabriele<\/p>\n<p>30.\u00a0Ruffano: DE VITIS Franco<\/p>\n<p>31.\u00a0Salve: VILLANOVA Gino<\/p>\n<p>32.\u00a0Sogliano: CONGEDO Giuseppe<\/p>\n<p>33.\u00a0Spongano: SCARCIGLIA Fernando<\/p>\n<p>34.\u00a0Taviano: TUNNO Leonardo<\/p>\n<p>35.\u00a0Tricase: GABELLONE Antonio<\/p>\n<p>36.\u00a0Tuglie: PERRONE Ugo<\/p>\n<p>37.\u00a0Veglie: CATAMO Lorenzo<\/p>\n<p>38.\u00a0Vernole: VESTITO Mauro<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/04\/28\/per-fratelli-ditalia-sempre-piu-centralita-politica\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/04\/28\/per-fratelli-ditalia-sempre-piu-centralita-politica\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Il coordinatore provinciale di Fratelli d&#8217;Italia di Lecce Saverio Congedo ci manda il seguente comunicato\u00a0\u00a0______ &nbsp; Prosegue la fase\u00a0riorganizzativa\u00a0di Fratelli d\u2019Italia in provincia di Lecce con la nomina\u00a0o la conferma dei coordinatori cittadini di quaranta comuni della provincia. Nei comuni con pi\u00f9 di 15.000 abitanti &#8211; Nard\u00f2, Gallipoli, Copertino, Tricase e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":198736,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/198735"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=198735"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/198735\/revisions"}],"predecessor-version":[{"id":198747,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/198735\/revisions\/198747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/198736"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=198735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=198735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=198735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}