{"id":19891,"date":"2013-09-05T08:06:55","date_gmt":"2013-09-05T08:06:55","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=19891"},"modified":"2013-09-05T08:06:55","modified_gmt":"2013-09-05T08:06:55","slug":"arrestato-insospettabile-spacciatore","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/05\/arrestato-insospettabile-spacciatore\/","title":{"rendered":"ARRESTATO INSOSPETTABILE SPACCIATORE"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/05\/arrestato-insospettabile-spacciatore\/droga-e-contanti-sequestro-spaccio-marijuana\/\" rel=\"attachment wp-att-19892\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/09\/Droga-e-contanti-sequestro-spaccio-marijuana-150x150.jpg\" alt=\"\" title=\"Droga e contanti sequestro spaccio marijuana\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-19892\" \/><\/a>I militari dell\u2019Aliquota Operativa della Compagnia di Gallipoli hanno proceduto, nella mattina odierna, all\u2019arresto di un soggetto, VISONE Francesco, 56enne nativo di Pollena Trocchia (NA), ma domiciliato in Gallipoli da ormai sette anni, ove portava avanti un\u2019attivit\u00e0 di vendita di souvenir in Gallipoli vecchia. I Carabinieri di Gallipoli, ormai da qualche giorno, avevano visto uno strano movimento da e per l\u2019abitazione del VISONE, soprattutto nelle ore notturne, di ragazzi che con scooter o anche a piedi, si fermavano sotto l\u2019abitazione, incontravano il soggetto per pochi minuti e poi sparivano nella notte. Nella mattinata odierna, visti questi movimenti, i militari hanno proceduto a fermare il VISONE per poi avviare la perquisizione domiciliare. Nonostante affermasse di non detenere alcuna sostanza stupefacente, in un sottoscala, all\u2019interno di un cestino di vimini, i carabinieri hanno rinvenuto 4 pezzi di HASHISH, per un peso di oltre 35 grammi, un coltello intriso della medesima sostanza, un bilancino di precisione e la somma di \u20ac 3500 in contanti. La sorpresa dei militari \u00e8 stata grande quando, nel prosieguo della perquisizione, dietro ad un mobile della camera da letto, sono stati rinvenuti oltre 20.000 euro in contanti, buttati alla rinfusa. Inoltre al piano superiore dell\u2019abitazione, in una stanza adibita a deposito, in uno zaino nascosto dietro un armadio, venivano trovati altri 30.000 euro in contanti. In tutto, quindi, oltre 50.000 euro in contanti dei quali il VISONE non ha potuto giustificare a sufficienza la provenienza e che vengono quindi ritenuti provento dell\u2019attivit\u00e0 di spaccio. Arrestato e sottoposto alle formalit\u00e0 di rito, su disposizione del Dott. Massimiliano Carducci, Sostituto Procuratore della Repubblica e Pubblico Ministero di Turno, il VISONE \u00e8 stato accompagnato nella propria abitazione, sottoposto alla misura degli arresti domiciliari. Lo stesso \u00e8 difeso dall\u2019Avv. Luca LATERZA del Foro di Lecce.<\/p>\n<p style=\"text-align: left;\" align=\"center\"><em><br \/>\n<\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/05\/arrestato-insospettabile-spacciatore\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/05\/arrestato-insospettabile-spacciatore\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>I militari dell\u2019Aliquota Operativa della Compagnia di Gallipoli hanno proceduto, nella mattina odierna, all\u2019arresto di un soggetto, VISONE Francesco, 56enne nativo di Pollena Trocchia (NA), ma domiciliato in Gallipoli da ormai sette anni, ove portava avanti un\u2019attivit\u00e0 di vendita di souvenir in Gallipoli vecchia. I Carabinieri di Gallipoli, ormai da qualche giorno, avevano visto uno [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19892,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19891"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19891"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19891\/revisions"}],"predecessor-version":[{"id":19894,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19891\/revisions\/19894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19892"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=19891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=19891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=19891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}