{"id":199116,"date":"2022-05-05T11:37:12","date_gmt":"2022-05-05T09:37:12","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=199116"},"modified":"2022-05-05T11:40:46","modified_gmt":"2022-05-05T09:40:46","slug":"ma-il-governo-italiano-se-ne-frega-delle-condanne-internaionali","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/05\/05\/ma-il-governo-italiano-se-ne-frega-delle-condanne-internaionali\/","title":{"rendered":"&#8230;MA IL GOVERNO ITALIANO SE NE FREGA DELLE CONDANNE INTERNAZIONALI, IL MOSTRO CONTINUA AD AVVELENARE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-199117\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/05\/1554462057189.jpg-taranto__in_quartiere_tamburi_agenti_inquinanti_piu_alti_rispetto_al_2018.jpg\" alt=\"\" width=\"970\" height=\"500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/05\/1554462057189.jpg-taranto__in_quartiere_tamburi_agenti_inquinanti_piu_alti_rispetto_al_2018.jpg 970w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/05\/1554462057189.jpg-taranto__in_quartiere_tamburi_agenti_inquinanti_piu_alti_rispetto_al_2018-300x155.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/05\/1554462057189.jpg-taranto__in_quartiere_tamburi_agenti_inquinanti_piu_alti_rispetto_al_2018-768x396.jpg 768w\" sizes=\"(max-width: 970px) 100vw, 970px\" \/><\/p>\n<p>(Rdl) ______\u00a0 Questa mattina a Strasburgo la Cedu, la Corte europea dei diritti umani, ha emesso quattro nuove condanne contro lo Stato italiano, a causa delle emissioni dell&#8217;Ilva che attentano alla salute dei cittadini.<\/p>\n<p>Queste nuove condanne &#8211; che si aggiungono a una nutrita schiera di decisioni analoghe, di altri organismi internazionali &#8211; riguardano i ricorsi presentati tra il 2016 e il 2019 da alcuni dipendenti me da duecento abitanti di Taranto e di alcuni comuni vicini.<\/p>\n<p>A loro nome, la professoressa Lina Ambrogi Melle, presidente del comitato donne e futuro per Taranto libera, aveva sottolineato il\u00a0grave e persistente inquinamento dell\u2019aria, del suolo e delle acque da parte del complesso siderurgico\u00a0 ex-Ilva.<\/p>\n<p>&nbsp;<\/p>\n<p>Si tratta di un secondo ricorso contro lo Stato italiano \u00a0presentato dagli avvocati dello studio legale internazionale Saccucci di Roma, che gi\u00e0 ci hanno rappresentato nel precedente ricorso conclusosi con la sentenza del 24 gennaio 2019, divenuta definitiva in data 24 giugno 2019, di \u00a0condanna dello Stato italiano per non aver protetto la salute\u00a0della popolazione.<\/p>\n<p>&nbsp;<\/p>\n<p>Con questo secondo ricorso sono stati portati a conoscenza della Corte tutti gli avvenimenti verificatisi successivamente alla precedente sentenza \u00a0di condanna e veniva chiesto di accertare anche la violazione\u00a0 del diritto alla vita.<\/p>\n<p>Volevano e hanno ottenuto i ricorrenti\u00a0l\u2019adozione di\u00a0 una sentenza pilota da adottare al fine di porre termine alle violazioni entro un arco temporale definito.\u00a0\u00a0______<\/p>\n<p>L&#8217;APPROFONDIMENTO nei nostro ultimi tre articoli dei mesi scorsi dedicati alla questione<\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"nBNQotbfoD\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/26\/taranto-da-giorni-sotto-attacco-di-armi-chimiche-il-mostro-continua-ad-avvelenare-e-uccidere\/\">TARANTO SOTTO ATTACCO CON ARMI CHIMICHE, IL MOSTRO CONTINUA AD AVVELENARE E UCCIDERE<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/03\/26\/taranto-da-giorni-sotto-attacco-di-armi-chimiche-il-mostro-continua-ad-avvelenare-e-uccidere\/embed\/#?secret=nBNQotbfoD\" data-secret=\"nBNQotbfoD\" width=\"500\" height=\"282\" title=\"&#8220;TARANTO SOTTO ATTACCO CON ARMI CHIMICHE, IL MOSTRO CONTINUA AD AVVELENARE E UCCIDERE&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"xJcoDsPvcm\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/02\/22\/il-mostro-che-avvelena-e-uccide-taranto\/\">IL MOSTRO CHE AVVELENA E UCCIDE TARANTO<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/02\/22\/il-mostro-che-avvelena-e-uccide-taranto\/embed\/#?secret=xJcoDsPvcm\" data-secret=\"xJcoDsPvcm\" width=\"500\" height=\"282\" title=\"&#8220;IL MOSTRO CHE AVVELENA E UCCIDE TARANTO&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"eYJ6EOUicH\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/02\/15\/il-mostro-avvelena-e-uccide-ora-lo-dice-pure-lonu-in-un-rapporto-choc-che-accusa-il-governo-italiano-di-crimini-contro-l-umanita-chissa-se-a-beppe-grillo-e-a-luigi-di-maio-stanno-fischiando\/\">IL MOSTRO AVVELENA E UCCIDE, ORA LO DICE PURE L&#8217;ONU IN UN RAPPORTO CHOC CHE ACCUSA IL GOVERNO ITALIANO DI CRIMINI CONTRO L&#8217; UMANITA&#8217;. CHISSA&#8217; SE A BEPPE GRILLO E A LUIGI DI MAIO FISCHIANO LE ORECCHIE&#8230;<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/02\/15\/il-mostro-avvelena-e-uccide-ora-lo-dice-pure-lonu-in-un-rapporto-choc-che-accusa-il-governo-italiano-di-crimini-contro-l-umanita-chissa-se-a-beppe-grillo-e-a-luigi-di-maio-stanno-fischiando\/embed\/#?secret=eYJ6EOUicH\" data-secret=\"eYJ6EOUicH\" width=\"500\" height=\"282\" title=\"&#8220;IL MOSTRO AVVELENA E UCCIDE, ORA LO DICE PURE L&#8217;ONU IN UN RAPPORTO CHOC CHE ACCUSA IL GOVERNO ITALIANO DI CRIMINI CONTRO L&#8217; UMANITA&#8217;. CHISSA&#8217; SE A BEPPE GRILLO E A LUIGI DI MAIO FISCHIANO LE ORECCHIE&#8230;&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/05\/05\/ma-il-governo-italiano-se-ne-frega-delle-condanne-internaionali\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/05\/05\/ma-il-governo-italiano-se-ne-frega-delle-condanne-internaionali\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl) ______\u00a0 Questa mattina a Strasburgo la Cedu, la Corte europea dei diritti umani, ha emesso quattro nuove condanne contro lo Stato italiano, a causa delle emissioni dell&#8217;Ilva che attentano alla salute dei cittadini. Queste nuove condanne &#8211; che si aggiungono a una nutrita schiera di decisioni analoghe, di altri organismi internazionali &#8211; riguardano i [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":199117,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/199116"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=199116"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/199116\/revisions"}],"predecessor-version":[{"id":199123,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/199116\/revisions\/199123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/199117"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=199116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=199116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=199116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}