{"id":19965,"date":"2013-09-13T07:26:55","date_gmt":"2013-09-13T07:26:55","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=19965"},"modified":"2013-09-13T07:27:57","modified_gmt":"2013-09-13T07:27:57","slug":"copertino-scippo-arrestati-due-ventenni","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/13\/copertino-scippo-arrestati-due-ventenni\/","title":{"rendered":"Copertino. Scippo, arrestati due ventenni."},"content":{"rendered":"<div style=\"text-align: -webkit-auto;\"><strong><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/11\/scippa-una-signora-nella-tarda-serata-immediatamente-arrestato\/criminalita-quattro-scippi-in-unora-20enne-preso-a-napoli\/\" rel=\"attachment wp-att-19944\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/09\/scippo-150x150.jpg\" alt=\"\" title=\"CRIMINALITA', QUATTRO SCIPPI IN UN'ORA: 20ENNE PRESO A NAPOLI\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-19944\" \/><\/a>Copertino<\/strong>.\u00a0 I Carabinieri della Tenenza di Copertino hanno arrestato in flagranza di reato\u00a0<strong>Gabriele Lezzi<\/strong>\u00a0e\u00a0<strong>Lorenzo Selce<\/strong>, entrambi ventenni del luogo, accusati di furto con strappo.<\/div>\n<p>Ieri sera un cinquantaquattrenne di Copertino, mentre sta rientrando a casa, nel centro abitato, si \u00e8 visto sbarrare la strada dai due ragazzi che gli hanno strappato la collana che portava al collo, del valore di ben\u00a0<strong>millecinquecento euro,<\/strong>\u00a0dandosi alla fuga.<\/p>\n<p>La vittima si \u00e8 recata subito dai Carabinieri della locale Tenenza denunciando il fatto e fornendo indicazioni utili alla loro individuazione. Scattate le ricerche i due sono stati rintracciati, uno dopo l\u2019altro, nella tarda serata\u00a0 e durante la notte.<\/p>\n<p>Le indagini sono supportate anche dal contributo di altri testimoni, che hanno riferito notizie ed indicazioni utili soprattutto per individuare uno dei due presunti correi.<\/p>\n<p>I due arrestati, cos\u00ec come disposto dal Pubblico Ministero Antonio Negro della Procura di Lecce sono stati condotti in carcere.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/13\/copertino-scippo-arrestati-due-ventenni\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/13\/copertino-scippo-arrestati-due-ventenni\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Copertino.\u00a0 I Carabinieri della Tenenza di Copertino hanno arrestato in flagranza di reato\u00a0Gabriele Lezzi\u00a0e\u00a0Lorenzo Selce, entrambi ventenni del luogo, accusati di furto con strappo. Ieri sera un cinquantaquattrenne di Copertino, mentre sta rientrando a casa, nel centro abitato, si \u00e8 visto sbarrare la strada dai due ragazzi che gli hanno strappato la collana che portava [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19944,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19965"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=19965"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19965\/revisions"}],"predecessor-version":[{"id":19969,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/19965\/revisions\/19969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/19944"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=19965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=19965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=19965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}