{"id":20025,"date":"2013-09-16T09:47:23","date_gmt":"2013-09-16T09:47:23","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=20025"},"modified":"2013-09-16T09:47:23","modified_gmt":"2013-09-16T09:47:23","slug":"riva-degli-angeli-scatta-il-sequestro-preventivo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/16\/riva-degli-angeli-scatta-il-sequestro-preventivo\/","title":{"rendered":"Riva degli Angeli: scatta il sequestro preventivo"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/16\/riva-degli-angeli-scatta-il-sequestro-preventivo\/riva-degli-angeli-cc-campi\/\" rel=\"attachment wp-att-20026\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/09\/Riva-degli-Angeli-CC-Campi-150x150.jpg\" alt=\"\" title=\"Riva degli Angeli CC Campi\" width=\"150\" height=\"150\" \/><\/a>I carabinieri dell&#8217;Aliquota Operativa della Compagnia di Campi Salentina, questa mattina, hanno proceduto al sequestro preventivo emesso dal G.I.P. di Lecce su richiesta del Pubblico Ministero Carmen Ruggiero, del complesso turistico Riva degli Angeli. Il complesso, che sorge nel comune di Porto Cesareo, era gi\u00e0 sotto sequestro penale dal 22.02.2013 per abusivismo edilizio. Nel corso delle ulteriori indagini e soprattutto alla luce della consulenza tecnica disposta dal P.M., cambia il titolo del reato contestato a Durante Giuseppe e ad altri soggetti in corso di identificazione, in quello di lottizzazione abusiva. In altre parole, allo stato del procedimento, sarebbe emerso che sul terreno ove sorge il complesso turistico suddetto, a partire dal lontano 1984, si sia operata una vera e propria trasformazione dell&#8217;assetto urbanistico in violazione degli strumenti urbanistici vigenti. Cos\u00ec scrive il G.I.P.: &#8220;L&#8217;attento esame degli atti consentir\u00e0 di concludere, concordemente al pm, che le opere realizzate sono assolutamente incompatibili con la destinazione urbanistica della zona, finalizzate a realizzare un ampio complesso residenziale che fin dal primo momento verr\u00e0 progressivamente ampliato sempre con il medesimo sistema truffaldino che prevedeva la presentazione di formali richieste di titoli edilizi quali varianti, richieste di sanatoria (mai concesse) senza alcuna determinazione sanzionatoria, nonch\u00e9 illecite richieste di modifiche di destinazione d&#8217;uso di singole strutture (cabine trasformate in cosidetti bungalow ma sostanzialmente in appartamenti non compatibili con la destinazione di zona) e ci\u00f2 grazie anche ad una serie di omessi controlli ed abusi dell&#8217;Amministrazione. Dagli accertamenti \u00e8 emerso inconfutabilmente come su quel terreno comunale di Porto Cesareo, pari a mq 77.076 si \u00e8 verificata una continua attivit\u00e0 di trasformazione urbanistico-edilizia avviata negli anni 84-85 e tutt&#8217;ora in atto, con realizzazione di un insediamento residenziale, comprensivo di strutture varie, parcheggi ed edifici destinati a molteplici usi, con una tipologia riservata dallo strumento urbanistico dell&#8217;epoca alle zone di sviluppo turistico C5 che prevedeva: &#8216;insediamenti residenziali ed alberghieri, locali per lo spettacolo&#8217;.<\/p>\n<p>La zona oggetto dell&#8217;illecito intervento di trasformazione urbanistica era invece caratterizzata come F7, ricompresa nelle &#8216;zone agricole di salvaguardia paesaggistica&#8217; sulle quali erano consentiti stabilimenti balneari, attrezzature consimili, dancing, ristoranti bar, piscine scoperte, previste come strutture prive di carattere di continuit\u00e0 tutto sottoposto ai pareri della Sovrintendenza ai monumenti e dell&#8217;Ufficio Urbanistico della Regione Puglia&#8221;. La trasformazione urbanistica \u00e8 considerata in atto (la lottizzazione abusiva \u00e8 un reato permanente), in quanto alcuni locali all&#8217;interno del complesso sono in fase di allestimento o si presentano sotto forma di rustico, e in quanto lo stesso Durante, il 10.10.12, a seguito di alcuni rilievi mossi dall&#8217;Asl, ha comunicato al Comune la chiusura del complesso poich\u00e9 &#8220;\u00e8 in atto un progetto generale di ristrutturazione. . . per la competitivit\u00e0 del mercato turistico-ricettivo&#8221;.<\/p>\n<p>In conclusione del provvedimento, il G.I.P., concordando con la tesi del P.M., ha ritenuto di sollecitare l&#8217;identificazione e quindi l&#8217;iscrizione nel registro degli indagati di tutti coloro che, a vario titolo, nel corso degli anni, hanno concorso nella lottizzazione abusiva, come ad esempio i progettisti incaricati o i soggetti che hanno rilasciato i titoli autorizzatori in violazione di legge.<a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/16\/riva-degli-angeli-scatta-il-sequestro-preventivo\/riva-degli-angeli-cc-campi\/\" rel=\"attachment wp-att-20026\"><br \/>\n<\/a><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/16\/riva-degli-angeli-scatta-il-sequestro-preventivo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/16\/riva-degli-angeli-scatta-il-sequestro-preventivo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>I carabinieri dell&#8217;Aliquota Operativa della Compagnia di Campi Salentina, questa mattina, hanno proceduto al sequestro preventivo emesso dal G.I.P. di Lecce su richiesta del Pubblico Ministero Carmen Ruggiero, del complesso turistico Riva degli Angeli. Il complesso, che sorge nel comune di Porto Cesareo, era gi\u00e0 sotto sequestro penale dal 22.02.2013 per abusivismo edilizio. Nel corso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20026,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20025"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=20025"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20025\/revisions"}],"predecessor-version":[{"id":20029,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20025\/revisions\/20029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/20026"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=20025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=20025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=20025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}