{"id":20031,"date":"2013-09-13T09:52:11","date_gmt":"2013-09-13T09:52:11","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=20031"},"modified":"2013-09-16T09:56:47","modified_gmt":"2013-09-16T09:56:47","slug":"redditometro-nessuna-norma-stabilisce-la-retrodatazione-degli-scostamenti-ad-annualita-prescritte","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/13\/redditometro-nessuna-norma-stabilisce-la-retrodatazione-degli-scostamenti-ad-annualita-prescritte\/","title":{"rendered":"Redditometro: nessuna norma stabilisce la retrodatazione degli scostamenti ad annualit\u00e0 prescritte."},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/13\/redditometro-nessuna-norma-stabilisce-la-retrodatazione-degli-scostamenti-ad-annualita-prescritte\/agenzia-delle-entrate_vetro-960x640\/\" rel=\"attachment wp-att-20032\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/09\/agenzia-delle-entrate_vetro-960x640-150x150.jpg\" alt=\"\" title=\"agenzia-delle-entrate_vetro-960x640\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-20032\" \/><\/a>L\u2019applicazione del nuovo e temuto redditometro sta creando, com\u2019era prevedibile, non pochi problemi applicativi. Ecco perch\u00e9 Giovanni D\u2019Agata presidente e fondatore dello \u201cSportello dei Diritti\u201d suggerisce la lettura dell\u2019articolo scritto a due mani dai due tributaristi avvocati Maurizio Villani e Francesca Giorgia Romana Sannicandro di seguito riportato e pubblicato in anteprima sul sito www.sportellodeidiritti.org, in particolare circa la carenza di connessione tra vecchia disciplina e nuova, specie per ci\u00f2 che concerne gli scostamenti con le annualit\u00e0 prescritte. In particolare, \u00e8 possibile verificare che in assenza di una norma transitoria, per l\u2019anno 2008 gli uffici fiscali non possono notificare gli accertamenti in base alla vecchia normativa, in quanto l\u2019anno 2007 risulta essere prescritto (salvo l\u2019omessa dichiarazione).<\/p>\n<p>Lecce, 06 settembre 2013<\/p>\n<p>Giovanni D\u2019AGATA<\/p>\n<p>Non era difficile immaginare che le problematiche sottese al redditometro si moltiplicassero alla luce delle nuove disposizioni che non sono mai state connesse con la vecchia disciplina, ancora applicabile per le annualit\u00e0 ante 2009.<\/p>\n<p>La vecchia formulazione dell\u2019art. 38 del D.P.R. n. 600\/73 (ovvero quella in vigore fino al periodo 2008), prevedeva che:<\/p>\n<p>\u201cL&#8217;ufficio, indipendentemente dalle disposizioni recate dai commi precedenti e dell&#8217;articolo 39, pu\u00f2, in base ad elementi e circostanze di fatto certi, determinare sinteticamente il reddito complessivo netto del contribuente in relazione al contenuto induttivo di tali elementi e circostanze quando il reddito complessivo netto accertabile si discosta per almeno un quarto da quello dichiarato. A tal fine, con decreto del Ministro delle finanze, da pubblicare nella Gazzetta Ufficiale, sono stabilite le modalit\u00e0 in base alle quali l&#8217;ufficio pu\u00f2 determinare induttivamente il reddito o il maggior reddito in relazione ad elementi indicativi di capacit\u00e0 contributiva individuati con lo stesso decreto, quando il reddito dichiarato non risulta congruo rispetto ai predetti elementi per due o pi\u00f9 periodi di imposta.\u201d.<\/p>\n<p>Il D.L. 31.05.2010, n. 78, art. 22, conv. con modif. con L. 30.07.2010, n. 122, ha modificato la citata norma ai commi 4,5,6,7 ed 8; infatti la nuova formulazione della norma prevede che:<\/p>\n<p>\u201cL&#8217;ufficio, indipendentemente dalle disposizioni recate dai commi precedenti e dall&#8217;articolo 39, pu\u00f2 sempre determinare sinteticamente il reddito complessivo del contribuente sulla base delle spese di qualsiasi genere sostenute nel corso del periodo d&#8217;imposta, salva la prova che il relativo finanziamento \u00e8 avvenuto con redditi diversi da quelli posseduti nello stesso periodo d&#8217;imposta, o con redditi esenti o soggetti a ritenuta alla fonte a titolo di imposta o, comunque, legalmente esclusi dalla formazione della base imponibile.<\/p>\n<p>La determinazione sintetica pu\u00f2 essere altres\u00ec fondata sul contenuto induttivo di elementi indicativi di capacit\u00e0 contributiva individuato mediante l&#8217;analisi di campioni significativi di contribuenti, differenziati anche in funzione del nucleo familiare e dell&#8217;area territoriale di appartenenza, con decreto del Ministero dell&#8217;Economia e delle Finanze da pubblicare nella Gazzetta Ufficiale con periodicit\u00e0 biennale. In tale caso \u00e8 fatta salva per il contribuente la prova contraria di cui al quarto comma.<\/p>\n<p>La determinazione sintetica del reddito complessivo di cui ai precedenti commi \u00e8 ammessa a condizione che il reddito complessivo accertabile ecceda di almeno un quinto quello dichiarato.\u201d<\/p>\n<p>Dette modifiche entrano in vigore per gli accertamenti relativi ai redditi per i quali il termine di dichiarazione non \u00e8 ancora scaduto alla data di entrata in vigore del D.L. 78\/2010 (cio\u00e8 per le annualit\u00e0 dal 2009 in poi). Vi \u00e8, pertanto, un periodo di necessaria coesistenza delle due discipline. Dal 2005, (annualit\u00e0 in scadenza ai fini accertativi, salvi i casi di raddoppio dei termini e l\u2019ipotesi dell\u2019aumento di un anno in caso di omessa dichiarazione, al 31\/12\/2010) al 2008 compreso trover\u00e0 applicazione l`articolo 38 del D.P.R. 600\/73 nella versione precedente, dal 2009 in poi invece il redditometro e l\u2019accertamento sintetico verranno disciplinati sulla base delle nuove disposizioni.<\/p>\n<p>Fatta questa necessaria premessa, si vuol prendere spunto dall\u2019articolo riportato sul quotidiano \u201cIl sole24ore\u201d del 03.09.2013, a firma di Dario Deotto, per formulare alcune osservazioni ed eccepire il grossolano errore in cui si incorrerebbe prendendo per effettivo quanto in esso riportato.<\/p>\n<p>Infatti, risulta evidente che, a seconda delle annualit\u00e0 che saranno oggetto di accertamento da parte dell\u2019amministrazione, ci troveremo a dover seguire una diversa disciplina sia in termini di calcolo che in termini di vero e proprio funzionamento dello strumento.<\/p>\n<p>Il problema sollevato nell\u2019articolo in questione riguarda la ricostruzione induttiva del reddito relativamente agli anni d\u2019imposta 2007 \u2013 2008, anni che seguono la vecchia disciplina, sia in termini di calcolo dello scostamento (pari al 25%) sia in relazione alla tempistica che segue questo scostamento (nella vecchia formulazione la norma dice: \u201cquando il reddito dichiarato non risulta congruo rispetto ai predetti elementi per due o pi\u00f9 periodi di imposta\u201d).<\/p>\n<p>E\u2019 importante subito chiarire che, per quanto riguarda il 2007, il periodo a disposizione dell&#8217;Amministrazione finanziaria per effettuare un accertamento sulle dichiarazioni presentate si \u00e8 prescritto nel 2012, mentre per quanto riguarda il 2008 potranno ancora essere esperiti gli accertamenti fino al 31.12.2013.<\/p>\n<p>Quello che lascia perplessi \u00e8 che nella nota divulgata dal Sole 24 Ore, non si tenga conto del dettato normativo, ovvero della consecutivit\u00e0 prevista dalla norma di cui all\u2019art. 38, cos\u00ec come formulata ante 2010; infatti, nell\u2019articolo si paventa l\u2019idea di un legittimo accertamento relativo all\u2019anno 2008, sulla base di presupposti presenti in una dichiarazione presentata nel 2007, anno orami prescritto ai fini dell\u2019accertamento e, pertanto, non pi\u00f9 sindacabile fiscalmente.<\/p>\n<p>Questo per tre ordini di motivi:<\/p>\n<p>1. La consecutivit\u00e0 richiesta ai fini dell\u2019accertamento effettuato con la vecchia disciplina, prevede, nel caso de quo, il verificarsi, per due o pi\u00f9 annualit\u00e0, di uno scostamento; nel caso di specie ci si riferisce al 2007, che ormai fiscalmente \u00e8 chiuso;<\/p>\n<p>2. In mancanza di tale consecutivit\u00e0 e con riferimento alla vecchia disciplina (applicabile esclusivamente fino al 2008), non vi possono essere accertamenti induttivi il cui presupposto riguardi uno scostamento di un solo anno d\u2019imposta ( perch\u00e9 di questo si tratterebbe, visto che soltanto al 2008 \u00e8 applicabile la vecchia disciplina);<\/p>\n<p>3. Non da ultimo, non vi \u00e8 nessuna norma che disciplini il raccordo tra la vecchia e la nuova disciplina, anzi, la circolare 24\/E del 31 luglio 2013, ribadisce e scandisce il momento applicativo della nuova formulazione del redditometro: \u201cai fini dell\u2019applicazione delle nuove regole \u00e8 sufficiente uno scostamento pi\u00f9 ridotto rispetto a quello previsto dalla disciplina applicabile fino agli accertamenti relativi alle annualit\u00e0 precedenti al 2009 (pari al 25%); \u00e8, inoltre, sufficiente lo scostamento per un solo periodo d\u2019imposta e non pi\u00f9 biennale\u201d.<\/p>\n<p>Risulta, pertanto, oltremodo temerario, da parte dell\u2019autore, dare una interpretazione di questo tenore \u2013 in termini di contenuti e di assenza di riferimenti normativi \u2013 in relazione alla \u201cnon congruit\u00e0 retrodatata\u201d, perch\u00e9 non pu\u00f2 essere effettuato un accertamento sulla base di un presupposto relativo ad un anno d\u2019imposta fiscalmente prescritto e che, per di pi\u00f9, non preveda la possibilit\u00e0 per il contribuente di potersi difendere, come previsto dalla normativa.<\/p>\n<p>Infatti, soprattutto nei casi degli accertamenti da redditometro (e lo vediamo con l\u2019introduzione del contraddittorio obbligatorio nella nuova formulazione), il contribuente deve essere sempre messo nella condizione di poter dimostrare la provenienza dei redditi presuntivamente accertati; se l\u2019accertamento sull\u2019anno 2008, si basasse (come scritto nell\u2019articolo in questione) sui presupposti di un annualit\u00e0 prescritta, vi sarebbe una grave lesione del diritto di difesa del contribuente, che non potrebbe usufruire dell\u2019unico potere che ha a disposizione in un sistema impositivo ormai continuamente invasivo e anticostituzionale.<\/p>\n<p>Per completezza, si fa presente che, l\u2019unico caso in cui, il presupposto potrebbe allinearsi con la vecchia disciplina, e quindi nel caso del 2008 risulterebbe accertabile induttivamente unitamente al 2007, riguarda il solo caso di omessa presentazione della dichiarazione, diversamente non sar\u00e0 esperibile il redditometro sulla base di una normativa che non ha mai espresso nulla in relazione al passaggio tra vecchia e nuova disciplina.<\/p>\n<p>Al fine di non creare ulteriori questioni di incostituzionalit\u00e0, \u00e8 importante ribadire che la non congruit\u00e0 per il 2007, in quanto anno prescritto, non potr\u00e0 e non dovr\u00e0 consentire l\u2019accertamento anche per il 2008, perch\u00e9 nessuna norma lo prevede e perch\u00e9 sarebbe grossolanamente leso il diritto di difesa del contribuente costituzionalmente garantito.<\/p>\n<p>Avv. Maurizio Villani Avv. Francesca Giorgia Romana Sannicandro<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/13\/redditometro-nessuna-norma-stabilisce-la-retrodatazione-degli-scostamenti-ad-annualita-prescritte\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/09\/13\/redditometro-nessuna-norma-stabilisce-la-retrodatazione-degli-scostamenti-ad-annualita-prescritte\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>L\u2019applicazione del nuovo e temuto redditometro sta creando, com\u2019era prevedibile, non pochi problemi applicativi. Ecco perch\u00e9 Giovanni D\u2019Agata presidente e fondatore dello \u201cSportello dei Diritti\u201d suggerisce la lettura dell\u2019articolo scritto a due mani dai due tributaristi avvocati Maurizio Villani e Francesca Giorgia Romana Sannicandro di seguito riportato e pubblicato in anteprima sul sito www.sportellodeidiritti.org, in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20032,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20031"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=20031"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20031\/revisions"}],"predecessor-version":[{"id":20035,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20031\/revisions\/20035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/20032"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=20031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=20031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=20031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}