{"id":200505,"date":"2022-06-06T10:57:28","date_gmt":"2022-06-06T08:57:28","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=200505"},"modified":"2022-06-06T12:08:48","modified_gmt":"2022-06-06T10:08:48","slug":"carla-vistarini-a-copertino-per-firmare-la-direzione-artistica-del-nuovo-profetto-di-ivan-raganato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/06\/06\/carla-vistarini-a-copertino-per-firmare-la-direzione-artistica-del-nuovo-profetto-di-ivan-raganato\/","title":{"rendered":"CARLA VISTARINI A COPERTINO PER FIRMARE LA DIREZIONE ARTISTICA DEL NUOVO PROGETTO DI IVAN RAGANATO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-200507\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/IMG-20220529-WA0079.jpg\" alt=\"\" width=\"1600\" height=\"900\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/IMG-20220529-WA0079.jpg 1600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/IMG-20220529-WA0079-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/IMG-20220529-WA0079-1024x576.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/IMG-20220529-WA0079-768x432.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/IMG-20220529-WA0079-1536x864.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p>(Rdl) ______<\/p>\n<p>Nei giorni scorsi a Copertino presso la scuola d&#8217;arte Scena Muta di Ivan Raganato si \u00e8 tenuta una serie di eventi e giornate formative culminate con la messa in scena dello spettacolo &#8220;Paura&#8221;.<\/p>\n<p>Non un semplice spettacolo, ma un vero e proprio progetto artistico ideato dal regista salentino, che \u00e8 avvalso della collaborazione di grandi nomi: il fotografo Massimo Cordella, l&#8217;editore Stefano Donno, gli scrittori Giuseppe Puppo e Alessandro de Roma e l&#8217;attore co-fondatore del teatro dell&#8217;Elfo di Milano Luca Toracca.<\/p>\n<p>La supervisione artistica del progetto resta per\u00f2 un cammeo che tutti i partecipanti potranno vantare nel corso della loro carriera artistica e della loro esperienza umana: Carla Vistarini, scrittrice, paroliera, autrice. Un nome che ha fatto la storia della musica, della televisione e del teatro.<\/p>\n<p>La stessa dopo l&#8217;esperienza salentina cos\u00ec si esprime sui suoi profili social e noi non aggiungiamo altro.<\/p>\n<p><em>&#8220;La Cultura \u00e8 un bene prezioso e indispensabile e lo \u00e8 ancora di pi\u00f9 quando \u00e8 diffusa, alimentata, voluta e cercata con impegno personale fortissimo ed entusiasta, mai domo. Questo \u00e8 Scena Muta, la realt\u00e0 teatrale, produttiva, e sociale ideata e guidata nel Salento e precisamente a Copertino\u00a0 da Ivan Raganato, regista, attore, capocomico, imprenditore e soprattutto artista e divulgatore. Scena Muta \u00e8 teatro, scuola di recitazione, di danza, di dizione, di scrittura e luogo di incontro, di fusione di et\u00e0, caste, censi e formazione personale. Allievi di tutte le et\u00e0, bambini e diversamente giovani vi formano una comunit\u00e0 straordinaria e viva, trasversale, ricca di fermenti, di crescita, di sapere. La settimana scorsa sono tornata da loro, nella loro vivace struttura teatrale, per tenere uno stage con queste persone meravigliose, artisti in pectore e non solo, e mettere in scena con loro una serata di monologhi a tema Paura&#8221;.<\/em><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-200508\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/IMG-20220529-WA0075.jpg\" alt=\"\" width=\"1128\" height=\"2000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/IMG-20220529-WA0075.jpg 1128w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/IMG-20220529-WA0075-169x300.jpg 169w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/IMG-20220529-WA0075-578x1024.jpg 578w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/IMG-20220529-WA0075-768x1362.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/IMG-20220529-WA0075-866x1536.jpg 866w\" sizes=\"(max-width: 1128px) 100vw, 1128px\" \/><\/p>\n<p><em>&#8220;Sono stati tutti brillanti&#8221;<\/em> continua l&#8217;autrice &#8220;<em>bravi, spiritosi, drammatici, tutto. Avidi di sapere, di crescere, di fare. Scena Muta vive del proprio entusiasmo, ma sarebbe ora che questa realt\u00e0, come altre simili, vivacissime, al Sud, ma anche al Nord, al Centro, nelle province straordinarie di questa nostra Italia, ricevessero maggiore attenzione e cura da parte dello Stato, perch\u00e9 davvero riempiono di Bellezza ogni cosa, e soprattutto quei vuoti sociali dove il Pubblico, inteso come Stato, Amministrazioni locali, non arriva, vuoi per inerzia, vuoi per distrazione, e invece queste realt\u00e0 convergono a tenere unito un tessuto sociale positivo, ricco e gentile. Queste sono alcune foto dei ringraziamenti dopo lo spettacolo finale, applaudito da spettatori partecipi e generosi. Grazie a Ivan, Maria Antonietta, Dalila, Cristina, Agnese, Lorenzo, Andrea, Riccardo, Ilaria, Patrizia, Luca, Marzia, Clara, Alessandro, Alisia, Mauro, Pierluigi. Bravissimi<\/em>.&#8221;<\/p>\n<p>Il testo Paura \u00e8 edito da edizioni I Quaderni del Bardo di Stefano Donno.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-200516\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/cover-Paura-book.jpg\" alt=\"\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/cover-Paura-book.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/cover-Paura-book-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/cover-Paura-book-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/cover-Paura-book-768x768.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/cover-Paura-book-60x60.jpg 60w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/06\/06\/carla-vistarini-a-copertino-per-firmare-la-direzione-artistica-del-nuovo-profetto-di-ivan-raganato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/06\/06\/carla-vistarini-a-copertino-per-firmare-la-direzione-artistica-del-nuovo-profetto-di-ivan-raganato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl) ______ Nei giorni scorsi a Copertino presso la scuola d&#8217;arte Scena Muta di Ivan Raganato si \u00e8 tenuta una serie di eventi e giornate formative culminate con la messa in scena dello spettacolo &#8220;Paura&#8221;. Non un semplice spettacolo, ma un vero e proprio progetto artistico ideato dal regista salentino, che \u00e8 avvalso della collaborazione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":200508,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/200505"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=200505"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/200505\/revisions"}],"predecessor-version":[{"id":200515,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/200505\/revisions\/200515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/200508"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=200505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=200505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=200505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}