{"id":200538,"date":"2022-06-06T19:03:47","date_gmt":"2022-06-06T17:03:47","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=200538"},"modified":"2022-06-06T19:11:52","modified_gmt":"2022-06-06T17:11:52","slug":"fronte-degli-incendi-a-leccecronaca-it-parlano-gli-agricoltori-che-cremano-gli-ulivi-lasciati-morire","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/06\/06\/fronte-degli-incendi-a-leccecronaca-it-parlano-gli-agricoltori-che-cremano-gli-ulivi-lasciati-morire\/","title":{"rendered":"SALENTO FUOCO E FUMO, A leccecronaca.it PARLANO GLI AGRICOLTORI CHE CREMANO GLI ULIVI LASCIATI MORIRE"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-200551\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/284274200_3271771786403450_6251979271401357792_n.jpg\" alt=\"\" width=\"1156\" height=\"868\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/284274200_3271771786403450_6251979271401357792_n.jpg 1156w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/284274200_3271771786403450_6251979271401357792_n-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/284274200_3271771786403450_6251979271401357792_n-1024x769.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/284274200_3271771786403450_6251979271401357792_n-768x577.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/06\/284274200_3271771786403450_6251979271401357792_n-400x300.jpg 400w\" sizes=\"(max-width: 1156px) 100vw, 1156px\" \/><\/p>\n<p>di <strong>Flora Fina<\/strong>\u00a0\u00a0______<\/p>\n<p>\u201c<em>Poter estirpare in maniera legale un albero di ulivo, anche secolare, mi costerebbe tempo e denaro non indifferente. \u00c8 meglio se sto zitto e non le spiego come stanno davvero le cose. Dico soltanto che con i tempi che abbiamo qui in Puglia, soprattutto qua, a Lecce, ci vorrebbe circa un anno, un annetto e mezzo per avere la concessione per poter estirpare l\u2019albero. Appiccare invece un fuoco controllato costa quasi zero e dopo un po&#8217; posso tranquillamente ripiantare alberi nuovi\u00a0<\/em>\u201d.<\/p>\n<p>Si ferma un attimo <strong>Antonio<\/strong>, nome di fantasia di un contadino della provincia, che,\u00a0 alle domande di leccecronaca.it\u00a0 tace inizialmente, ma per dare poi immediatamente libero sfogo a tutto quanto si porta dentro. E infatti riparte subito:\u00a0\u201c<em>A me dispiace che la situazione sia questa, ma questa rimane, se n\u2019arilu me costa mille\/milletrecentu euro cu lu tiru e tocca spettu puru tantu tiempu, tantu vale ca li dau fuecu<\/em> \u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>A pochi chilometri di distanza, al lavoro nei campi, incontriamo un altro agricoltore, <strong>Oronzo<\/strong>, che racconta la stessa storia:\u00a0\u00a0<em>&#8220;<\/em><em>La Regione Puglia non aiuta, abbiamo bisogno di bonus e sostegni agricoli, non posso permettermi che l&#8217;espianto di dieci alberi, letteralmente morti, costi di tasca mia quasi quindicimila euro, dove li trovo?? Siamo disperati, ma non possiamo fare altrimenti, ci mancano gli aiuti, ma ci manca anche il pane, e dobbiamo di corsa ripiantare tutto&#8221;.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>La tutela del territorio, non \u00e8 stata mai la priorit\u00e0 qui nel nostro Salento, se roghi, incendi e devastazioni continuano ad essere la pura e semplice normalit\u00e0, che nemmeno fa pi\u00f9 notizia.<\/p>\n<p>Sono il frutto del nostro fallimento nei confronti della natura tutta, e sono il risultato di inadempienze e incapacit\u00e0 delle istituzioni.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c8 il caso ad esempio, dei tanti, tantissimi commenti che si rincorrono negli ultimi tempi su Facebook, sotto i numerosi post riguardanti l\u2019escalation di incendi avvenuta proprio in questi giorni, complici un sole battente e temperature improponibili in un mese come giugno:<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u201cRisultato dei terreni incolti e dimenticati, o meglio, il fuoco \u00e8 gratis, il trincio ha un costo, nonostante i contributi per la pulizia dei terreni. Sono necessari pi\u00f9 controlli da parte della forestale\u201d<\/em><\/p>\n<p><em>\u201c Costa di meno bruciarli che farli estirpare\u2026\u201d<\/em><\/p>\n<p><em>\u201c Incominciate ad arrestare qualcuno. Sono incendi dolosi, piromani in azione come l\u2019anno scorso \u201d<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>\u201c Quando chiami i Vigili del Fuoco e ti chiedono: ma gli alberi sono sani? Perch\u00e9 se sono malati che veniamo a fare \u201d<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Insomma, i roghi degli ulivi hanno cause e responsabilit\u00e0 precise, come ci hanno raccontato, di persona e sui social.<\/p>\n<p>Questo, senza entrare in questa sede sulla cosiddetta questione Xylella, degli ulivi abbandonati senza cure al disseccamento rapido.<\/p>\n<p>MA I ROGHI DEGLI ULIVI SONO SOLO UNA PARTE DEL PROBLEMA DEGLI INCENDI NEL SALENTO.<\/p>\n<p>Il grosso sta nelle\u00a0devastazioni operate in altri contesti di macchia mediterranea, in zone di alto pregio naturalistico, da piromani criminali senza scrupoli.<\/p>\n<p>Continueremo ad occuparcene nei prossimi giorni, per cercare di scuotere le coscienze,\u00a0 per capirci tutti qualcosa in pi\u00f9.<\/p>\n<p>&nbsp;<\/p>\n<p>Oggi, dopo il lungo fine settimana di devastazioni, fortunatamente si sono registrati &#8216;solo&#8217; incendi\u00a0 di sterpaglie, che \u00e8 poi l&#8217;ultimo aspetto del problema.<\/p>\n<p>Qua e l\u00e0 nel Salento, soprattutto lungo la tangenziale di Lecce, nelle campagne di Ugento, e nel territorio di Surbo\u00a0(nella foto).<\/p>\n<p>Una pratica che continua, &#8216;ripulire&#8217; i terreni col fuoco, nonostante i divieti espliciti e pressanti, cui per\u00f2 non seguono controlli e\u00a0 sanzioni.<\/p>\n<p>Inoltre, una pratica pericolosa, a parte per i danni che fa quando, come capita sovente, le fiamme sfuggono ai controlli dei contadini, anche per i danni che arreca all&#8217;ambiente, per il fatto che distoglie uomini e mezzi dei Vigili del Fuoco che sarebbero preziosi altrove e, infine, per le vittime, solo negli ultimi mesi sono gi\u00e0 due i proprietari di terreni morti intossicati dagli incendi che avevano appiccato nelle loro campagne.<\/p>\n<p>______<\/p>\n<p>LA RICERCA nei nostri articoli del 3, 4 e 5 giugno scorsi<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"jGvWffgeiz\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/06\/03\/l-approfondimento-un-piano-vecchio-di-quattro-anni-che-in-quattro-anni-ha-fatto-acqua-da-tutte-le-parti-ma-non-ha-contrastato-gli-incendi\/\">L&#8217; APPROFONDIMENTO \/ UN PIANO VECCHIO DI QUATTRO ANNI<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/06\/03\/l-approfondimento-un-piano-vecchio-di-quattro-anni-che-in-quattro-anni-ha-fatto-acqua-da-tutte-le-parti-ma-non-ha-contrastato-gli-incendi\/embed\/#?secret=jGvWffgeiz\" data-secret=\"jGvWffgeiz\" width=\"500\" height=\"282\" title=\"&#8220;L&#8217; APPROFONDIMENTO \/ UN PIANO VECCHIO DI QUATTRO ANNI&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"4ve6tHF2A5\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/06\/04\/incendi-in-puglia-la-tristezza-piu-grande-e-che-non-facciano-neppure-piu-notizia\/\">INCENDI, UN INFERNO QUOTIDIANO<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/06\/04\/incendi-in-puglia-la-tristezza-piu-grande-e-che-non-facciano-neppure-piu-notizia\/embed\/#?secret=4ve6tHF2A5\" data-secret=\"4ve6tHF2A5\" width=\"500\" height=\"282\" title=\"&#8220;INCENDI, UN INFERNO QUOTIDIANO&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"d3z16Ik9Ui\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/06\/05\/salento-fuoco-e-fumo-la-devastazione-continua-nelle-ultime-ore-un-crescendo-drammatico-nellindifferenza-delle-istituzioni\/\">SALENTO FUOCO E FUMO, LA DEVASTAZIONE CONTINUA<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/06\/05\/salento-fuoco-e-fumo-la-devastazione-continua-nelle-ultime-ore-un-crescendo-drammatico-nellindifferenza-delle-istituzioni\/embed\/#?secret=d3z16Ik9Ui\" data-secret=\"d3z16Ik9Ui\" width=\"500\" height=\"282\" title=\"&#8220;SALENTO FUOCO E FUMO, LA DEVASTAZIONE CONTINUA&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/06\/06\/fronte-degli-incendi-a-leccecronaca-it-parlano-gli-agricoltori-che-cremano-gli-ulivi-lasciati-morire\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/06\/06\/fronte-degli-incendi-a-leccecronaca-it-parlano-gli-agricoltori-che-cremano-gli-ulivi-lasciati-morire\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>&nbsp; di Flora Fina\u00a0\u00a0______ \u201cPoter estirpare in maniera legale un albero di ulivo, anche secolare, mi costerebbe tempo e denaro non indifferente. \u00c8 meglio se sto zitto e non le spiego come stanno davvero le cose. Dico soltanto che con i tempi che abbiamo qui in Puglia, soprattutto qua, a Lecce, ci vorrebbe circa un [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":200551,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/200538"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=200538"}],"version-history":[{"count":8,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/200538\/revisions"}],"predecessor-version":[{"id":200555,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/200538\/revisions\/200555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/200551"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=200538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=200538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=200538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}