{"id":201974,"date":"2022-07-07T14:55:52","date_gmt":"2022-07-07T12:55:52","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=201974"},"modified":"2022-07-07T19:08:24","modified_gmt":"2022-07-07T17:08:24","slug":"operazione-della-guardia-di-finanza-cinque-arresti","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/07\/07\/operazione-della-guardia-di-finanza-cinque-arresti\/","title":{"rendered":"OPERAZIONE DELLA GUARDIA DI FINANZA, CINQUE ARRESTI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-201977\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/guardia-di-finanza3-1.jpg\" alt=\"\" width=\"1536\" height=\"900\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/guardia-di-finanza3-1.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/guardia-di-finanza3-1-300x176.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/guardia-di-finanza3-1-1024x600.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/guardia-di-finanza3-1-768x450.jpg 768w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/p>\n<p>(e.l.) ______\u00a0 Militari della Guardia di Finanza del Comando Provinciale di Lecce stanno eseguendo in queste ore undici misure cautelari emesse dal gip del Tribunale di Lecce, su richiesta della Procura della Repubblica, di cui cinque ai domiciliari, quattro all\u2019obbligo di dimora, uno di divieto di dimora e un divieto di esercitare attivit\u00e0 imprenditoriale.<\/p>\n<p>Le undici persone sono accusate di corruzione, traffico di influenze illecite, e falso ideologico commesso da pubblico ufficiale.<\/p>\n<p>Ci sono inoltre altri dieci indagati.<\/p>\n<p>Le indagini, svolte dai finanzieri della Compagnia di Otranto e coordinate dalla Procura della Repubblica di Lecce, si riferiscono a\u00a0 comportamenti ispirati non solo all\u2019arricchimento personale, ma anche tesi ad assicurarsi e mantenere bacini di consenso elettorale attraverso una gestione personalistica di presidi di potere ormai consolidati in alcuni dei punti nevralgici della macchina amministrativa sia a livello provinciale, sia a livello regionale.<\/p>\n<p>Nella sostanza parliamo della promessa di posti di lavoro da parte di alcuni pubblici ufficiali, in cambio di plurime utilit\u00e0, nel collocamento di persone di fiducia in posizioni strategiche di svariati Enti pubblici, nell\u2019adozione di decisioni dell\u2019indagato principale, ovvero di altre persone a lui vicine, che &#8211; secondo gli inquirenti &#8211; hanno comportato illeciti profitti personali. ______<\/p>\n<p>&nbsp;<\/p>\n<p>VEDI IL NOSTRO ARTICOLO SUCCESSIVO DI AGGIORNAMENTO CON TUTTI I NOMI<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"zsXTADyrzf\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/07\/07\/operazione-della-guardia-di-finanza-sviluppi\/\">OPERAZIONE DELLA GUARDIA DI FINANZA \/ SVILUPPI<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/07\/07\/operazione-della-guardia-di-finanza-sviluppi\/embed\/#?secret=zsXTADyrzf\" data-secret=\"zsXTADyrzf\" width=\"500\" height=\"282\" title=\"&#8220;OPERAZIONE DELLA GUARDIA DI FINANZA \/ SVILUPPI&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/07\/07\/operazione-della-guardia-di-finanza-cinque-arresti\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/07\/07\/operazione-della-guardia-di-finanza-cinque-arresti\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______\u00a0 Militari della Guardia di Finanza del Comando Provinciale di Lecce stanno eseguendo in queste ore undici misure cautelari emesse dal gip del Tribunale di Lecce, su richiesta della Procura della Repubblica, di cui cinque ai domiciliari, quattro all\u2019obbligo di dimora, uno di divieto di dimora e un divieto di esercitare attivit\u00e0 imprenditoriale. Le [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":201975,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/201974"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=201974"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/201974\/revisions"}],"predecessor-version":[{"id":202001,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/201974\/revisions\/202001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/201975"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=201974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=201974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=201974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}