{"id":201980,"date":"2022-07-07T15:41:38","date_gmt":"2022-07-07T13:41:38","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=201980"},"modified":"2022-07-07T15:47:28","modified_gmt":"2022-07-07T13:47:28","slug":"controlli-di-polizia-straordinari-a-gallipoli","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/07\/07\/controlli-di-polizia-straordinari-a-gallipoli\/","title":{"rendered":"CONTROLLI DI POLIZIA STRAORDINARI A GALLIPOLI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-201982\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/GdF.jpg\" alt=\"\" width=\"709\" height=\"448\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/GdF.jpg 709w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/GdF-300x190.jpg 300w\" sizes=\"(max-width: 709px) 100vw, 709px\" \/>(e.l.) ______<\/p>\n<p>Ieri pomeriggio su tutto il territorio di Gallipoli c&#8217;\u00e8 stato un controllo di polizia finalizzato a contrastare la criminalit\u00e0 e l\u2019illegalit\u00e0 diffusa.<\/p>\n<p>Il dispositivo predisposto dal Questore di Lecce, d&#8217;intesa col Prefetto, ha coinvolto agenti della Polizia di Stato, della Polizia Stradale, i Carabinieri, la Guardia di Finanza, la Guardia Costiera e la Polizia Locale.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-201983\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/CC-e-GC.jpg\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/CC-e-GC.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/CC-e-GC-225x300.jpg 225w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Tre pubblici esercizi sono stati sottoposti a verifica documentale in materia di regolare possesso di autorizzazioni, contrasto al lavoro nero e controlli strumentali. Dai primi accertamenti \u00e8 emerso che due attivit\u00e0 avevano occupato spazi pubblici senza la prevista autorizzazione da parte del Comune di Gallipoli, pertanto, i titolari dei locali sono stati sanzionati con obbligo di ripristino dello stato dei luoghi.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-201984\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/Stradale-e-locale.jpg\" alt=\"\" width=\"817\" height=\"999\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/Stradale-e-locale.jpg 817w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/Stradale-e-locale-245x300.jpg 245w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/Stradale-e-locale-768x939.jpg 768w\" sizes=\"(max-width: 817px) 100vw, 817px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Inoltre \u00e8 stato effettuato un sequestro di un veicolo, intestato ad un giovane con precedenti perch\u00e9 \u00a0privo di assicurazione.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-201985\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/Polizia.jpg\" alt=\"\" width=\"679\" height=\"873\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/Polizia.jpg 679w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/Polizia-233x300.jpg 233w\" sizes=\"(max-width: 679px) 100vw, 679px\" \/><\/p>\n<p>Sul Piazzale della Madonna del Canneto sono stati sorpresi due parcheggiatori abusivi i quali hanno avuto due sanzioni per oltre 700 euro,\u00a0 il sequestro della somma trovata addosso in un marsupio, provento dell\u2019attivit\u00e0 illecita, e un ordine di allontanamento da quei luoghi.<\/p>\n<p>&nbsp;<\/p>\n<p>E&#8217; stata sequestrata un&#8217;auto del valore di 40 mila euro, proveniente dagli Emirati Arabi,\u00a0perch\u00e9 trovata\u00a0con targa prova scaduta di validit\u00e0, senza immatricolazione in Italia e privo di assicurazione.<\/p>\n<p>Inoltre sono state ritirate sei carte di circolazione e contestate ulteriori infrazioni per violazione al codice della strada, come mancato uso di cinture di sicurezza, mancata revisione e mancata patente al seguito.<\/p>\n<p>&nbsp;<\/p>\n<p>La Guardia Costiera ha operato un\u2019attivit\u00e0 di controllo nell\u2019area del mercato ittico, dove \u00e8 stata stata accertata una occupazione abusiva del suolo demaniale, con il posizionamento di tavolini, sedie e sgabelli,\u00a0 per oltre duecento metri quadri.<\/p>\n<p>&nbsp;<\/p>\n<p>Infine, sempre i militari della Guardia Costiera hanno elevato un verbale di oltre 2.000,00 euro a due turisti tedeschi che, con la propria imbarcazione, si erano ormeggiati senza alcun tipo di autorizzazione, in un\u2019area in violazione delle disposizioni di security portuale.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/07\/07\/controlli-di-polizia-straordinari-a-gallipoli\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/07\/07\/controlli-di-polizia-straordinari-a-gallipoli\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ______ Ieri pomeriggio su tutto il territorio di Gallipoli c&#8217;\u00e8 stato un controllo di polizia finalizzato a contrastare la criminalit\u00e0 e l\u2019illegalit\u00e0 diffusa. Il dispositivo predisposto dal Questore di Lecce, d&#8217;intesa col Prefetto, ha coinvolto agenti della Polizia di Stato, della Polizia Stradale, i Carabinieri, la Guardia di Finanza, la Guardia Costiera e la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":201982,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/201980"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=201980"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/201980\/revisions"}],"predecessor-version":[{"id":201987,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/201980\/revisions\/201987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/201982"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=201980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=201980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=201980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}