{"id":203556,"date":"2022-08-08T15:39:00","date_gmt":"2022-08-08T13:39:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=203556"},"modified":"2022-08-08T16:12:58","modified_gmt":"2022-08-08T14:12:58","slug":"casa-lecce-la-presentazione-di-bistrovic-arrivati-nel-salento-cetin-e-banda","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/08\/08\/casa-lecce-la-presentazione-di-bistrovic-arrivati-nel-salento-cetin-e-banda\/","title":{"rendered":"CASA LECCE \/ LA PRESENTAZIONE DI BISTROVIC. ARRIVATI NEL SALENTO CETIN E BANDA. E IL PUNTO-NAVE SULLA ROTTA DEL CALCIOMERCATO DI PANTALEO CORVINO"},"content":{"rendered":"\n<p>di <strong>Mattia Ala______<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"827\" height=\"697\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/bistrovic-3.jpg\" alt=\"\" class=\"wp-image-202929\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/bistrovic-3.jpg 827w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/bistrovic-3-300x253.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/07\/bistrovic-3-768x647.jpg 768w\" sizes=\"(max-width: 827px) 100vw, 827px\" \/><\/figure>\n\n\n\n<p>Questa mattina al Via del Mare si \u00e8 tenuta la conferenza stampa di presentazione del nuovo centrocampista del <strong>Lecce Kristijan Bristovic<\/strong> (nella foto), proveniente dal <strong>Cska Mosca.<\/strong><\/p>\n\n\n\n<p>Ad introdurlo, come di consueto, il Responsabile dell&#8217;Area Tecnica <strong>Pantaleo Corvino<\/strong> e il direttore sportivo <strong>Stefano Trinchera<\/strong>, i quali   hanno poi  fatto il punto sul mercato.<\/p>\n\n\n\n<p>Di seguito la conferenza stampa completa:<\/p>\n\n\n\n<p><strong>PANTALEO CORVINO<\/strong>: <em>&#8220;Oggi presentiamo il nostro nuovo centrocampista Bristovic. Intanto partiamo con una considerazione. Come potete vedere, quasi tutti i centrocampisti che abbiamo valutato e, poi, acquistato, hanno tutti in comune una cosa: la fisicit\u00e0. Riteniamo che in A la componente fisica in certi ruoli , assieme a quella tecno tattica, abbia una sua importanza. Bistrovic ha disputato 128 presenze in A fra Croazia, Russia e Turchia. Ha disputato, inoltre, le competizioni europee. Ha forza fisica, una tecnica eccellente ed un&#8217;intelligenza tattica importante. Offre il suo contributo anche dal punto di vista difensivo.  Palla al piede ha una percentuale di passaggi pari all&#8217;85%. E&#8217; dotato poi di un ottimo tiro dalla distanza. Dermaku e Tuia? Nell&#8217;ultimo anno e mezzo hanno avuto vari problemi fisici, \u00e8 vero. Dermaku, lo scorso anno, ha avuto il Covid e l&#8217;appendicite. Tuia prendiamo atto che \u00e8 un ragazzo sfortunato, gli dir di andare in giro con qualche santino. Ha avuto una contusione, un trauma procurato e questo gli ha creato un versamento muscolare. La sfiga ha voluto che, in un reparto avevamo in partenza due calciatori affidabili, sia avvenuto un doppio infortunio. <\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Quanto al mercato, sapete cosa che c&#8217;\u00e8 in giro. Se il tifoso sente che Rugani \u00e8 in vendita e io ci posso arrivare, non \u00e8 cos\u00ec. Percepisce circa 2,5 milioni, e anche se si dimezzasse l&#8217;ingaggio, non potrei avvicinarlo  comunque. Se uno \u00e8 un difensore da Lecce deve avere un ingaggio da Lecce. Non prendiamo difensori senza senso, solo per farci dire bravi. Ingaggiamo solo gente che risponde a determinati requisiti.  Siamo qui anche a sentire le lamentele di coloro che dicono che non siamo in grado di prendere difensori perch\u00e9 non sanno. Per carit\u00e0, il punto di vista del tifoso \u00e8 giusto, ma ci sono tante altre cose di cui dobbiamo tenere conto.  Io non mi piango addosso, so che ci sono incidenti di percorso, per Maksimovic avevamo i moduli del Genoa in sede. <\/em><\/p>\n\n\n\n<p><em>Non intendiamo farci dire che siamo sfortunati. Lavoriamo per dare un senso a tutto. Abbonati? Lavoriamo soprattutto  per loro, non per i 5 milioni che ci portano, perch\u00e9 5 milioni valgono un giocatore di A, compreso lo stipendio lordo. Sentiamo la responsabilit\u00e0 perch\u00e9 siamo figli di questo territorio. Con i 20 mila abbonati non si cambia la forza economica di un club, ma ti dimostrano fiducia e stima. Si sono fidati a scatola chiusa. Oggi c&#8217;\u00e8 la stessa fiducia del 2019, con la speranza che non accada lo stesso, quando fu adottata un&#8217;altra strategia. Lavoriamo per farcela e non doverci poi rimproverare nulla dopo. Il nostro modo di procedere tiene conto anche del futuro. Eccetto due calciatori di 34 anni, abbiamo mantenuto l&#8217;impalcatura dello scorso anno. Pensavamo di giocarcela con Monza e Cremonese, ma sia i brianzoli che i biancorossi si stanno muovendo con risorse illimitate. Noi andiamo avanti con la schiena dritta&#8221;.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>STEFANO TRINCHERA<\/strong>: <em>&#8220;Seguiamo Bistrovic da tempo e abbiamo intravisto in lui delle qualit\u00e0. D\u00e0 equilibrio alla squadra ed \u00e8 bravo in entrambe le fasi. Si tratta di una nostra intuizione, ci pu\u00f2 dare un grande aiuto&#8221;.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>KRISTIJAN BRISTOVIC<\/strong>:<em> &#8220;Contro il Cittadella dopo il pari dei veneti abbiamo sofferto un po&#8217; troppo. Prima abbiamo giocato bene. Continuiamo a lavorare duramente e saremo pronti per il campionato. Si, in Turchia ho conosciuto alcuni calciatori italiani come Viviano, Borini e Biraschi. Mi hanno augurato il meglio . <\/em><\/p>\n\n\n\n<p><em>Non \u00e8 stato difficile accettare di venire qui. Conosco la passione dei tifosi del Lecce e il Via del Mare \u00e8 praticamente sold- out, lo apprezzo molto. Inter? Sono partite che ti stimolano a giocare a calcio. E&#8217; un onore giocare in uno stadio pieno contro una grande squadra. <\/em><\/p>\n\n\n\n<p><em>Numero di maglia? Mi piace il numero 8 da quando sono bambino. Credo sia perfetto per un centrocampista box to box come me. Punizioni? Ci lavoro da due anni, mi auguro di aiutare la squadra ,tramite le mie punizioni, ad ottenere  quanti pi\u00f9 punti possibili. <\/em><\/p>\n\n\n\n<p><em>Cetin? Non ho la certezza di averci giocato contro ma sono sicuro che sia forte. Non vedo l&#8217;ora di incontrarlo. Chi mi ha impressionato di pi\u00f9? Nonostante sia una squadra giovane, qui c&#8217;\u00e8 tanta qualit\u00e0. Non voglio, per\u00f2, fare nomi. Dico solo che \u00e8 un piacere allenarmi con i miei compagni. Serie A? E&#8217; uno dei tornei pi\u00f9 difficili, per questo sono felicissimo di affrontare questa sfida. Dobbiamo disputare ogni partita al massimo e ritengo che la squadra sia pronta per questa nuova avventura. Quanto a me sto bene sia fisicamente che mentalmente, non vedo l&#8217;ora che inizi la Serie A. Voglio giocare il pi\u00f9 possibile e aiutare la squadra. Siamo giovani ma pronti&#8221;.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>CORVINO INGAGGIA IL TURCO CETIN PER RINFORZARE LA DIFESA <\/strong><\/p>\n\n\n\n<p>Il duo <strong>Corvino-Trinchera<\/strong>, a causa della contemporanea assenza di <strong>Dermaku<\/strong> e <strong>Tuia<\/strong>, e considerato che il campionato \u00e8 ormai alle porte, \u00e8 dovuto intervenire sul mercato per assicurare in tempi brevi  a mister <strong>Baroni<\/strong> almeno  due centrali.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"506\" height=\"675\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/cetin.jpg\" alt=\"\" class=\"wp-image-203580\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/cetin.jpg 506w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/cetin-225x300.jpg 225w\" sizes=\"(max-width: 506px) 100vw, 506px\" \/><\/figure>\n\n\n\n<p>Uno \u00e8 gi\u00e0 arrivato: <strong>Mert Cetin<\/strong>(nella foto).<\/p>\n\n\n\n<p>Il calciatore turco classe 1997 sembrava ad un passo dal ritornare nuovamente in Patria, ma alla fine <strong>Pantaleo Corvino<\/strong> ha sbaragliato la concorrenza dopo una trattativa imbastita in poco tempo.<\/p>\n\n\n\n<p> Un&#8217;opportunit\u00e0 fondamentale per rilanciare la sua carriera dopo  annate altalenanti.<\/p>\n\n\n\n<p>Portato in Italia dalla Roma nel 2019  su intuizione dell&#8217;allora direttore sportivo capitolino  <strong>Gianluca<\/strong> <strong>Petrachi<\/strong>(salentino doc, figlio dell&#8217;indimenticato cantante leccese <strong>Bruno<\/strong>), per una serie di motivazioni, soprattutto fisiche, non riesce a incidere, vivendo un annata ai margini della rosa. In tutto colleziona soltanto 6 presenze. <\/p>\n\n\n\n<p>Nel 2020, passa all&#8217;<strong>Hellas Verona<\/strong>   nell&#8217;ambito della trattativa che ha portato <strong>Kumbulla<\/strong> a compiere il percorso inverso. <\/p>\n\n\n\n<p>Anche nella citt\u00e0 di Romeo e Giuletta le cose, per\u00f2, non cambiano. <\/p>\n\n\n\n<p><strong>Cetin<\/strong> non riesce a trovare continuit\u00e0 per via di alcune problematiche fisiche che influiscono non poco nel suo rendimento, e ancora una volta trova poco spazio.<\/p>\n\n\n\n<p>Lo scorso gennaio si trasferisce in prestito al <strong>Kayseripsor<\/strong>, compagine del massimo campionato turco, dove gioca discretamente e  colleziona 10 presenze condite da un gol.<\/p>\n\n\n\n<p>Adesso lo attende il <strong>Lecce<\/strong>, certo della sua voglia di riscatto.<\/p>\n\n\n\n<p>Si tratta di un marcatore roccioso e piuttosto aggressivo, con un piede educato che gli permette di essere abile in fase di impostazione.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>E&#8217; ARRIVATO  LAMECK BANDA<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"867\" height=\"1024\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/banda-867x1024.jpg\" alt=\"\" class=\"wp-image-203581\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/banda-867x1024.jpg 867w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/banda-254x300.jpg 254w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/banda-768x907.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/banda.jpg 1080w\" sizes=\"(max-width: 867px) 100vw, 867px\" \/><\/figure>\n\n\n\n<p>L&#8217;esterno offensivo <strong>Lameck Banda<\/strong>(nella foto), di cui vi abbiamo parlato l&#8217;altro giorno, \u00e8 appena sbarcato a Brindisi. . Il calciatore zambiano classe 2001  ora si sta dirigendo in citt\u00e0 per sottoporsi alle visite mediche di rito.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/08\/08\/casa-lecce-la-presentazione-di-bistrovic-arrivati-nel-salento-cetin-e-banda\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/08\/08\/casa-lecce-la-presentazione-di-bistrovic-arrivati-nel-salento-cetin-e-banda\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Mattia Ala______ Questa mattina al Via del Mare si \u00e8 tenuta la conferenza stampa di presentazione del nuovo centrocampista del Lecce Kristijan Bristovic (nella foto), proveniente dal Cska Mosca. Ad introdurlo, come di consueto, il Responsabile dell&#8217;Area Tecnica Pantaleo Corvino e il direttore sportivo Stefano Trinchera, i quali hanno poi fatto il punto sul [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":202929,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/203556"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=203556"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/203556\/revisions"}],"predecessor-version":[{"id":203596,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/203556\/revisions\/203596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/202929"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=203556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=203556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=203556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}