{"id":203610,"date":"2022-08-08T19:40:54","date_gmt":"2022-08-08T17:40:54","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=203610"},"modified":"2022-08-08T19:40:57","modified_gmt":"2022-08-08T17:40:57","slug":"sequestrati-due-parcheggi-abusivi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2022\/08\/08\/sequestrati-due-parcheggi-abusivi\/","title":{"rendered":"SEQUESTRATI DUE PARCHEGGI ABUSIVI"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1920\" height=\"1440\" class=\"wp-image-203611\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/porcheggio.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/porcheggio.jpg 1920w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/porcheggio-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/porcheggio-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/porcheggio-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/porcheggio-1536x1152.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2022\/08\/porcheggio-400x300.jpg 400w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\n\n\n\n<p>(e.l. ) ______\u00a0 Nei giorni scorsi militari della Guardia di Finanza del Comando Provinciale di Lecce hanno sequestrato, nei Comuni di Sannicola e Ugento, due ampie aree adibite \u2018abusivamente\u2019 a parcheggio, a servizio di altrettante attivit\u00e0 commerciali, in assenza dei prescritti titoli autorizzativi previsti dalla vigente normativa, nonch\u00e9 in spregio ai vincoli paesaggistici ed idrogeologici.<\/p>\n\n\n\n<p>In particolare, in data 7 agosto 2022, i finanzieri del Gruppo di Gallipoli hanno sequestrato un terreno di circa 15mila mq. ubicato in agro di Sannicola, destinato a parcheggio di autoveicoli, nei pressi di una rinomata attivit\u00e0 di intrattenimento, in assenza di tutte le autorizzazioni di legge, pur essendo paesaggisticamente vincolata e perimetrata come sito di interesse comunitario (SIC) e di protezione speciale (ZPS), per la protezione e la conservazione degli habitat e della specie animali e vegetali cd. \u201cRete Natura 2000\u201d.<\/p>\n\n\n\n<p>Inoltre, nell\u2019area in rassegna, che era stata dotata dai fruitori di illuminazione e di recinzione, i finanzieri hanno individuato oltre 450 autovetture, per il cui parcheggio, al momento dell\u2019intervento, non sono risultati essere stati emessi i connessi scontrini fiscali, circostanza che sar\u00e0 oggetto di opportuni approfondimenti.<\/p>\n\n\n\n<p>Nel corso dell\u2019attivit\u00e0 ispettiva, svolta in materia di sommerso da lavoro, \u00e8 stata altres\u00ec riscontrata la presenza di 2 lavoratori \u201cin nero\u201d.<\/p>\n\n\n\n<p>Le condotte penalmente rilevanti ai sensi del vigente Testo Unico dell\u2019Edilizia, del Codice dei Beni Culturali e Paesaggistici e del Codice Penale, al momento individuate nei confronti di tre persone, sono state oggetto di notizia di reato, ora al vaglio della competente Autorit\u00e0 Giudiziaria.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Sempre in tema di reati ambientali, in data 28 luglio 2022, i Finanzieri della Tenenza di Casarano, nella localit\u00e0 balneare di Torre Mozza del Comune di Ugento, hanno individuato e sottoposto a sequestro preventivo, un\u2019ulteriore area \u2018privata\u2019 adibita a parcheggio \u2018abusivo\u2019 ad uso esclusivo per i clienti di un lido balneare.<\/p>\n\n\n\n<p>Il parcheggio, esteso per oltre 1.400 mq., \u00e8 stato ricavato dallo spianamento di una duna, a seguito di rimozione della sabbia e collocazione di materiale inerte, artatamente livellato; il tutto in una zona di pubblico interesse per la presenza di numerosi vincoli paesaggistici e ambientali, tutelata come Parco Naturale Regionale.<\/p>\n\n\n\n<p>A seguito dei preliminari accertamenti eseguiti presso i competenti uffici territoriali, che ne hanno consentito di accertare le violazioni di natura penale ipotizzate, le condotte del titolare del lido sono state rimesse alla valutazione della competente Procura della Repubblica di Lecce, per le fattispecie delittuose di \u2018distruzione o deturpamento di bellezze naturali\u2019, nonch\u00e9 per \u2019opere eseguite in assenza di autorizzazioni o in difformit\u00e0 di essa\u2019 in violazione delle vigenti disposizioni del Testo Unico dei Beni Culturali e del Paesaggio ed in materia di edilizia.<\/p>\n\n\n\n<p>A tal ultimo riguardo, il Giudice per le Indagini Preliminari ha gi\u00e0 emesso Ordinanza di convalida di sequestro preventivo di urgenza e contestuale decreto di sequestro preventivo, eseguito in data 4 agosto 2022.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2022\/08\/08\/sequestrati-due-parcheggi-abusivi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2022\/08\/08\/sequestrati-due-parcheggi-abusivi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l. ) ______\u00a0 Nei giorni scorsi militari della Guardia di Finanza del Comando Provinciale di Lecce hanno sequestrato, nei Comuni di Sannicola e Ugento, due ampie aree adibite \u2018abusivamente\u2019 a parcheggio, a servizio di altrettante attivit\u00e0 commerciali, in assenza dei prescritti titoli autorizzativi previsti dalla vigente normativa, nonch\u00e9 in spregio ai vincoli paesaggistici ed idrogeologici. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/203610"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=203610"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/203610\/revisions"}],"predecessor-version":[{"id":203612,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/203610\/revisions\/203612"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=203610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=203610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=203610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}