{"id":20413,"date":"2013-10-03T15:21:45","date_gmt":"2013-10-03T15:21:45","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=20413"},"modified":"2013-10-03T15:35:58","modified_gmt":"2013-10-03T15:35:58","slug":"bullismo-il-ministero-deve-risarcire-il-bambino-picchiato-a-scuola-dai-compagni","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/03\/bullismo-il-ministero-deve-risarcire-il-bambino-picchiato-a-scuola-dai-compagni\/","title":{"rendered":"Bullismo. Il Ministero deve risarcire il bambino picchiato a scuola dai compagni."},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/03\/bullismo-il-ministero-deve-risarcire-il-bambino-picchiato-a-scuola-dai-compagni\/bullismo-gruppo\/\" rel=\"attachment wp-att-20414\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/bullismo-gruppo-150x150.jpg\" alt=\"\" title=\"bullismo gruppo\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-20414\" \/><\/a>Riceviamo e volentieri pubblichiamo.<\/p>\n<p>Risarcita la grave sindrome psichica a causa delle percosse sub\u00ecte. Alla scuola spetta l\u2019onere della prova di aver adottato le misure disciplinari idonee a evitare situazioni pericolose. Pesante, pesantissima decisione a carico del Ministero della pubblica istruzione in tema di bullismo e danni subiti dallo scolaro a causa delle percosse subite dai compagni. A segnalarla Giovanni D&#8217;Agata, presidente e fondatore dello \u201cSportello dei Diritti\u201d, che ne sottolinea la rilevanza alla luce del fatto che si tratta di un fenomeno ancora troppo sottovalutato all\u2019interno stesso delle Nostre scuole, ma che forse con precedenti di tale portata si potr\u00e0 iniziare a persuadere il personale docente e non docente ad una maggiore vigilanza e prevenzione. Con la sentenza 8081\/2013, infatti, il Tribunale di Milano ha stabilito che il Ministero deve risarcire i danni patiti dall\u2019alunno vittima di episodi di bullismo tenuti da altri allievi dell&#8217;Istituto scolastico, consistiti in aggressioni fisiche. Per il tribunale meneghino, infatti, la condotta omissiva del personale docente configura una \u00abculpa in vigilando\u00bb: per superare la presunzione di responsabilit\u00e0 ex art. 2048 c.c., non \u00e8 sufficiente la sola dimostrazione di non essere stati in grado di spiegare un intervento correttivo o repressivo, ma \u00e8 necessario anche dimostrare di aver adottato, in via preventiva, tutte le misure disciplinari o organizzative idonee ad evitare il sorgere di situazioni pericolose. Peraltro, nel caso di specie, nessuna prova \u00e8 stata fornita al riguardo da parte convenuta che, invece, \u00e8 rimasta contumace, disinteressandosi al giudizio. Secondo la norma citata, i precettori e coloro che insegnano un mestiere o un&#8217;arte sono responsabili del danno cagionato dal fatto illecito dei loro allievi e apprendisti nel tempo in cui sono sotto la loro vigilanza, prevedendo altres\u00ec che tali persone siano &#8220;liberate dalla responsabilit\u00e0 soltanto se provano di non aver potuto impedire il fatto&#8221;. E ancora, si legge in sentenza che \u00abin tema di responsabilit\u00e0 dell&#8217;amministrazione scolastica ex l. n. 312 del 1980, art. 61, sul danneggiato incombe l&#8217;onere di provare soltanto che il danno \u00e8 stato cagionato al minore durante il tempo in cui lo stesso era sottoposto alla vigilanza del personale scolastico; il che \u00e8 sufficiente a rendere operante la presunzione di colpa per inosservanza dell&#8217;obbligo di sorveglianza, mentre spetta all&#8217;amministrazione scolastica dimostrare di aver esercitato la sorveglianza sugli allievi con diligenza idonea ad impedire il fatto\u00bb. Insomma, per superare la presunzione di responsabilit\u00e0 di cui all\u2019art. 2048 del codice civile, non \u00e8 sufficiente la sola dimostrazione di non essere stati in grado di spiegare un intervento correttivo o repressivo, ma \u00e8 necessario anche dimostrare di aver adottato, in via preventiva, tutte le misure disciplinari o organizzative idonee a evitare il sorgere di situazioni pericolose. Peraltro, il giudice del capoluogo lombardo ha rilevato che una volta stabilita la responsabilit\u00e0 della scuola per i danni non patrimoniali subiti dallo studente \u00e8 compito dello stesso magistrato accertare l&#8217;effettiva consistenza del pregiudizio individuando a prescindere dal nome attribuitogli, quali ripercussioni negative sul valore &#8211; uomo si siano verificate e provvedendo alla loro integrale ripartizione: ed il giudice anzich\u00e9 procedere alla separata liquidazione del danno morale in termini di una percentuale del danno biologico (procedimento che determina una duplicazione di danno), deve procedere a un&#8217;adeguata personalizzazione della liquidazione del danno biologico, valutando nella loro effettiva consistenza le sofferenze fisiche e psichiche patite dal soggetto leso, onde pervenire al ristoro del danno nella sua interezza. Nella fattispecie, la CTU ha accertato che il ragazzo nel corso di causa divenuto maggiorenne, ha sub\u00ecto l\u2019insorgenza di una grave sindrome psichica. Dalla malattia suddetta \u00e8 derivato un danno biologico permanente subito dall&#8217;attore nella misura del 20%, ed un danno biologico temporaneo protrattosi per mesi diciotto. Il danno subito dal giovane che aveva 13 anni all\u2019epoca dei fatti \u00e8 stato liquidato nella complessiva somma rivalutata ad oggi di Euro 125.000,00. Oltre alle spese di lite ed interessi. Il tutto a carico del Ministero dell\u2019Istruzione.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/03\/bullismo-il-ministero-deve-risarcire-il-bambino-picchiato-a-scuola-dai-compagni\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/03\/bullismo-il-ministero-deve-risarcire-il-bambino-picchiato-a-scuola-dai-compagni\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Risarcita la grave sindrome psichica a causa delle percosse sub\u00ecte. Alla scuola spetta l\u2019onere della prova di aver adottato le misure disciplinari idonee a evitare situazioni pericolose. Pesante, pesantissima decisione a carico del Ministero della pubblica istruzione in tema di bullismo e danni subiti dallo scolaro a causa delle percosse subite [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20414,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20413"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=20413"}],"version-history":[{"count":9,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20413\/revisions"}],"predecessor-version":[{"id":20423,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20413\/revisions\/20423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/20414"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=20413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=20413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=20413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}