{"id":20475,"date":"2013-10-04T14:26:35","date_gmt":"2013-10-04T14:26:35","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=20475"},"modified":"2013-10-04T14:26:35","modified_gmt":"2013-10-04T14:26:35","slug":"noi-lecce-2","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/04\/noi-lecce-2\/","title":{"rendered":"NOI LECCE"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/noi-lecce.png\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/10\/noi-lecce-300x121.png\" alt=\"\" width=\"300\" height=\"121\" class=\"alignleft size-medium wp-image-20476\" \/><\/a>In un momento cos\u00ec delicato per la storia sportiva dell\u2019U.S. Lecce, occorre esser pi\u00f9 che mai uniti nel cercare ogni via percorribile affinch\u00e9 si tuteli e preservi il futuro calcistico della nostra squadra del cuore. \u201c<strong><em>Noi Lecce\u201d <\/em><\/strong>dalla sua fondazione<strong><em> <\/em><\/strong>\u00a0ha perseguito, in tal senso, l\u2019idea tutt\u2019altro che peregrina di poter dar vita, anche in questo territorio, all\u2019<strong>azionariato popolare <\/strong>quale strumento per vigilare e partecipare attivamente nelle vicende che riguardano il <strong>club giallorosso<\/strong>; e ci\u00f2 nella ferma convinzione che &#8211; a prescindere da chi ha guidato, guida e guider\u00e0\u00a0 la struttura societaria &#8211; il Lecce \u00e8 stato, \u00e8 e rester\u00e0 un patrimonio del territorio e, soprattutto, dei tifosi.<\/p>\n<p>Dando seguito alla scelta di contribuire alla creazione del progetto nazionale \u201c<strong><em>Supporters in campo<\/em><\/strong>\u201d, l\u2019associazione dei tifosi leccese parteciper\u00e0 il prossimo <strong>luned\u00ec 7 ottobre a Roma<\/strong> al convegno dal titolo <strong>\u201c<em>Supporters\u2019 Trusts, Lega Pro: occasione per un nuovo rapporto tra Club e tifosi.<\/em><\/strong><strong><em> Anche in Italia da oggi si pu\u00f2: per un progetto di gestione del calcio moderno<\/em>\u201d<\/strong>,<strong> <\/strong>organizzato da Supporters in Campo e dalla Lega Pro per mettere a confronto diretto i fan ed i proprietari delle societ\u00e0 calcistiche. L\u2019evento \u00e8 stato organizzato affinch\u00e9 i protagonisti dell\u2019evento, ossia i supporters e le societ\u00e0, si riuniscano attorno ad uno stesso tavolo per confrontarsi sul tema della <em>governance<\/em> dei club.<\/p>\n<p>Tra gli invitati figurano <strong>Giovanni Malag\u00f2<\/strong> (Presidente CONI), <strong>Giancarlo Abete<\/strong> (Presidente FIGC), <strong>Antonio Talarico<\/strong> (<em>Supporter<\/em><em> Liaison Officer<\/em>-FIGC), <strong>Mario Macalli<\/strong> (Presidente Lega Pro), <strong>Francesco Ghirelli<\/strong> (Direttore Generale Lega Pro), <strong>Francesco Cirillo<\/strong> (Vicedirettore generale della Pubblica Sicurezza \u2013 Direttore Centrale della\u00a0Polizia Criminale e presidente dell\u2019Unit\u00e0 Informativa Scommesse Sportive), <strong>Roberto Massucci<\/strong> (Vice Presidente Osservatorio Nazionale per le Manifestazioni Sportive), <strong>Antonia Hagemann<\/strong> (responsabile attivit\u00e0 europee di Supporters Direct Europe), <strong>David Miani<\/strong> (componente del coordinamento di Supporters in Campo). <strong>Lega Pro <\/strong>e<strong> Supporters in Campo<\/strong> assisteranno i tifosi ed i dirigenti che vi parteciperanno al\u00a0reciproco dialogo, pur sempre nel rispetto\u00a0della propria rispettiva indipendenza ed\u00a0autonomia. Sar\u00e0 quindi costituito un <strong>tavolo di confronto permanente<\/strong> per la verifica del percorso intrapreso.<\/p>\n<p>Piena condivisione del progetto, del percorso e degli obiettivi hanno manifestato \u201c<strong>Lecce In Azione<\/strong>\u201d e \u201c<strong>Salento GialloRosso<\/strong>\u201d che parteciperanno all\u2019appuntamento romano con <strong>proprie delegazioni<\/strong>. Pertanto, le associazioni \u201cNoi Lecce\u201d, \u201cLecce In Azione\u201d e \u201cSalento GialloRosso\u201d lanciano un vibrante appello a tutti coloro che hanno a cuore i colori giallorossi affinch\u00e9 si sia compatti e propositivi nel difendere la nostra passione.<\/p>\n<p align=\"right\"><strong>\u00a0<\/strong><\/p>\n<p align=\"right\"><strong>I Direttivi di Noi Lecce, Lecce in Azione, Salento GialloRosso<\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/04\/noi-lecce-2\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/04\/noi-lecce-2\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>In un momento cos\u00ec delicato per la storia sportiva dell\u2019U.S. Lecce, occorre esser pi\u00f9 che mai uniti nel cercare ogni via percorribile affinch\u00e9 si tuteli e preservi il futuro calcistico della nostra squadra del cuore. \u201cNoi Lecce\u201d dalla sua fondazione \u00a0ha perseguito, in tal senso, l\u2019idea tutt\u2019altro che peregrina di poter dar vita, anche in [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20475"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=20475"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20475\/revisions"}],"predecessor-version":[{"id":20477,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20475\/revisions\/20477"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=20475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=20475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=20475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}