{"id":20482,"date":"2013-10-04T14:35:15","date_gmt":"2013-10-04T14:35:15","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=20482"},"modified":"2013-10-04T14:35:15","modified_gmt":"2013-10-04T14:35:15","slug":"lunedi-si-riunisce-il-consiglio-provinciale","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/04\/lunedi-si-riunisce-il-consiglio-provinciale\/","title":{"rendered":"LUNEDI&#8217; SI RIUNISCE IL CONSIGLIO PROVINCIALE"},"content":{"rendered":"<p><em><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/11\/provincia_di_lecce.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/11\/provincia_di_lecce-300x229.jpg\" alt=\"\" width=\"300\" height=\"229\" class=\"alignleft size-medium wp-image-7683\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/11\/provincia_di_lecce-300x229.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/11\/provincia_di_lecce.jpg 364w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Riceviamo e volentieri pubblichiamo.<\/em><\/p>\n<p>Questi i punti all&#8217;odg.<strong>\u00a0<\/strong><\/p>\n<p>Ai sensi e per gli effetti delle vigenti norme di legge e regolamentari, il Consiglio Provinciale, \u00e8\u00a0 convocato in seduta\u00a0 <strong>ordinaria\u00a0 <\/strong>presso questa sede (Lecce \u2013 Via Umberto I, n. 13), nell\u2019apposita aula consiliare, in <strong>prima<\/strong> convocazione per il\u00a0 <strong>giorno\u00a0 7\u00a0 Ottobre\u00a0 2013\u00a0 <\/strong>alle <strong>ore\u00a0 10,00\u00a0 <\/strong>con continuazione<strong>\u00a0 <\/strong>per la trattazione\u00a0 dei seguenti argomenti:<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>Lettura e approvazione verbali sedute consiliari del\u00a0 5 \u2013 9 Agosto\u00a0\u00a0 e 13 \u2013 16 Settembre 2013.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol start=\"2\">\n<li>Interrogazione presentata dal gruppo consiliare Patto per il Salento \u2013 prot. n.\u00a0 75792 dell\u20198.08.2013 \u2013 primo firmatario Consigliere Mario Pendinelli \u2013 in merito al Regolamento Contabilit\u00e0.- Possibile modifica.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol start=\"3\">\n<li>Interrogazione presentata in data 12.09.2013 dal gruppo consiliare P.D. \u2013 primo firmatario Consigliere Cosimo Durante &#8211; in merito al progetto ASIA.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol>\n<li>Bilancio di previsione per l\u2019esercizio finanziario 2013 \u2013 <strong>Variazione n. 9 \u2013 <\/strong>Ratifica delib. G.P. n. 156 del\u00a0 09.08.2013.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol>\n<li>Bilancio di previsione per l\u2019esercizio finanziario 2013 \u2013 <strong>Variazione n. 10 \u2013 <\/strong>Ratifica delib. G.P. n. 171 dell\u201911.09.2013.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>Esercizio finanziario 2013 \u2013 Ricognizione sullo stato di attuazione dei programmi e verifica degli equilibri generali di bilancio (art. 193 Dlgs. 267\/2000) alla data del 12 settembre 2013 \u2013 Variazione di bilancio n. 11.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol>\n<li>Riconoscimento debito fuori bilancio Sentenza Tar Lecce n. 849\/2013 per occupazione illegittima per lavori di rettifica della S.P. \u201cdalla SS n. 16 alla S.P. Cavallino \u2013Caprarica per Caprarica \u2013 Martano alla S.P. Martano \u2013 Otranto con raccordi alla circonvallazione di\u00a0 Lizzanello e alla S.P. Caprarica alla Lizzanello \u2013 Calimera\u201d \u2013 Primo stralcio \u2013 Primo lotto.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol>\n<li>Risarcimento danno economico a seguito di Sentenza della Corte d\u2019Appello di Lecce \u2013 Sezione lavoro n. 1126\/2013. Provvisoriamente esecutiva \u2013 Riconoscimento debito fuori bilancio ai sensi dell\u2019art. 194 \u2013 comma 1 \u2013 lett. A) D.Lgs. 267\/2000.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol>\n<li>Riconoscimento debito fuori bilancio per liquidazione sentenza Corte di\u00a0 Appello di Lecce n. 140\/2013 a seguito oppostone determinazione indennit\u00e0 di espropriazione suolo per la costruzione dell\u2019Ist. Geometri di Casarano.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol>\n<li>Ordinanza Tribunale di Lecce \u2013 Sezione staccata di Casarano nella causa civile n. 430\/2011 \u2013 Riconoscimento debito fuori bilancio ai sensi dell\u2019art. 194 \u2013 comma 1 \u2013 lettera a) del D.Lgs. 267\/2000.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol>\n<li>Lavori di costruzione dell\u2019Istituto professionale di Martano. Giudizio Provincia di Lecce contro Saracino Patrizia. Sentenza Corte di Appello di Lecce n. 23\/2003 \u2013 Riconoscimento debito fuori bilancio.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>IL PRESIDENTE DEL CONSIGLIO<\/p>\n<p>(Dott. Giorgio Primiceri)<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/04\/lunedi-si-riunisce-il-consiglio-provinciale\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/10\/04\/lunedi-si-riunisce-il-consiglio-provinciale\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Questi i punti all&#8217;odg.\u00a0 Ai sensi e per gli effetti delle vigenti norme di legge e regolamentari, il Consiglio Provinciale, \u00e8\u00a0 convocato in seduta\u00a0 ordinaria\u00a0 presso questa sede (Lecce \u2013 Via Umberto I, n. 13), nell\u2019apposita aula consiliare, in prima convocazione per il\u00a0 giorno\u00a0 7\u00a0 Ottobre\u00a0 2013\u00a0 alle ore\u00a0 10,00\u00a0 con [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":7683,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20482"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=20482"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20482\/revisions"}],"predecessor-version":[{"id":20483,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/20482\/revisions\/20483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/7683"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=20482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=20482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=20482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}